{"id":352617,"date":"2023-05-18T09:26:27","date_gmt":"2023-05-18T07:26:27","guid":{"rendered":"https:\/\/www.welcomepickups.com\/colombo\/taxi\/"},"modified":"2023-05-18T09:44:46","modified_gmt":"2023-05-18T07:44:46","slug":"taxi","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/","title":{"rendered":"Colombo Taxi"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":338171,"parent":352539,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-transfer-v1.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-352617","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"show_in_frontpage":false,"is_seo_five":false,"second_destination":false,"title":"Colombo Taxi","small_title":"","heading_title":"h1","subtitle":"G\u00fcnstige Festpreise f\u00fcr Taxis in Colombo","heading_subtitle":"h2","background":{"ID":338171,"id":338171,"title":"Colombo,Aerial,Shot,,Iconic,Places,In,Sri,Lanka,,Lotus,Tower","filename":"shutterstock_1745929967.jpg","filesize":119335,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","link":"https:\/\/www.welcomepickups.com\/de\/colombo\/flughafen-transfer-zur-stadt\/attachment\/colomboaerialshoticonicplacesinsrilankalotustower-2\/","alt":"","author":"176","description":"Colombo Airport to Colombo City Center","caption":"","name":"colomboaerialshoticonicplacesinsrilankalotustower-2","status":"inherit","uploaded_to":352609,"date":"2022-12-28 16:13:14","modified":"2024-10-01 17:39:34","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1000,"height":564,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","large-width":960,"large-height":541,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","1536x1536-width":1000,"1536x1536-height":564,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","2048x2048-width":1000,"2048x2048-height":564,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-672x372.jpg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-450x225.jpg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-290x117.jpg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-290x170.jpg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-112x117.jpg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-64x64.jpg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-88x66.jpg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-197x151.jpg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-667x416.jpg","first_full-width":667,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-340x188.jpg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","main_hero-width":1000,"main_hero-height":564,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967-200x125.jpg","sidebar_cta-width":200,"sidebar_cta-height":125}},"tts_title":"Schnelle und unkomplizierte Taxidienste in Colombo","tts__title_heading":"h2","tts_text":"<p>Colombo ist die stolze und gesch\u00e4ftige Hauptstadt von Sri Lanka. Es ist die perfekte Mischung aus Gro\u00dfstadt und atemberaubenden wei\u00dfen Sandstr\u00e4nden und damit der perfekte Ort f\u00fcr einen entspannten tropischen Kurzurlaub und eine St\u00e4dtereise. Um sich in dieser gro\u00dfen Stadt fortzubewegen und ihre beiden einzigartigen Seiten zu erkunden, nehmen Sie am besten ein Taxi nach Colombo. Es gibt zwei Arten von Taxis in Colombo: Tuk Tuks und normale Taxis. Sie k\u00f6nnen beides ganz einfach auf der Stra\u00dfe anhalten, ein regul\u00e4res Taxi \u00fcber eine der vielen Telefongesellschaften bestellen oder <a href=\"https:\/\/www.welcomepickups.com\/de\/colombo\/airport-taxi\/\" title=\"Ihr Taxi In Colombo Im Voraus Buchen\">Ihr Taxi in Colombo im Voraus buchen<\/a>.<\/p>\n","tts_photo":{"ID":338249,"id":338249,"title":"Colombo Taxi","filename":"Colombo-Taxi.jpeg","filesize":61057,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi.jpeg","link":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/attachment\/colombo-taxi-2\/","alt":"","author":"176","description":"","caption":"","name":"colombo-taxi-2","status":"inherit","uploaded_to":352617,"date":"2022-12-28 16:41:09","modified":"2022-12-28 16:41:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":850,"height":350,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-300x124.jpeg","medium-width":300,"medium-height":124,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-768x316.jpeg","medium_large-width":768,"medium_large-height":316,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi.jpeg","large-width":850,"large-height":350,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi.jpeg","1536x1536-width":850,"1536x1536-height":350,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi.jpeg","2048x2048-width":850,"2048x2048-height":350,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-672x350.jpeg","post-thumbnail-width":672,"post-thumbnail-height":350,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-450x225.jpeg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-290x117.jpeg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-290x170.jpeg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-112x117.jpeg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-64x64.jpeg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-88x66.jpeg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-197x151.jpeg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-667x350.jpeg","first_full-width":667,"first_full-height":350,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-340x188.jpeg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi.jpeg","main_hero-width":850,"main_hero-height":350,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Colombo-Taxi-200x125.jpeg","sidebar_cta-width":200,"sidebar_cta-height":125}},"photo_captions":"","tts_title_2":"Wie hoch sind die Taxitarife auf Colombo?","tts__title_2_heading":"h2","tts_text_2":"<p>Da es in Colombo zwei Arten von Taxis gibt, Tuk Tuks und regul\u00e4re Taxis, lassen sich die Taxitarife in Colombo auf zwei verschiedene Arten berechnen. Tuk Tuk-Fahrer sind viel weniger formell und nennen Ihnen einen Festpreis, der sich danach richtet, wie weit Ihr Ziel entfernt ist, wohingegen normale Taxis in der Regel einen Taxameter verwenden. Obwohl die meisten regul\u00e4ren Taxis in Colombo mit einem Taxameter ausgestattet sind, verwenden sie nicht alle die gleichen Tarife. Jedes Unternehmen kalibriert seinen eigenen Taxameter und einige berechnen sogar Festpreise f\u00fcr ihre Fahrten in der Stadt. Als grobe Orientierung k\u00f6nnen Sie die Taxitarife in Colombo wie folgt veranschlagen:<\/p>\n<p><b>Grundpreis:<\/b> 1,14\u00a0\u20ac (100\u00a0RS)<\/p>\n<p><b>Preis pro Meile:<\/b> 1,82\u00a0\u20ac (160\u00a0RS)<\/p>\n<p><strong>Preis pro 1 Stunde Wartezeit<\/strong>: 2,05\u00a0\u20ac (180\u00a0RS)<\/p>\n","car_type":false,"cb_title":"Wie man ein Taxi in Colombo bekommt","cb_text":"<p>Der einfachste Weg, in Colombo ein Taxi oder Tuk Tuk zu bekommen, ist, eines auf der Stra\u00dfe anzuhalten. Sowohl regul\u00e4re Taxis als auch Tuk Tuks finden Sie \u00fcberall in der Innenstadt, an den wichtigsten Hotels, gro\u00dfen Einkaufszentren und Touristenattraktionen, so dass es kaum einfacher sein k\u00f6nnte, eines im Stadtzentrum zu finden. Wenn Sie sp\u00e4tabends unterwegs sind oder au\u00dferhalb des Stadtzentrums ein Taxi suchen, sollten Sie entweder <a href=\"https:\/\/www.welcomepickups.com\/de\/colombo\/airport-taxi\/\" title=\"Ihre Fahrt Im Voraus Buchen\">Ihre Fahrt im Voraus buchen<\/a> oder eines der Taxiunternehmen in Colombo anrufen. Einige der am besten bewerteten \u00f6rtlichen Taxiunternehmen, die Sie anrufen k\u00f6nnen, sind:<\/p>\n<p><b>Taxi Sri Lanka:<\/b> +94 71 6299 969<\/p>\n<p><b>TaxiGo Cab Service:<\/b> +94 77 083 3772<\/p>\n<p><b>Senu Cab Service:<\/b> +94 77 378 8646<\/p>\n","content_below_car_title_heading":"h3","content_below_car_type":[{"title":"Erstklassige Taxifahrten in Colombo mit Welcome","content_below_type_heading":"h2","text":"<p>Wenn Sie in Colombo ein \u00f6rtliches Taxi nehmen, kann es zu Problemen kommen, wie Missverst\u00e4ndnissen und sich st\u00e4ndig \u00e4ndernden Taxitarifen. Es kann schwierig sein, sich hier zurechtzufinden, besonders f\u00fcr Besucher, die zum ersten Mal hier sind. Wenn Sie Ihre Taxifahrten in Colombo jedoch im Voraus mit <a href=\"https:\/\/www.welcomepickups.com\/de\/colombo\/airport-taxi\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a> buchen, bleiben Ihnen solche Probleme erspart. Wir bieten garantierte p\u00fcnktliche Abholungen, flie\u00dfend Englisch sprechende Fahrer, wettbewerbsf\u00e4hige Festpreise, auf die Sie sich immer verlassen k\u00f6nnen, und einen Kundendienst rund um die Uhr.<\/p>\n","list":false},{"title":"Taxitipps in Colombo","content_below_type_heading":"h2","text":"","list":false},{"title":"Rollstuhlgerechte Taxis in Colombo","content_below_type_heading":"h2","text":"<p>Leider sind die \u00f6rtlichen Taxis in Colombo nicht rollstuhlgerecht. Wenn Sie ein normales Taxi nehmen, k\u00f6nnen Sie den Rollstuhl leicht zusammenfalten und im Kofferraum des Fahrzeugs verstauen, aber in einem Tuk Tuk k\u00f6nnen Sie als Rollstuhlfahrer nicht mitfahren. Wenn Sie ein vollst\u00e4ndig rollstuhlgerechtes Taxi in Colombo ben\u00f6tigen, m\u00fcssen Sie im Voraus bei einem spezialisierten Anbieter buchen.<\/p>\n","list":false},{"title":"Taxis in Colombo: Sicherheit und Beschwerden","content_below_type_heading":"h2","text":"<p>Da es in Colombo viele verschiedene Taxi-Unternehmen gibt, die in der ganzen Stadt t\u00e4tig sind, k\u00f6nnen Service und Sicherheit stark variieren. Im Gro\u00dfen und Ganzen sind Taxifahrten in Colombo sicher, aber wenn Sie Probleme haben, sollten Sie das Unternehmen, mit dem Sie gefahren sind, direkt anrufen und eine Beschwerde einreichen. Notieren Sie sich vor dem Anruf den Namen des Fahrers, die Taxinummer und alle anderen Details Ihrer Fahrt.<\/p>\n","list":false}],"faq_2":[{"title":"Ist der Taxiservice in Colombo zuverl\u00e4ssig?","response":"<p>In der Regel ist die Fahrt mit einem \u00f6rtlichen Taxidienst in Colombo zuverl\u00e4ssig und unkompliziert. Aufgrund der vielen verschiedenen Fahrer und Unternehmen, die in der Stadt t\u00e4tig sind, kann es jedoch vorkommen, dass die Qualit\u00e4t des Services zu w\u00fcnschen \u00fcbrig l\u00e4sst. Wenn Sie einen Taxiservice in Colombo bevorzugen, der Ihnen einen 5-Sterne-Service bietet und Sie garantiert jedes Mal p\u00fcnktlich abholt, k\u00f6nnen Sie bei <a href=\"https:\/\/www.welcomepickups.com\/de\/colombo\/airport-taxi\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a> im Voraus buchen.<\/p>\n"},{"title":"Wie rufe ich in Colombo ein Taxi?","response":"<p>Es gibt viele verschiedene Taxiunternehmen in Colombo, die telefonisch erreichbar sind. Allerdings kann das Serviceniveau der einzelnen Dienste variieren. Dies sind einige der besser bewerteten Telefontaxis in Colombo:<\/p>\n<p><b>Taxi Sri Lanka<\/b> (+94 71 6299 969),<\/p>\n<p><b>TaxiGo Cab Service<\/b> (+94 77 083 3772) und<\/p>\n<p><b>Senu Cab Service<\/b> (+94 77 378 8646).<\/p>\n"},{"title":"Gibt es in Colombo offizielle Taxitarife, an die sich die Taxis halten m\u00fcssen?","response":"<p>Nein, es gibt keine offiziellen Taxitarife in Colombo. Die meisten Taxi-Unternehmen in Colombo berechnen die Fahrtkosten mit Hilfe von Taxametern, aber sie w\u00e4hlen ihre Tarife weitgehend selbst. Die durchschnittlichen Taxameter-Tarife lauten wie folgt: Grundtarif 1,14\u00a0\u20ac (100\u00a0RS) und Preis pro Meile 1,82\u00a0\u20ac (160\u00a0RS). Wenn Sie stattdessen lieber ein Taxi in Colombo zu einem Festpreis nehmen m\u00f6chten, k\u00f6nnen Sie bei <a href=\"https:\/\/www.welcomepickups.com\/de\/colombo\/airport-taxi\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a> im Voraus buchen.<\/p>\n"}],"pricing_table_header":"","pricing_table":[{"destination":"VOM FLUGHAFEN IN DIE INNENSTADT","price_day_time":"27","price_night_time":"27","time":"40 MIN."},{"destination":"VOM STRAND ZUM BAHNHOF COLOMBO FORT","price_day_time":"7,5","price_night_time":"7,5","time":"15 MIN."},{"destination":"VON DEN HOTELS ZUR LAGUNE","price_day_time":"6,75","price_night_time":"6,75","time":"13 MIN."}],"is_mozio_destination":false,"city_center_coords":false,"render_new_widget":false,"pdf_guide_url":"","download_and_read_later_title":"","below_contact_form":"","faq":false,"traveling_with_friends":false,"from_id":"","is_seo_6":false,"posts_category":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Taxi in Colombo\u00a0\u2013 Allgemeine Informationen und Tipps f\u00fcr Ihr Taxi in Colombo<\/title>\n<meta name=\"description\" content=\"Holen Sie sich n\u00fctzliche Tipps f\u00fcr Ihr Colombo-Taxi, bevor Sie in der Stadt ankommen; von Taxipreisen in Colombo bis hin zu Informationen \u00fcber private Transfers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colombo Taxi\" \/>\n<meta property=\"og:description\" content=\"Holen Sie sich n\u00fctzliche Tipps f\u00fcr Ihr Colombo-Taxi, bevor Sie in der Stadt ankommen; von Taxipreisen in Colombo bis hin zu Informationen \u00fcber private Transfers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T07:44:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"564\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/\",\"url\":\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/\",\"name\":\"Taxi in Colombo\u00a0\u2013 Allgemeine Informationen und Tipps f\u00fcr Ihr Taxi in Colombo\",\"isPartOf\":{\"@id\":\"https:\/\/www.welcomepickups.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg\",\"datePublished\":\"2023-05-18T07:26:27+00:00\",\"dateModified\":\"2023-05-18T07:44:46+00:00\",\"description\":\"Holen Sie sich n\u00fctzliche Tipps f\u00fcr Ihr Colombo-Taxi, bevor Sie in der Stadt ankommen; von Taxipreisen in Colombo bis hin zu Informationen \u00fcber private Transfers.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#primaryimage\",\"url\":\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg\",\"contentUrl\":\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg\",\"width\":1000,\"height\":564},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.welcomepickups.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colombo &#8211; Hub\",\"item\":\"https:\/\/www.welcomepickups.com\/de\/colombo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Colombo Taxi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.welcomepickups.com\/de\/#website\",\"url\":\"https:\/\/www.welcomepickups.com\/de\/\",\"name\":\"Welcome Pickups\",\"description\":\"F\u00fchlen Sie sich in jeder neuen Stadt wie zu Hause.\",\"publisher\":{\"@id\":\"https:\/\/www.welcomepickups.com\/de\/#organization\"},\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.welcomepickups.com\/de\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\/\/www.welcomepickups.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.welcomepickups.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png\",\"contentUrl\":\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\/\/www.welcomepickups.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Taxi in Colombo\u00a0\u2013 Allgemeine Informationen und Tipps f\u00fcr Ihr Taxi in Colombo","description":"Holen Sie sich n\u00fctzliche Tipps f\u00fcr Ihr Colombo-Taxi, bevor Sie in der Stadt ankommen; von Taxipreisen in Colombo bis hin zu Informationen \u00fcber private Transfers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/","og_locale":"de_DE","og_type":"article","og_title":"Colombo Taxi","og_description":"Holen Sie sich n\u00fctzliche Tipps f\u00fcr Ihr Colombo-Taxi, bevor Sie in der Stadt ankommen; von Taxipreisen in Colombo bis hin zu Informationen \u00fcber private Transfers.","og_url":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2023-05-18T07:44:46+00:00","og_image":[{"width":1000,"height":564,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/","url":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/","name":"Taxi in Colombo\u00a0\u2013 Allgemeine Informationen und Tipps f\u00fcr Ihr Taxi in Colombo","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","datePublished":"2023-05-18T07:26:27+00:00","dateModified":"2023-05-18T07:44:46+00:00","description":"Holen Sie sich n\u00fctzliche Tipps f\u00fcr Ihr Colombo-Taxi, bevor Sie in der Stadt ankommen; von Taxipreisen in Colombo bis hin zu Informationen \u00fcber private Transfers.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/shutterstock_1745929967.jpg","width":1000,"height":564},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/de\/colombo\/taxi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/de\/"},{"@type":"ListItem","position":2,"name":"Colombo &#8211; Hub","item":"https:\/\/www.welcomepickups.com\/de\/colombo\/"},{"@type":"ListItem","position":3,"name":"Colombo Taxi"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/de\/#website","url":"https:\/\/www.welcomepickups.com\/de\/","name":"Welcome Pickups","description":"F\u00fchlen Sie sich in jeder neuen Stadt wie zu Hause.","publisher":{"@id":"https:\/\/www.welcomepickups.com\/de\/#organization"},"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/de\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.welcomepickups.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages\/352617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/comments?post=352617"}],"version-history":[{"count":2,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages\/352617\/revisions"}],"predecessor-version":[{"id":354364,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages\/352617\/revisions\/354364"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages\/352539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/media\/338171"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/media?parent=352617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}