{"id":382333,"date":"2024-01-30T12:19:46","date_gmt":"2024-01-30T10:19:46","guid":{"rendered":"https:\/\/www.welcomepickups.com\/antigua\/taxi\/"},"modified":"2024-01-30T16:41:45","modified_gmt":"2024-01-30T14:41:45","slug":"taxi","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/","title":{"rendered":"Antigua Taxi"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":305881,"parent":382307,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-transfer-v1.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-382333","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"show_in_frontpage":false,"is_seo_five":false,"second_destination":false,"small_title":"","tts__title_heading":"h2","photo_captions":"","tts__title_2_heading":"h2","car_type":false,"content_below_car_title_heading":"h3","is_mozio_destination":false,"city_center_coords":false,"pdf_guide_url":"","download_and_read_later_title":"","below_contact_form":"","faq":false,"traveling_with_friends":false,"render_new_widget":false,"background":{"ID":305881,"id":305881,"title":"antigua 4","filename":"antigua-4-e1644491172707.jpeg","filesize":289275,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-e1644491172707.jpeg","link":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/attachment\/antigua-4-2\/","alt":"brightly painted wooden house with red roof, yellow front and purple windows framed by green lines","author":"176","description":"antigua","caption":"antigua","name":"antigua-4-2","status":"inherit","uploaded_to":382333,"date":"2022-02-10 11:00:33","modified":"2022-02-10 11:07:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":2400,"height":1800,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-300x225.jpeg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-768x576.jpeg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-1024x768.jpeg","large-width":960,"large-height":720,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-1536x1152.jpeg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-2048x1536.jpeg","2048x2048-width":2048,"2048x2048-height":1536,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-672x372.jpeg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-450x225.jpeg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-290x117.jpeg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-290x170.jpeg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-112x117.jpeg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-64x64.jpeg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-88x66.jpeg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-197x151.jpeg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-667x416.jpeg","first_full-width":667,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-340x188.jpeg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-1920x660.jpeg","main_hero-width":1920,"main_hero-height":660,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-200x125.jpeg","sidebar_cta-width":200,"sidebar_cta-height":125}},"cb_text":"<p>Die Suche nach einem Taxi auf Antigua k\u00f6nnte nicht einfacher sein. Taxis sind auf der ganzen Insel rund um die Uhr verf\u00fcgbar und k\u00f6nnen problemlos auf der Stra\u00dfe angehalten werden, wenn Sie sich in einer belebten Gegend befinden. Sie k\u00f6nnen auch zu Fu\u00df zu einem der vielen Taxist\u00e4nde auf Antigua gehen, die sich vor den gro\u00dfen Hotels, den H\u00e4fen, den beliebten Str\u00e4nden und dem Flughafen befinden. Sie sollten wissen, dass die Taxis auf Antigua keine einheitliche Farbe haben und sich in der Regel in Privatbesitz befinden. Daher ist es nicht ungew\u00f6hnlich, dass Sie bei Ihrer Ankunft auf der Insel einen Fahrer finden und dessen Telefonnummer behalten, um ihn w\u00e4hrend Ihres gesamten Aufenthalts zu kontaktieren.<\/p>\n<p>Wenn Sie sp\u00e4t abends unterwegs sind oder einen Service von T\u00fcr zu T\u00fcr bevorzugen, k\u00f6nnen Sie Ihr Hotel bitten, ein Taxi f\u00fcr Sie zu rufen, oder einen der \u00f6rtlichen Taxidienstleister nutzen. Einige vertrauensw\u00fcrdige Antigua-Taxifahrer sind:<\/p>\n<ul>\n<li><b>CC Tours and Taxi Services<\/b>: +1 268 720 3443<\/li>\n<li><b>Kenny Roberts: <\/b>+1 268 782 2884<\/li>\n<li><b>Barry Taxi and Tours:<\/b> +1 268 724 9119<\/li>\n<li><b>Roger Taxi Tours:<\/b> +1 268 764 6331<\/li>\n<\/ul>\n","cb_title":"Wie man auf Antigua ein Taxi bekommt","content_below_car_type":[{"title":"Vorteile, wenn Sie Ihr Taxi auf Antigua mit Welcome buchen","content_below_type_heading":"h2","text":"<p>Obwohl es in Antigua viele \u00f6rtliche Taxifahrer gibt, kann es zu Sto\u00dfzeiten passieren, dass Sie sehr lange auf Ihr Taxi warten m\u00fcssen. Wenn Sie keine kostbaren Sonnenstunden vergeuden, Ihre Reservierung f\u00fcr das Abendessen verpassen oder in einen Tropenschauer geraten m\u00f6chten, w\u00e4hrend Sie auf Ihr Taxi auf Antigua warten, empfehlen wir Ihnen, im Voraus bei Welcome Pickups zu buchen.<\/p>\n<p>Wir bieten garantiert p\u00fcnktliche Abholungen, spannende Reise-Extras, personalisierte Transfers und englischsprachige einheimische Fahrer \u2013 und das alles zu unschlagbaren Preisen. Wir k\u00fcmmern uns um alle Ihre Transferw\u00fcnsche auf Antigua, damit Sie Ihren Inselurlaub voll und ganz genie\u00dfen k\u00f6nnen.<\/p>\n","list":false},{"title":"Tipps f\u00fcr das Taxifahren auf Antigua","content_below_type_heading":"h2","text":"","list":[{"text":"Die Taxis auf Antigua k\u00f6nnen bis zu 4 Passagiere zum angegebenen Preis mitnehmen."},{"text":"Fragen Sie auf jeden Fall nach den Kosten f\u00fcr Ihre Fahrt und greifen Sie bei Bedarf auf die Tarifkarte zur\u00fcck."},{"text":"Wenn Sie Ihren Taxifahrer m\u00f6gen, k\u00f6nnen Sie ihn nach seiner Nummer fragen und seine Dienste w\u00e4hrend Ihres gesamten Aufenthalts in Anspruch nehmen."},{"text":"Auf Antigua wird ein Trinkgeld in H\u00f6he von 10-15\u00a0% f\u00fcr den Fahrer erwartet. "}]},{"title":"Rollstuhlgerechte Taxis auf Antigua","content_below_type_heading":"h2","text":"<p>Da viele der Taxis in Antigua Kombis sind, passt ein Rollstuhl in der Regel bequem hinein. Die \u00f6rtlichen Taxis sind jedoch nicht standardm\u00e4\u00dfig f\u00fcr Rollst\u00fchle ausger\u00fcstet. Wenn Sie einen spezialisierten Service suchen, bieten einige Reiseveranstalter rollstuhlgerechte Fahrzeuge an, wie <a href=\"https:\/\/www.barrytaxi.com\/\" title=\"Barry Taxi And Tours\">Barry Taxi and Tours<\/a>. Sie k\u00f6nnen online buchen oder unter der Nummer +1 678 528 4432 anrufen.<\/p>\n","list":false},{"title":"Taxis auf Antigua: Sicherheit und Beschwerden","content_below_type_heading":"h2","text":"<p>Generell ist Antigua ein sehr sicherer und gastfreundlicher Ort, und das gilt auch f\u00fcr die \u00f6rtlichen Taxifahrer. Sollten Sie jedoch bei der Fahrt mit einem Taxi auf Antigua auf Probleme sto\u00dfen, beispielsweise einen \u00fcberh\u00f6hten Preis oder einen unh\u00f6flichen Fahrer erleben, k\u00f6nnen Sie eine offizielle Beschwerde bei der Touristenpolizei unter der Nummer +502 5978 3586 einreichen.<\/p>\n<p>Es ist wichtig, dass Sie sich die Ausweisnummer des Fahrers und das Nummernschild notieren, bevor Sie Ihre Beschwerde einreichen, damit die Beh\u00f6rden den Fahrer besser finden k\u00f6nnen.<\/p>\n","list":false}],"faq_2":[{"title":"Wie viel kostet ein Taxi auf Antigua?","response":"<p>Die \u00f6rtlichen Taxifahrer in Antigua berechnen Festpreise, je nachdem, von wo aus Sie losfahren und zu welchem Reiseziel Sie m\u00f6chten. Je l\u00e4nger Ihre Reise dauert, desto teurer wird sie. Die Fahrpreise liegen in der Regel zwischen 5 und 27\u00a0\u20ac (6 bis 31\u00a0USD). Wenn Sie Ihren Fahrpreis lieber im Voraus kennen m\u00f6chten, k\u00f6nnen Sie Ihr Taxi in Antigua bei <a href=\"https:\/\/www.welcomepickups.com\/de\/antigua\/flughafentaxi\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a> im Voraus buchen.<\/p>\n"},{"title":"Wie zahlt man auf Antigua f\u00fcr Taxis?","response":"<p>Sie bezahlen Ihren Fahrer unmittelbar nach Beendigung der Fahrt f\u00fcr Ihr Taxi. Die Taxifahrer auf Antigua akzeptieren Zahlungen in US-Dollar und in Ostkaribischen Dollar.<\/p>\n"},{"title":"Sind Taxis auf Antigua sicher?","response":"<p>Ja, ein Taxi auf Antigua zu nehmen ist normalerweise sehr sicher, auch f\u00fcr Alleinreisende. Sollten Sie jedoch w\u00e4hrend Ihrer Reise auf Probleme sto\u00dfen oder sich zu irgendeinem Zeitpunkt unsicher f\u00fchlen, notieren Sie sich die Ausweisnummer Ihres Fahrers und fotografieren Sie das Nummernschild, um es der Touristenpolizei von Antigua zu melden. Sie k\u00f6nnen sie unter +502 5978 3586 erreichen.<\/p>\n"}],"pricing_table":[{"destination":"VOM FLUGHAFEN ANTIGUA NACH ST JOHN'S","price_day_time":"14","price_night_time":"14","time":"18 MIN."},{"destination":"VON ST JOHN'S ZUM YACHTHAFEN BAY BEACH","price_day_time":"10,50","price_night_time":"10,50","time":"8 MIN."},{"destination":"VOM TIEFSEEHAFEN ZUR HALBMONDBUCHT","price_day_time":"30","price_night_time":"30","time":"40 MIN."}],"subtitle":"Allgemeine Informationen und Tipps zu den Taxis auf Antigua","tts_photo":{"ID":307633,"id":307633,"title":"Antigua Taxi Sign","filename":"Antigua-Taxi-Sign.webp","filesize":171564,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign.webp","link":"https:\/\/www.welcomepickups.com\/de\/antigua\/attachment\/antigua-taxi-sign-2\/","alt":"Antigua Taxi Sign","author":"6","description":"","caption":"","name":"antigua-taxi-sign-2","status":"inherit","uploaded_to":382307,"date":"2022-02-22 17:44:55","modified":"2024-08-28 20:17:28","menu_order":0,"mime_type":"image\/webp","type":"image","subtype":"webp","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1660,"height":1568,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-150x150.webp","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-300x283.webp","medium-width":300,"medium-height":283,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-768x725.webp","medium_large-width":768,"medium_large-height":725,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-1024x967.webp","large-width":960,"large-height":907,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-1536x1451.webp","1536x1536-width":1536,"1536x1536-height":1451,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign.webp","2048x2048-width":1660,"2048x2048-height":1568,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-672x372.webp","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-450x225.webp","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-290x117.webp","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-290x170.webp","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-112x117.webp","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-64x64.webp","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-88x66.webp","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-197x151.webp","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-667x416.webp","first_full-width":667,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-340x188.webp","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-1660x660.webp","main_hero-width":1660,"main_hero-height":660,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/Antigua-Taxi-Sign-200x125.webp","sidebar_cta-width":200,"sidebar_cta-height":125}},"tts_text":"<p>Von atemberaubenden Str\u00e4nden und Yachth\u00e4fen bis hin zu faszinierenden Museen und Wanderwegen, die Ihnen atemberaubende Panoramablicke bieten, gibt es auf Antigua so viel zu erleben. Ganz gleich, ob Sie einen entspannten Urlaub in der Sonne oder eine erlebnisreiche Reise planen, ein Taxi ist auf Antigua der beste Weg, um die Insel zu erkunden. Sie k\u00f6nnen ein Taxi auf der Stra\u00dfe anhalten, telefonisch ein \u00f6rtliches Taxi bestellen, das Sie abholt, oder Sie <a href=\"https:\/\/www.welcomepickups.com\/de\/antigua\/flughafentaxi\/\" title=\"Buchen Ihre Transfers Im Voraus\">buchen Ihre Transfers im Voraus<\/a>.<\/p>\n","tts_text_2":"<p>Die \u00f6rtlichen Taxifahrer auf Antigua bieten Festpreise f\u00fcr Fahrten \u00fcber die Insel an, wobei Start- und Zielort den Preis bestimmen. Um zum Beispiel vom internationalen Flughafen V.C. Bird zum Yachthafen Bay Beach zu gelangen, m\u00fcssen Sie mit einem Taxipreis von 14\u00a0\u20ac (16\u00a0USD) rechnen, die Fahrt von St. John&#8217;s zum Galleon Beach kostet 21\u00a0\u20ac (24\u00a0USD). Die offiziellen Festpreise werden vom Verkehrsministerium von Antigua und Barbuda festgelegt und direkt von der Regierung von Antigua und Barbuda genehmigt. Eine vollst\u00e4ndige Liste der Preise und verf\u00fcgbaren Routen f\u00fcr <a href=\"https:\/\/www.antiguanice.com\/v2\/uploadsfiles\/Taxi%20and%20tour%20fares%20-%20ABTB%20final.pdf\" title=\"Taxis Auf Antigua K\u00f6nnen Sie Hier Einsehen\">Taxis auf Antigua k\u00f6nnen Sie hier einsehen<\/a>.<\/p>\n","tts_title":"Antigua Taxi","tts_title_2":"Wie hoch sind die Taxitarife auf Antigua?","title":"Antigua Taxi","heading_title":"h1","heading_subtitle":"h2","from_id":"","pricing_table_header":"","brushed_up_on":"","is_seo_6":false,"posts_category":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Taxis auf Antigua\u00a0\u2013 Preise und n\u00fctzliche Tipps zu Taxis auf Antigua<\/title>\n<meta name=\"description\" content=\"Alle Tipps, die Sie f\u00fcr Ihr Taxi auf Antigua brauchen, bevor Sie die Stadt besuchen; von Taxipreisen bis hin zu Informationen \u00fcber personalisierte Transfers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antigua Taxi\" \/>\n<meta property=\"og:description\" content=\"Alle Tipps, die Sie f\u00fcr Ihr Taxi auf Antigua brauchen, bevor Sie die Stadt besuchen; von Taxipreisen bis hin zu Informationen \u00fcber personalisierte Transfers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T14:41:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-e1644491172707.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/taxi\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/taxi\\\/\",\"name\":\"Taxis auf Antigua\u00a0\u2013 Preise und n\u00fctzliche Tipps zu Taxis auf Antigua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/taxi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/taxi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/antigua-4-e1644491172707.jpeg\",\"datePublished\":\"2024-01-30T10:19:46+00:00\",\"dateModified\":\"2024-01-30T14:41:45+00:00\",\"description\":\"Alle Tipps, die Sie f\u00fcr Ihr Taxi auf Antigua brauchen, bevor Sie die Stadt besuchen; von Taxipreisen bis hin zu Informationen \u00fcber personalisierte Transfers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/taxi\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/taxi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/taxi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/antigua-4-e1644491172707.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/antigua-4-e1644491172707.jpeg\",\"width\":2400,\"height\":1800,\"caption\":\"antigua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/taxi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antigua &#8211; Hub\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/antigua\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antigua Taxi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"F\u00fchlen Sie sich in jeder neuen Stadt wie zu Hause.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/#organization\"},\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Taxis auf Antigua\u00a0\u2013 Preise und n\u00fctzliche Tipps zu Taxis auf Antigua","description":"Alle Tipps, die Sie f\u00fcr Ihr Taxi auf Antigua brauchen, bevor Sie die Stadt besuchen; von Taxipreisen bis hin zu Informationen \u00fcber personalisierte Transfers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/","og_locale":"de_DE","og_type":"article","og_title":"Antigua Taxi","og_description":"Alle Tipps, die Sie f\u00fcr Ihr Taxi auf Antigua brauchen, bevor Sie die Stadt besuchen; von Taxipreisen bis hin zu Informationen \u00fcber personalisierte Transfers.","og_url":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2024-01-30T14:41:45+00:00","og_image":[{"width":2400,"height":1800,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-e1644491172707.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/","url":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/","name":"Taxis auf Antigua\u00a0\u2013 Preise und n\u00fctzliche Tipps zu Taxis auf Antigua","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-e1644491172707.jpeg","datePublished":"2024-01-30T10:19:46+00:00","dateModified":"2024-01-30T14:41:45+00:00","description":"Alle Tipps, die Sie f\u00fcr Ihr Taxi auf Antigua brauchen, bevor Sie die Stadt besuchen; von Taxipreisen bis hin zu Informationen \u00fcber personalisierte Transfers.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-e1644491172707.jpeg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/02\/antigua-4-e1644491172707.jpeg","width":2400,"height":1800,"caption":"antigua"},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/de\/antigua\/taxi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/de\/"},{"@type":"ListItem","position":2,"name":"Antigua &#8211; Hub","item":"https:\/\/www.welcomepickups.com\/de\/antigua\/"},{"@type":"ListItem","position":3,"name":"Antigua Taxi"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/de\/#website","url":"https:\/\/www.welcomepickups.com\/de\/","name":"Welcome Pickups","description":"F\u00fchlen Sie sich in jeder neuen Stadt wie zu Hause.","publisher":{"@id":"https:\/\/www.welcomepickups.com\/de\/#organization"},"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/de\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.welcomepickups.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages\/382333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/comments?post=382333"}],"version-history":[{"count":3,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages\/382333\/revisions"}],"predecessor-version":[{"id":392946,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages\/382333\/revisions\/392946"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/pages\/382307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/media\/305881"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/de\/wp-json\/wp\/v2\/media?parent=382333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}