{"id":292169,"date":"2023-10-25T14:11:58","date_gmt":"2023-10-25T12:11:58","guid":{"rendered":"https:\/\/www.welcomepickups.com\/?page_id=292169"},"modified":"2023-11-08T18:05:59","modified_gmt":"2023-11-08T16:05:59","slug":"aeropuerto-a-ciudad","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/","title":{"rendered":"Opciones de transporte desde el aeropuerto de San Francisco al centro urbano"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":68,"featured_media":373031,"parent":292151,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-v4.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-292169","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"flat_price_1_value":"","flat_price_2_value":"","from_id":"329074","to_id":"","posts_category":false,"to":"","detailed_comparison_title":"","detailed_comparison_subtitle":"","welcome_image":false,"taxi_image":false,"welcome_title":"","welcome_content":"","render_new_widget":false,"safety_widget_title":"","safety_widget_subtitle":"","breadcrumbs":[{"title":"Welcome Pickups","link":"https:\/\/www.welcomepickups.com\/es\/"},{"title":"San Francisco","link":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/"},{"title":"Del aeropuerto de San Francisco al centro de la ciudad","link":""}],"faq":[{"question":"\u00bfC\u00f3mo llego al centro de la ciudad desde el aeropuerto de San Francisco?","answer":"<p>Para desplazarte desde el aeropuerto puedes tomar un taxi, un traslado privado, el metro o el autob\u00fas.<\/p>\n"},{"question":"\u00bfCu\u00e1nto cuesta un taxi del aeropuerto de San Francisco a Union Square?","answer":"<p>El recorrido en taxi desde el aeropuerto de San Francisco hasta la Union Square cuesta unos 56\u00a0$ (51\u00a0\u20ac). Si quieres viajar con una tarifa fija, puedes reservar un traslado privado por adelantado.<\/p>\n"},{"question":"\u00bfA cu\u00e1nto est\u00e1 Fisherman's Wharf del aeropuerto de San Francisco?","answer":"<p>Fisherman&#8217;s Wharf est\u00e1 a 25\u00a0km al norte del aeropuerto de San Francisco.<\/p>\n"},{"question":"\u00bfSe puede ir en BART desde el aeropuerto hasta Union Square?","answer":"<p>El BART del aeropuerto de San Francisco llega hasta las estaciones de Civic Centre y Powell Street, muy cerca de Union Square en el centro de San Francisco.<\/p>\n"}],"from":"Aeropuerto de San Francisco (SFO)","header_picture":{"ID":248964,"id":248964,"title":"san francisco - city","filename":"golden-gate-bridge-1081782_640.jpg","filesize":59262,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640.jpg","link":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/attachment\/golden-gate-bridge-1081782_640-2\/","alt":"","author":"68","description":"All You Need to Know About Transportation from San Francisco Airport to Golden Gate Bridge - Best Options from SFO to the Golden Gate Bridge.","caption":"","name":"golden-gate-bridge-1081782_640-2","status":"inherit","uploaded_to":292169,"date":"2020-01-25 12:10:43","modified":"2025-08-21 16:01:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":640,"height":426,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640.jpg","medium_large-width":640,"medium_large-height":426,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640.jpg","large-width":640,"large-height":426,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640.jpg","1536x1536-width":640,"1536x1536-height":426,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640.jpg","2048x2048-width":640,"2048x2048-height":426,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-640x372.jpg","post-thumbnail-width":640,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-450x225.jpg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-290x117.jpg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-290x170.jpg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-112x117.jpg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-64x64.jpg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-88x66.jpg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-197x151.jpg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-640x416.jpg","first_full-width":640,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-340x188.jpg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640.jpg","main_hero-width":640,"main_hero-height":426,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2020\/01\/golden-gate-bridge-1081782_640-200x125.jpg","sidebar_cta-width":200,"sidebar_cta-height":125}},"line_above_title":"LAS MEJORES GU\u00cdAS DE TRASPORTE EN EL AEROPUERTO","title_line":"C\u00f3mo llegar al centro de la ciudad desde el aeropuerto de San Francisco","transportation_means":[{"name":"Welcome Pickups","title_line":"","top_description":"","fares":"","trip_duration":"","line_below_price_and_time":"","perks":false,"availability":"","middle_description_title":"","middle_description":"","middle_2_description_title":"","middle_2_description":"","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"","bottom_description":"","bottom_description_rating":"4","timetables":false,"editors_note":"","useful_tips":false,"photos":false,"gallery_subline":"","infographics_only":true,"price_per_passenger_1":"64","price_per_passenger_2":"64","price_per_passenger_3":"64","price_per_passenger_4":"85","price_per_passenger_5":"85","price_per_passenger_6":"149","price_per_passenger_7":"149","price_per_passenger_8":"149","price_per_passenger_9":"170","price_per_passenger_10":"170","price_per_passenger_11":"234","price_per_passenger_12":"234","waiting_duration":"0","traveling_duration":"35","availability_from":"","availability_until":"","availability_picture":false,"is_247":true,"plot_color":"taxi","pricing_table_header":"","pricing_table_":false},{"name":"Taxi o traslado privado en minib\u00fas","title_line":"C\u00f3mo llegar al centro de la ciudad desde el aeropuerto de San Francisco en taxi o en traslado privado en minib\u00fas.","top_description":"<p>Los taxis y <a href=\"https:\/\/www.welcomepickups.com\/es\/san-francisco\/taxi-aeropuerto\/\" title=\"Los Veh\u00edculos De Traslado Privado Del Aeropuerto De San Francisco\">los veh\u00edculos de traslado privado del aeropuerto de San Francisco<\/a> est\u00e1n disponibles 24\/7. Para tomar un taxi desde el aeropuerto de San Francisco (SFO) hasta el centro urbano tienes que caminar hasta el nivel de llegadas\/recogida de equipaje de cualquiera de las terminales del aeropuerto. Los taxis en el SFO funcionan con tax\u00edmetro, por lo que la tarifa depende del tiempo y la distancia recorrida. En cualquier caso, el precio estimado para una carrera con hasta 5 pasajeros hasta la mayor\u00eda de puntos en el centro de la ciudad, incluida Union Square, es de 56\u00a0$ (51\u00a0\u20ac). Si quieres viajar con una tarifa fija, puedes reservar con antelaci\u00f3n un traslado privado y evitarte molestias o costes ocultos. Tanto los taxis como los traslados privados tardan unos 35 minutos desde el aeropuerto SFO hasta el centro urbano.<\/p>\n","fares":"\u20ac51","trip_duration":"35 Min.","line_below_price_and_time":"*En hora punta, la duraci\u00f3n del viaje se puede alargar hasta una hora o m\u00e1s, dependiendo del destino final exacto al que te dirijas en el centro de San Francisco.","perks":[{"perk":"Comodidad","rating":"5"},{"perk":"Seguridad","rating":"5"},{"perk":"Relaci\u00f3n calidad-precio","rating":"4"}],"availability":"En el aeropuerto de San Francisco puedes tomar un taxi o un traslado privado disponibles 24\/7.","middle_description_title":"Precio del taxi del aeropuerto de San Francisco al centro de la ciudad","middle_description":"<p>Un taxi desde el aeropuerto hasta el centro de San Francisco cuesta unos 56\u00a0$ (51\u00a0\u20ac) para un recorrido con hasta 5 pasajeros. Los taxis funcionan con tax\u00edmetro, por lo que el coste final depender\u00e1 del tiempo empleado y la distancia recorrida. Ten en cuenta que se te sumar\u00e1 un coste adicional de 4\u00a0$ (3,60\u00a0\u20ac) que se aplica a todos los taxis que salen del aeropuerto SFO. Sin embargo, si reservas un traslado privado con antelaci\u00f3n te puedes asegurar un precio fijo, independientemente de la duraci\u00f3n del viaje, con recogidas a tiempo y sin esperas en las paradas del taxi.<\/p>\n","middle_2_description_title":"\u00bfEn d\u00f3nde lo puedo tomar?","middle_2_description":"<p>Los taxis del aeropuerto de San Francisco est\u00e1n situados en las paradas designadas en el nivel de llegadas\/recogida de equipaje del aeropuerto. Hay zonas de parada de taxi en todas las terminales del SFO (T1, T2, T3). Sigue las se\u00f1ales y dir\u00edgete hacia las isletas del centro de la calzada para tomar un taxi. Si has reservado un traslado privado por adelantado, tu conductor estar\u00e1 esper\u00e1ndote a la salida de la sala de llegadas, sujetando un cartel con tu nombre.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Comodidad","bottom_description":"<p>Tanto el taxi como el traslado privado son alternativas realmente c\u00f3modas para desplazarte hasta el centro de San Francisco, donde puedes visitar Union Square, el Civic Center y otros atractivos que te ofrece la ciudad. En el aeropuerto siempre hay taxis y veh\u00edculos para el traslado privado disponibles y que te ofrecen un servicio puerta a puerta. Tanto los taxis como los veh\u00edculos de traslado privado se pueden compartir entre 5 pasajeros, lo que ayuda a reducir el precio por persona.<\/p>\n","bottom_description_rating":"3","timetables":[{"title":"Tarifas de taxi","description":"Aeropuerto de San Francisco","view_more_url":"https:\/\/www.flysfo.com\/to-from\/ground-transportation"}],"editors_note":"De 7:00 a 01:00 ver\u00e1s que en las zonas de parada de taxis del SFO hay coordinadores de taxis uniformados para ayudarte a encontrar un taxi y organizar tu viaje.","useful_tips":[{"tip":"Los taxis que funcionan a trav\u00e9s de aplicaciones m\u00f3viles tienen puntos de recogida diferentes a los de los taxis convencionales del aeropuerto."},{"tip":"Si buscas la experiencia de viaje m\u00e1s agradable, te recomendamos que reserves un traslado privado por adelantado."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"51","price_per_passenger_2":"51","price_per_passenger_3":"51","price_per_passenger_4":"51","price_per_passenger_5":"51","price_per_passenger_6":"102","price_per_passenger_7":"102","price_per_passenger_8":"102","price_per_passenger_9":"102","price_per_passenger_10":"102","price_per_passenger_11":"153","price_per_passenger_12":"153","waiting_duration":"10","traveling_duration":"35","availability_from":"","availability_until":"","availability_picture":{"ID":129126,"id":129126,"title":"icn-rankings-taxi","filename":"icn-rankings-taxi.svg","filesize":3270,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","link":"https:\/\/www.welcomepickups.com\/es\/paris\/aeropuerto-orly-a-ciudad\/attachment\/icn-rankings-taxi-2\/","alt":"icn-rankings-taxi","author":"1","description":"","caption":"","name":"icn-rankings-taxi-2","status":"inherit","uploaded_to":534709,"date":"2017-06-14 15:41:30","modified":"2020-11-02 14:46:50","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","2048x2048-width":1,"2048x2048-height":1,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","post-thumbnail-width":1,"post-thumbnail-height":1,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","slider-thumb-width":1,"slider-thumb-height":1,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","v3_gallery_1-width":1,"v3_gallery_1-height":1,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","v3_gallery_3-width":1,"v3_gallery_3-height":1,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","v3_gallery_2-width":1,"v3_gallery_2-height":1,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","sidebar_1-width":1,"sidebar_1-height":1,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","sidebar_2-width":1,"sidebar_2-height":1,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","sidebar_3-width":1,"sidebar_3-height":1,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","first_full-width":1,"first_full-height":1,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","main_thumbnail-width":1,"main_thumbnail-height":1,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","main_hero-width":1,"main_hero-height":1,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","sidebar_cta-width":1,"sidebar_cta-height":1}},"is_247":true,"plot_color":"train","pricing_table_header":"","pricing_table_":[{"destination":"DESDE SFO AL CENTRO URBANO DE SAN FRANCISCO","price_day_time":"51","price_night_time":"51","time":"35"},{"destination":"DE SFO A HOTELES EN EL CENTRO DE LA CIUDAD","price_day_time":"51","price_night_time":"51","time":"35"},{"destination":"DESDE SFO A UNION SQUARE","price_day_time":"51","price_night_time":"51","time":"35"},{"destination":"DESDE SFO A NAPA VALLEY","price_day_time":"180","price_night_time":"180","time":"120"},{"destination":"DESDE SFO A SAN JOS\u00c9","price_day_time":"68","price_night_time":"68","time":"50"}]},{"name":"Metro","title_line":"C\u00f3mo llegar del aeropuerto de San Francisco al centro de la ciudad en metro","top_description":"<p>Trasladarse en metro desde el aeropuerto de San Francisco hasta el centro de la ciudad es una opci\u00f3n c\u00f3moda y barata. El sistema de metro BART opera todos los d\u00edas y para en la terminal internacional del aeropuerto cada 15 o 20 minutos. Toma la l\u00ednea amarilla en direcci\u00f3n Antioch y b\u00e1jate en la estaci\u00f3n Civic Center o en la de Powell Street, ambas a unos pasos de Union Square y el resto del centro neur\u00e1lgico de San Francisco. El viaje dura 27 minutos y el billete simple cuesta 9,6\u00a0$ (8,75\u00a0\u20ac).<\/p>\n","fares":"\u20ac8.75","trip_duration":"27 Min.","line_below_price_and_time":"*El tren pasa cada 15 minutos de lunes a viernes y cada 20 minutos los s\u00e1bados y domingos.","perks":[{"perk":"Comodidad","rating":"4"},{"perk":"Seguridad","rating":"5"},{"perk":"Relaci\u00f3n calidad-precio","rating":"5"}],"availability":"La l\u00ednea amarilla de metro BART opera en el aeropuerto de San Francisco de lunes a viernes de 05:11 a 23:54, los s\u00e1bados de 06:07 a 23:54 y los domingos de 08:17 a 23:56.","middle_description_title":"\u00bfCu\u00e1nto cuesta el metro desde el aeropuerto SFO hasta el centro de San Francisco?","middle_description":"<p>Un billete de metro simple hasta el centro de San Francisco cuesta 9,65\u00a0$ (8,75\u00a0\u20ac). Puedes comprar el billete al centro en las m\u00e1quinas de venta autom\u00e1tica de la estaci\u00f3n del BART del aeropuerto y se puede pagar en met\u00e1lico o con tarjeta.<\/p>\n","middle_2_description_title":"\u00bfEn d\u00f3nde lo puedo tomar?","middle_2_description":"<p>Para tomar la l\u00ednea amarilla del Bay Area Rapid Transit tienes que llegar hasta la terminal internacional del SFO y simplemente seguir las indicaciones hasta la estaci\u00f3n del BART. Para ir al centro de la ciudad, tienes que tomar el tren en direcci\u00f3n Antioch y bajarte en 9 paradas.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Comodidad","bottom_description":"<p>El BART es una forma bastante c\u00f3moda de trasladarse hasta el centro de San Francisco y con un acceso relativamente f\u00e1cil hasta Union Square. Tan solo tienes que caminar hasta el hotel desde la estaci\u00f3n Civic Center o desde la de Powell Street. Aparte de esto, recuerda que pasada la media noche no hay servicio de metro al centro de la ciudad.<\/p>\n","bottom_description_rating":"2","timetables":[{"title":"Billetes y tarifas del metro","description":"Aeropuerto de San Francisco","view_more_url":"https:\/\/www.bart.gov\/tickets\/calculator"},{"title":"Horarios y rutas del metro","description":"Aeropuerto de San Francisco","view_more_url":"https:\/\/www.bart.gov\/schedules\/bystation"}],"editors_note":"Si no aterrizas en la terminal internacional y quieres ir a la estaci\u00f3n del BART, puedes hacerlo de forma gratuita en el Air Train del aeropuerto. El Air Train circula alrededor del aeropuerto de San Francisco. Como alternativa, si no llevas demasiado equipaje puedes ir tambi\u00e9n caminando hasta la terminal internacional.","useful_tips":[{"tip":" Los ni\u00f1os hasta 4 a\u00f1os no necesitan billete porque el metro es gratuito para ellos."},{"tip":"Hay otras opciones de billetes y tarjetas disponibles si planeas usar el sistema de metro con frecuencia durante tu estancia en San Francisco."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"8.75","price_per_passenger_2":"17.5","price_per_passenger_3":"26.25","price_per_passenger_4":"35","price_per_passenger_5":"43.75","price_per_passenger_6":"52.5","price_per_passenger_7":"61.25","price_per_passenger_8":"70","price_per_passenger_9":"78.75","price_per_passenger_10":"87.5","price_per_passenger_11":"96.25","price_per_passenger_12":"105","waiting_duration":"18","traveling_duration":"27","availability_from":"05:11","availability_until":"23:56","availability_picture":{"ID":129162,"id":129162,"title":"icn-rankings-metro","filename":"icn-rankings-metro.svg","filesize":3462,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","link":"https:\/\/www.welcomepickups.com\/es\/paris\/aeropuerto-orly-a-ciudad\/attachment\/icn-rankings-metro-2\/","alt":"icn-rankings-metro","author":"1","description":"","caption":"","name":"icn-rankings-metro-2","status":"inherit","uploaded_to":534709,"date":"2017-06-14 15:41:31","modified":"2020-11-17 10:00:19","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","2048x2048-width":1,"2048x2048-height":1,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","post-thumbnail-width":1,"post-thumbnail-height":1,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","slider-thumb-width":1,"slider-thumb-height":1,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","v3_gallery_1-width":1,"v3_gallery_1-height":1,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","v3_gallery_3-width":1,"v3_gallery_3-height":1,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","v3_gallery_2-width":1,"v3_gallery_2-height":1,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","sidebar_1-width":1,"sidebar_1-height":1,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","sidebar_2-width":1,"sidebar_2-height":1,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","sidebar_3-width":1,"sidebar_3-height":1,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","first_full-width":1,"first_full-height":1,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","main_thumbnail-width":1,"main_thumbnail-height":1,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","main_hero-width":1,"main_hero-height":1,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-metro.svg","sidebar_cta-width":1,"sidebar_cta-height":1}},"is_247":false,"plot_color":"bus","pricing_table_header":"","pricing_table_":false},{"name":"Autob\u00fas","title_line":"C\u00f3mo llegar al centro de la ciudad desde el aeropuerto de San Francisco en autob\u00fas","top_description":"<p>Hay dos l\u00edneas de autob\u00fas que unen el aeropuerto de San Francisco con el centro urbano: la 292 y la 398. El autob\u00fas 292 llega a Market Street y el 398 a Mission Street, ambos muy cerca de Union Square. El viaje suele durar una media de 75 minutos tanto en uno como en el otro, pero el 292 opera con m\u00e1s frecuencia que el 398. El 292 para cada 27 minutos y el 398 cada 57 minutos.<\/p>\n","fares":"\u20ac2","trip_duration":"75 Min.","line_below_price_and_time":"*Los autobuses operan con menos frecuencia los fines de semana y a altas horas de la noche.","perks":[{"perk":"Comodidad","rating":"3"},{"perk":"Seguridad","rating":"5"},{"perk":"Relaci\u00f3n calidad-precio","rating":"5"}],"availability":"El autob\u00fas 292 opera de lunes a viernes de 04:30 a 01:40, los s\u00e1bados de 04:30 a 01:32 y los domingos de 04:30 a 01:22. El autob\u00fas 398 opera de lunes a viernes de 05:48 a 22:36, los s\u00e1bados de 06:34 a 22:26 y los domingos de 05:42 a 21:44.","middle_description_title":"\u00bfCu\u00e1nto cuesta el autob\u00fas del aeropuerto de San Francisco al centro de la ciudad?","middle_description":"<p>El billete de autob\u00fas desde el aeropuerto internacional hasta el centro de San Francisco cuesta 2,25\u00a0$ (2\u00a0\u20ac). Puedes comprarlo a bordo del autob\u00fas pag\u00e1ndolo en met\u00e1lico, con una Clipper Card o a trav\u00e9s de la aplicaci\u00f3n m\u00f3vil samTrans.<\/p>\n","middle_2_description_title":"\u00bfEn d\u00f3nde lo puedo tomar?","middle_2_description":"<p>Para tomar el autob\u00fas 292, tienes que dirigirte al patio A del nivel inferior de llegadas de la terminal 1, a la isleta central de la terminal 2 y a la acera en la terminal 3. En el aeropuerto de San Francisco hay indicaciones para guiarte hasta las paradas del autob\u00fas.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Comodidad","bottom_description":"<p>El autob\u00fas hasta el centro de San Francisco no es la forma de transporte m\u00e1s c\u00f3moda porque no pasa con tanta frecuencia como el metro y el viaje dura m\u00e1s. Se tarda 75 minutos en ir desde el aeropuerto de San Francisco hasta el centro de la ciudad en autob\u00fas. La duraci\u00f3n del trayecto depende del tr\u00e1fico, por lo que puede tardar a\u00fan m\u00e1s si la situaci\u00f3n del tr\u00e1fico es peor de lo habitual.<\/p>\n","bottom_description_rating":"3","timetables":[{"title":"Billetes y tarifas del autob\u00fas","description":"Aeropuerto de San Francisco","view_more_url":"http:\/\/www.samtrans.com\/fares\/farechart.html"},{"title":"Horario de la ruta 292","description":"Aeropuerto de San Francisco","view_more_url":"http:\/\/www.samtrans.com\/schedulesandmaps\/timetables\/292.html"},{"title":"Horario de la ruta 398","description":"Aeropuerto de San Francisco","view_more_url":"http:\/\/www.samtrans.com\/schedulesandmaps\/timetables\/398.html"}],"editors_note":"Hay m\u00e1s autobuses a distintos destinos tanto en el centro como en las afueras de San Francisco. Tambi\u00e9n puedes hacer trasbordos si te conviene seg\u00fan tu itinerario.","useful_tips":[{"tip":"Quiz\u00e1 te interesa comprar una Clipper Card para la red de autobuses de San Francisco que ofrece tarifas reducidas."},{"tip":"Desde la parada del autob\u00fas, son solo unos 10 minutos caminando hasta Union Square."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"2","price_per_passenger_2":"4","price_per_passenger_3":"6","price_per_passenger_4":"8","price_per_passenger_5":"10","price_per_passenger_6":"12","price_per_passenger_7":"14","price_per_passenger_8":"16","price_per_passenger_9":"18","price_per_passenger_10":"20","price_per_passenger_11":"22","price_per_passenger_12":"24","waiting_duration":"27","traveling_duration":"75","availability_from":"04:30","availability_until":"01:40","availability_picture":{"ID":129198,"id":129198,"title":"icn-rankings-bus","filename":"icn-rankings-bus.svg","filesize":2526,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","link":"https:\/\/www.welcomepickups.com\/es\/barcelona\/aeropuerto-a-ciudad\/attachment\/icn-rankings-bus-2\/","alt":"icn-rankings-bus","author":"1","description":"","caption":"","name":"icn-rankings-bus-2","status":"inherit","uploaded_to":8954,"date":"2017-06-14 15:41:32","modified":"2017-06-14 15:41:32","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","2048x2048-width":1,"2048x2048-height":1,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","post-thumbnail-width":1,"post-thumbnail-height":1,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","slider-thumb-width":1,"slider-thumb-height":1,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","v3_gallery_1-width":1,"v3_gallery_1-height":1,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","v3_gallery_3-width":1,"v3_gallery_3-height":1,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","v3_gallery_2-width":1,"v3_gallery_2-height":1,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","sidebar_1-width":1,"sidebar_1-height":1,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","sidebar_2-width":1,"sidebar_2-height":1,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","sidebar_3-width":1,"sidebar_3-height":1,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","first_full-width":1,"first_full-height":1,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","main_thumbnail-width":1,"main_thumbnail-height":1,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","main_hero-width":1,"main_hero-height":1,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","sidebar_cta-width":1,"sidebar_cta-height":1}},"is_247":false,"plot_color":"bus","pricing_table_header":"","pricing_table_":false}],"description":"<p>El aeropuerto internacional de San Francisco (SFO) es el m\u00e1s grande y uno de los cuatro aeropuertos situados en el \u00e1rea de la bah\u00eda de San Francisco. Est\u00e1 ubicado a 20\u00a0km al sur del centro de San Francisco. Una vez en el SFO, hay 4 formas de desplazarse hasta el centro urbano y Union Square. Puedes tomar un taxi, un traslado privado, el metro o el autob\u00fas.<\/p>\n<p>Los taxis y los traslados privados operan 24\/7 desde el aeropuerto de San Francisco y el tiempo de viaje hasta la ciudad es de unos 35 minutos. Si prefieres ir en metro, puedes tomar la l\u00ednea amarilla del Bay Area Rapid Transit (BART). Los trenes pasan por la estaci\u00f3n del aeropuerto cada 18 minutos m\u00e1s o menos. El autob\u00fas es la \u00faltima opci\u00f3n para un servicio directo hasta Union Square en San Francisco centro. Las l\u00edneas de autob\u00fas 292 y 398 operan todos los d\u00edas y el trayecto hasta el centro de San Francisco suele durar 1 hora y 15 minutos. Aparte de esto, tambi\u00e9n hay traslados privados en minib\u00fas hasta el centro de San Francisco, pero no se trata de un servicio programado y tienes que reservarlo con antelaci\u00f3n.<\/p>\n","main_title":"Opciones de transporte desde el aeropuerto de San Francisco al centro urbano","brushed_up_on":"","is_seo_2":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u2708 Ir del aeropuerto de San Francisco al centro de la ciudad con Welcome Pickups<\/title>\n<meta name=\"description\" content=\"Tu transporte del aeropuerto de San Francisco. Compara todas las opciones de transporte disponibles desde el aeropuerto de San Francisco hasta el centro con Welcome Pickups.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opciones de transporte desde el aeropuerto de San Francisco al centro urbano\" \/>\n<meta property=\"og:description\" content=\"Tu transporte del aeropuerto de San Francisco. Compara todas las opciones de transporte disponibles desde el aeropuerto de San Francisco hasta el centro con Welcome Pickups.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-08T16:05:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/San-Francisco-United-States-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/aeropuerto-a-ciudad\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/aeropuerto-a-ciudad\\\/\",\"name\":\"\u2708 Ir del aeropuerto de San Francisco al centro de la ciudad con Welcome Pickups\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/aeropuerto-a-ciudad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/aeropuerto-a-ciudad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/San-Francisco-United-States-.jpeg\",\"datePublished\":\"2023-10-25T12:11:58+00:00\",\"dateModified\":\"2023-11-08T16:05:59+00:00\",\"description\":\"Tu transporte del aeropuerto de San Francisco. Compara todas las opciones de transporte disponibles desde el aeropuerto de San Francisco hasta el centro con Welcome Pickups.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/aeropuerto-a-ciudad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/aeropuerto-a-ciudad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/aeropuerto-a-ciudad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/San-Francisco-United-States-.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/San-Francisco-United-States-.jpeg\",\"width\":1920,\"height\":1280,\"caption\":\"San Francisco, United States\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/aeropuerto-a-ciudad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Francisco &#8211; Hub\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/san-francisco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Opciones de transporte desde el aeropuerto de San Francisco al centro urbano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u2708 Ir del aeropuerto de San Francisco al centro de la ciudad con Welcome Pickups","description":"Tu transporte del aeropuerto de San Francisco. Compara todas las opciones de transporte disponibles desde el aeropuerto de San Francisco hasta el centro con Welcome Pickups.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/","og_locale":"es_ES","og_type":"article","og_title":"Opciones de transporte desde el aeropuerto de San Francisco al centro urbano","og_description":"Tu transporte del aeropuerto de San Francisco. Compara todas las opciones de transporte disponibles desde el aeropuerto de San Francisco hasta el centro con Welcome Pickups.","og_url":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2023-11-08T16:05:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/San-Francisco-United-States-.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/","url":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/","name":"\u2708 Ir del aeropuerto de San Francisco al centro de la ciudad con Welcome Pickups","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/San-Francisco-United-States-.jpeg","datePublished":"2023-10-25T12:11:58+00:00","dateModified":"2023-11-08T16:05:59+00:00","description":"Tu transporte del aeropuerto de San Francisco. Compara todas las opciones de transporte disponibles desde el aeropuerto de San Francisco hasta el centro con Welcome Pickups.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/San-Francisco-United-States-.jpeg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/San-Francisco-United-States-.jpeg","width":1920,"height":1280,"caption":"San Francisco, United States"},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/aeropuerto-a-ciudad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/es\/"},{"@type":"ListItem","position":2,"name":"San Francisco &#8211; Hub","item":"https:\/\/www.welcomepickups.com\/es\/san-francisco\/"},{"@type":"ListItem","position":3,"name":"Opciones de transporte desde el aeropuerto de San Francisco al centro urbano"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/es\/#website","url":"https:\/\/www.welcomepickups.com\/es\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/es\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/es\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.welcomepickups.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/292169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/comments?post=292169"}],"version-history":[{"count":4,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/292169\/revisions"}],"predecessor-version":[{"id":381167,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/292169\/revisions\/381167"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/292151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/media\/373031"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/media?parent=292169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}