{"id":352267,"date":"2023-05-25T10:04:54","date_gmt":"2023-05-25T08:04:54","guid":{"rendered":"https:\/\/www.welcomepickups.com\/colombo\/airport-to-negombo\/"},"modified":"2023-05-25T19:36:30","modified_gmt":"2023-05-25T17:36:30","slug":"aeropuerto-a-negombo","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/","title":{"rendered":"C\u00f3mo llegar del Aeropuerto de Colombo a Negombo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":338203,"parent":351676,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-v61.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-352267","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"main_title":"C\u00f3mo llegar del Aeropuerto de Colombo a Negombo","from":"Aeropuerto Internacional Bandaranaike (CMB)","to":"","header_picture":{"ID":338203,"id":338203,"title":"Negombo, Sri Lanka","filename":"Negombo-Sri-Lanka.jpeg","filesize":312889,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka.jpeg","link":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/attachment\/negombo-sri-lanka-2\/","alt":"","author":"176","description":"","caption":"","name":"negombo-sri-lanka-2","status":"inherit","uploaded_to":352267,"date":"2022-12-28 16:13:53","modified":"2022-12-28 16:13:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-300x200.jpeg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-768x512.jpeg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-1024x683.jpeg","large-width":960,"large-height":640,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-1536x1024.jpeg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka.jpeg","2048x2048-width":1920,"2048x2048-height":1280,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-672x372.jpeg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-450x225.jpeg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-290x117.jpeg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-290x170.jpeg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-112x117.jpeg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-64x64.jpeg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-88x66.jpeg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-197x151.jpeg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-667x416.jpeg","first_full-width":667,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-340x188.jpeg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-1920x660.jpeg","main_hero-width":1920,"main_hero-height":660,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka-200x125.jpeg","sidebar_cta-width":200,"sidebar_cta-height":125}},"line_above_title":"LAS MEJORES GU\u00cdAS DE TRASPORTE AL AEROPUERTO","title_line":"C\u00f3mo llegar del Aeropuerto de Colombo a Negombo","description":"<p>Negombo es una pintoresca ciudad mar\u00edtima ubicada en la costa occidental de Sri Lanka. Negombo tiene dos zonas distintivas, el centro bullicioso y una tranquila franja de playas, en donde se encuentran la mayor\u00eda de hoteles y complejos tur\u00edsticos. Aseg\u00farate de visitar la Laguna de Negombo y el impresionante fuerte holand\u00e9s del siglo XVII durante tu estad\u00eda. Existen dos opciones de traslado para viajar del Aeropuerto de Colombo a Negombo: en taxi o en autob\u00fas. Si tomas un <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Taxi Desde El Aeropuerto De Colombo\">taxi desde el Aeropuerto de Colombo<\/a> hacia Negombo, tardar\u00e1s \u00fanicamente 15 minutos en llegar, por lo que es la opci\u00f3n m\u00e1s r\u00e1pida, pero te costar\u00e1 unos \u20ac5 (LKR 2.000). Por otro lado, tomar el autob\u00fas local te costar\u00e1 s\u00f3lo \u20ac0,20 euros (LKR 70) por trayecto, pero tardar\u00e1s cerca de 40 minutos en llegar a Negombo.<\/p>\n","transportation_means":[{"name":"Welcome Pickups","title_line":"","top_description":"","fares":"","trip_duration":"","line_below_price_and_time":"","perks":false,"availability":"","middle_description_title":"","middle_description":"","middle_2_description_title":"","middle_2_description":"","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"","bottom_description":"","bottom_description_rating":"5","timetables":false,"editors_note":"","useful_tips":false,"photos":false,"gallery_subline":"","infographics_only":true,"price_per_passenger_1":"14","price_per_passenger_2":"14","price_per_passenger_3":"14","price_per_passenger_4":"27","price_per_passenger_5":"27","price_per_passenger_6":"27","price_per_passenger_7":"42","price_per_passenger_8":"42","price_per_passenger_9":"42","price_per_passenger_10":"42","price_per_passenger_11":"42","price_per_passenger_12":"42","waiting_duration":"0","traveling_duration":"15","availability_from":"","availability_until":"","availability_picture":false,"is_247":true,"plot_color":"welcome","pricing_table_header":"","pricing_table_":false},{"name":"Taxi","title_line":"C\u00f3mo tomar un Taxi del Aeropuerto de Colombo a Negombo","top_description":"<p>La forma m\u00e1s r\u00e1pida de recorrer el trayecto desde el Aeropuerto de Colombo a Negombo es tomando un <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Taxi Del Aeropuerto\">taxi del aeropuerto<\/a>. El trayecto ser\u00e1 de unos r\u00e1pidos 15 minutos y el costo de un taxi local del Aeropuerto de Colombo a Negombo rondar\u00e1 los \u20ac5 (LKR 2.000), lo que resulta muy econ\u00f3mico.<\/p>\n","fares":"\u20ac5 (LKR 2.000)","trip_duration":"15 min.","line_below_price_and_time":"*Los precios pueden variar si no reservas con antelaci\u00f3n.","perks":[{"perk":"Comodidad","rating":"5"},{"perk":"Seguridad","rating":"5"},{"perk":"Relaci\u00f3n calidad-precio","rating":"5"}],"availability":"Hay taxis disponibles fuera del Aeropuerto de Colombo las 24 horas del d\u00eda.","middle_description_title":"\u00bfCu\u00e1nto cuesta un taxi del Aeropuerto de Colombo a Negombo?","middle_description":"<p>Un taxi local del Aeropuerto de Colombo a Negombo te costar\u00e1 unos \u20ac5 (LKR 2.000). Sin embargo, esta no es una tarifa fija. Tu conductor utilizar\u00e1 un tax\u00edmetro para calcular el costo de tu viaje a Negombo, por lo que \u00e9ste puede aumentar. Si prefieres la tranquilidad de asegurar una tarifa fija, te sugerimos que reserves su trayecto con <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a> con antelaci\u00f3n.<\/p>\n","middle_2_description_title":"\u00bfD\u00f3nde encuentro un taxi en el Aeropuerto de Colombo?","middle_2_description":"<p>Es f\u00e1cil encontrar taxis fuera de la terminal principal del Aeropuerto de Colombo. En tanto salgas del de la zona de llegadas, ver\u00e1s la fila de taxis esperando en la parada.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Comodidad","bottom_description":"<p>Tomar un taxi desde el Aeropuerto de Colombo a Negombo es la forma m\u00e1s f\u00e1cil y r\u00e1pida de viajar. El transporte p\u00fablico s\u00f3lo te dejar\u00e1 en el centro de Negombo, as\u00ed que si te alojas en la zona de la playa, tomar un taxi es la \u00fanica forma de llegar directamente a la puerta de tu hotel.<\/p>\n","bottom_description_rating":"5","timetables":false,"editors_note":"Los taxis en Sri Lanka son muy asequibles, sin embargo, puedes reducir a\u00fan m\u00e1s el costo de tu trayecto en taxi desde el Aeropuerto de Colombo a Negombo dividi\u00e9ndolo con otros miembros de tu grupo.","useful_tips":[{"tip":"Si lo deseas, puedes intentar negociar una tarifa fija con tu conductor antes de salir del aeropuerto."},{"tip":"Un taxi convencional del Aeropuerto de Colombo puede llevar hasta 4 pasajeros."},{"tip":"Aseg\u00farate de llevar efectivo en la moneda local para pagar el taxi, ya que los conductores no aceptan pagos con tarjeta."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"5","price_per_passenger_2":"5","price_per_passenger_3":"5","price_per_passenger_4":"5","price_per_passenger_5":"10","price_per_passenger_6":"10","price_per_passenger_7":"10","price_per_passenger_8":"10","price_per_passenger_9":"15","price_per_passenger_10":"15","price_per_passenger_11":"15","price_per_passenger_12":"15","waiting_duration":"10","traveling_duration":"15","availability_from":"","availability_until":"","availability_picture":false,"is_247":true,"plot_color":"taxi","pricing_table_header":"","pricing_table_":false},{"name":"Autob\u00fas","title_line":"C\u00f3mo ir del Aeropuerto de Colombo a Negombo en Autob\u00fas","top_description":"<p>Desafortunadamente, no hay un autob\u00fas que te lleve del Aeropuerto de Colombo a Negombo. Primero tendr\u00e1s que caminar alrededor de 1 km hasta la parada de autob\u00fas de Katunayake. Una vez est\u00e9s en la parada de autob\u00fas de Katunayake, debes tomar el autob\u00fas p\u00fablico en direcci\u00f3n a Negombo. La duraci\u00f3n total del trayecto del Aeropuerto de Colombo a Negombo en autob\u00fas es de 40 minutos y el costo es de \u20ac0,20 (LKR 70) por trayecto.<\/p>\n","fares":"\u20ac0,20 (LKR 70)","trip_duration":"40 Minutos.","line_below_price_and_time":"*El tiempo de espera para tomar el autob\u00fas es de 30 minutos.","perks":[{"perk":"Comodidad","rating":"2"},{"perk":"Seguridad","rating":"3"},{"perk":"Relaci\u00f3n calidad-precio","rating":"5"}],"availability":"El autob\u00fas funciona de 05:30 a 19:00.","middle_description_title":"\u00bfCu\u00e1nto cuesta un billete de autob\u00fas desde el Aeropuerto de Colombo a Negombo?","middle_description":"<p>El precio de un billete de ida en el autob\u00fas local de Negombo al Aeropuerto de Colombo y viceversa es de s\u00f3lo \u20ac0,20 (LKR 70). Puedes pagar el billete al conductor en tanto subas al autob\u00fas.<\/p>\n","middle_2_description_title":"\u00bfD\u00f3nde puedo encontrar el autob\u00fas en el Aeropuerto de Colombo?","middle_2_description":"<p>Desafortunadamente, el autob\u00fas del Aeropuerto de Colombo a Negombo no parte directamente del aeropuerto. Tendr\u00e1s que caminar alrededor de 1 km desde el aeropuerto hasta la parada de autob\u00fas de Katunayake para tomar el autob\u00fas a Negombo.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Comodidad","bottom_description":"<p>Aunque es una opci\u00f3n de traslado muy econ\u00f3mica desde el Aeropuerto de Colombo a Negombo, tomar el autob\u00fas es la forma menos c\u00f3moda de viajar. No s\u00f3lo tendr\u00e1s que caminar unos 10 minutos hasta la parada del autob\u00fas, sino que te dejar\u00e1n en el centro de Negombo, no en la zona tur\u00edstica. Esto significa que tendr\u00e1s que buscar un transporte alternativo hasta tu hotel, lo que a\u00f1ade tiempo, esfuerzo y costo a tu viaje en general.<\/p>\n","bottom_description_rating":"2","timetables":false,"editors_note":"Los autobuses locales se llenan r\u00e1pidamente y a menudo no tienen asientos muy c\u00f3modos. Si viajas con ni\u00f1os peque\u00f1os o con personas mayores, te recomendamos que tomes un taxi para mayor comodidad.","useful_tips":[{"tip":"El autob\u00fas local no siempre tiene aire acondicionado, prep\u00e1rate para un viaje caluroso."},{"tip":"No hay almacenamiento de equipaje en el autob\u00fas."},{"tip":"Lleva cambio en la moneda local para pagarle al conductor al subir al autob\u00fas."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"0,20","price_per_passenger_2":"0,40","price_per_passenger_3":"0,60","price_per_passenger_4":"0,80","price_per_passenger_5":"1","price_per_passenger_6":"1,20","price_per_passenger_7":"1,40","price_per_passenger_8":"1,60","price_per_passenger_9":"1,80","price_per_passenger_10":"2","price_per_passenger_11":"2,20","price_per_passenger_12":"2,40","waiting_duration":"30","traveling_duration":"40","availability_from":"05:30","availability_until":"19:00","availability_picture":false,"is_247":false,"plot_color":"bus","pricing_table_header":"","pricing_table_":false}],"faq":[{"question":"\u00bfC\u00f3mo puedo llegar del Aeropuerto de Colombo a Negombo?","answer":"<p>Hay dos formas de ir del Aeropuerto de Colombo a Negombo: en taxi o en autob\u00fas. Tomar un <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Taxi Del Aeropuerto De Colombo\">taxi del Aeropuerto de Colombo<\/a> es f\u00e1cil y r\u00e1pido, la duraci\u00f3n del trayecto es de tan s\u00f3lo 15 minutos y el costo de tu viaje estar\u00e1 cerca de los \u20ac5 (LKR 2.000). Con el autob\u00fas p\u00fablico tardar\u00e1s unos 40 minutos en llegar a Negombo, pero s\u00f3lo te costar\u00e1 \u20ac0,20 euros (LKR 70) por pasajero.<\/p>\n"},{"question":"\u00bfCu\u00e1l es la distancia entre el Aeropuerto de Colombo y Negombo?","answer":"<p>La distancia entre Negombo y el Aeropuerto de Colombo es de 7,6 km. Si tomas un <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Taxi Del Aeropuerto De Colombo\">taxi del Aeropuerto de Colombo<\/a> tardar\u00e1s 15 minutos, mientras que en el autob\u00fas p\u00fablico te tomar\u00e1 cerca de 40 minutos llegar a Negombo.<\/p>\n"},{"question":"\u00bfHay un servicio directo de autob\u00fas del Aeropuerto de Colombo a Negombo?","answer":"<p>No, no hay un trayecto de autob\u00fas directo desde el Aeropuerto de Colombo a Negombo. Lo primero que debes hacer es salir del recinto del aeropuerto y encontrar la parada de autob\u00fas de Katunayake, desde donde podr\u00e1s tomar el autob\u00fas a Negombo. Con esta caminata, la duraci\u00f3n total de tu trayecto ser\u00e1 de unos 40 minutos, sin incluir los tiempos de espera.<\/p>\n"}],"detailed_comparison_title":"","detailed_comparison_subtitle":"","breadcrumbs":[{"title":"Welcome Pickups","link":"https:\/\/www.welcomepickups.com\/es\/"},{"title":"Colombo","link":"https:\/\/www.welcomepickups.com\/es\/colombo\/"},{"title":"Del Aeropuerto a Negombo","link":""}],"welcome_image":false,"taxi_image":false,"welcome_title":"","welcome_content":"","render_new_widget":false,"safety_widget_title":"","safety_widget_subtitle":"","from_id":"","to_id":"","posts_category":false,"flat_price_1_value":"","flat_price_2_value":"","is_seo_2":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Opciones de traslado desde el Aeropuerto de Colombo a Negombo<\/title>\n<meta name=\"description\" content=\"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Negombo. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo llegar del Aeropuerto de Colombo a Negombo\" \/>\n<meta property=\"og:description\" content=\"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Negombo. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-25T17:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/aeropuerto-a-negombo\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/aeropuerto-a-negombo\\\/\",\"name\":\"Opciones de traslado desde el Aeropuerto de Colombo a Negombo | Welcome Pickups\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/aeropuerto-a-negombo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/aeropuerto-a-negombo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Negombo-Sri-Lanka.jpeg\",\"datePublished\":\"2023-05-25T08:04:54+00:00\",\"dateModified\":\"2023-05-25T17:36:30+00:00\",\"description\":\"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Negombo. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/aeropuerto-a-negombo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/aeropuerto-a-negombo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/aeropuerto-a-negombo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Negombo-Sri-Lanka.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Negombo-Sri-Lanka.jpeg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/aeropuerto-a-negombo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colombo &#8211; Punto Central\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo llegar del Aeropuerto de Colombo a Negombo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Opciones de traslado desde el Aeropuerto de Colombo a Negombo","description":"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Negombo. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo llegar del Aeropuerto de Colombo a Negombo","og_description":"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Negombo. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.","og_url":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2023-05-25T17:36:30+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/","url":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/","name":"Opciones de traslado desde el Aeropuerto de Colombo a Negombo | Welcome Pickups","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka.jpeg","datePublished":"2023-05-25T08:04:54+00:00","dateModified":"2023-05-25T17:36:30+00:00","description":"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Negombo. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka.jpeg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Negombo-Sri-Lanka.jpeg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/aeropuerto-a-negombo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/es\/"},{"@type":"ListItem","position":2,"name":"Colombo &#8211; Punto Central","item":"https:\/\/www.welcomepickups.com\/es\/colombo\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo llegar del Aeropuerto de Colombo a Negombo"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/es\/#website","url":"https:\/\/www.welcomepickups.com\/es\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/es\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/es\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.welcomepickups.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/352267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/comments?post=352267"}],"version-history":[{"count":4,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/352267\/revisions"}],"predecessor-version":[{"id":355507,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/352267\/revisions\/355507"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/351676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/media\/338203"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/media?parent=352267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}