{"id":352269,"date":"2023-05-17T13:00:05","date_gmt":"2023-05-17T11:00:05","guid":{"rendered":"https:\/\/www.welcomepickups.com\/colombo\/airport-to-unawatuna\/"},"modified":"2023-05-17T14:02:09","modified_gmt":"2023-05-17T12:02:09","slug":"traslado-aeropuerto-a-unawatuna","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/","title":{"rendered":"C\u00f3mo llegar del Aeropuerto de Colombo a Unawatuna"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":338229,"parent":351676,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-v61.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-352269","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"main_title":"C\u00f3mo llegar del Aeropuerto de Colombo a Unawatuna","from":"Aeropuerto Internacional Bandaranaike (CMB)","to":"","header_picture":{"ID":338229,"id":338229,"title":"Unawatuna, Sri Lanka","filename":"Unawatuna-Sri-Lanka-.jpeg","filesize":343778,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka-.jpeg","link":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/attachment\/unawatuna-sri-lanka-2\/","alt":"","author":"176","description":"","caption":"","name":"unawatuna-sri-lanka-2","status":"inherit","uploaded_to":352269,"date":"2022-12-28 16:35:08","modified":"2022-12-28 16:35:08","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--300x200.jpeg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--768x512.jpeg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--1024x683.jpeg","large-width":960,"large-height":640,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--1536x1024.jpeg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka-.jpeg","2048x2048-width":1920,"2048x2048-height":1280,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--672x372.jpeg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--450x225.jpeg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--290x117.jpeg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--290x170.jpeg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--112x117.jpeg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--64x64.jpeg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--88x66.jpeg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--197x151.jpeg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--667x416.jpeg","first_full-width":667,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--340x188.jpeg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--1920x660.jpeg","main_hero-width":1920,"main_hero-height":660,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka--200x125.jpeg","sidebar_cta-width":200,"sidebar_cta-height":125}},"line_above_title":"LAS MEJORES GU\u00cdAS DE TRASPORTE AL AEROPUERTO","title_line":"C\u00f3mo llegar del Aeropuerto de Colombo a Unawatuna","description":"<p>Si buscas las mejores vacaciones de playa tropical en Sri Lanka, Unawatuna es el destino perfecto. Puedes pasar las ma\u00f1anas descansando en playas rodeadas de palmeras, pasar las tardes explorando la Pagoda Japonesa de la Paz y la selva circundante, y pasar las noches paseando por el casco antiguo fortificado de Galle.<\/p>\n<p>Cuando se trata de viajar desde el Aeropuerto de Colombo a Unawatuna, tienes dos opciones: taxi o tren. Tomar un <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Taxi Del Aeropuerto De Colombo\">taxi del Aeropuerto de Colombo<\/a> es la forma m\u00e1s sencilla de viajar. La duraci\u00f3n total del trayecto del Aeropuerto de Colombo a Unawatuna en taxi es de s\u00f3lo 2 horas y 10 minutos, y el costo rondar\u00e1 los \u20ac40 (LKR 15.000). En cambio, tomar el tren te cuesta solo \u20ac2 (LKR 720), pero se tarda al menos 4 horas y 30 minutos en llegar a Unawatuna.<\/p>\n","transportation_means":[{"name":"Welcome Pickups","title_line":"","top_description":"","fares":"","trip_duration":"","line_below_price_and_time":"","perks":false,"availability":"","middle_description_title":"","middle_description":"","middle_2_description_title":"","middle_2_description":"","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"","bottom_description":"","bottom_description_rating":"5","timetables":false,"editors_note":"","useful_tips":false,"photos":false,"gallery_subline":"","infographics_only":true,"price_per_passenger_1":"75","price_per_passenger_2":"75","price_per_passenger_3":"75","price_per_passenger_4":"88","price_per_passenger_5":"88","price_per_passenger_6":"88","price_per_passenger_7":"180","price_per_passenger_8":"180","price_per_passenger_9":"180","price_per_passenger_10":"180","price_per_passenger_11":"180","price_per_passenger_12":"180","waiting_duration":"0","traveling_duration":"130","availability_from":"","availability_until":"","availability_picture":false,"is_247":true,"plot_color":"welcome","pricing_table_header":"","pricing_table_":false},{"name":"Taxi","title_line":"C\u00f3mo tomar un taxi del Aeropuerto de Colombo a Unawatuna","top_description":"<p>La forma m\u00e1s r\u00e1pida y c\u00f3moda de ir del Aeropuerto de Colombo a Unawatuna es tomando un taxi. La duraci\u00f3n del trayecto en <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Un Taxi Del Aeropuerto\">un taxi del aeropuerto<\/a> es de 2 horas y 10 minutos, y el precio ser\u00e1 de aproximadamente \u20ac40 (LKR 15,000) &#8211; precio que ser\u00e1 calculado con mayor precisi\u00f3n usando un tax\u00edmetro.<\/p>\n","fares":"\u20ac40 (LKR 15.000)","trip_duration":"2 h 10 min","line_below_price_and_time":"*Los precios pueden variar si no reservas con antelaci\u00f3n.","perks":[{"perk":"Comodidad","rating":"5"},{"perk":"Seguridad","rating":"5"},{"perk":"Relaci\u00f3n calidad-precio","rating":"5"}],"availability":"Hay taxis disponibles las 24 horas y 7 d\u00edas a la semana desde el Aeropuerto de Colombo.","middle_description_title":"Precio de un taxi del Aeropuerto de Colombo a Unawatuna","middle_description":"<p>Los conductores de taxi locales no ofrecen tarifas fijas por sus servicios. El costo promedio de un taxi del Aeropuerto de Colombo a Unawatuna ser\u00e1 de unos \u20ac40 (LKR 15.000), pero estar\u00e1 sujeto a cambios dependiendo del tr\u00e1fico y de tu destino exacto en Unawatuna.<\/p>\n<p>Para un traslado desde el aeropuerto que te garantice siempre una tarifa fija, puedes reservar con antelaci\u00f3n con <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a>.<\/p>\n","middle_2_description_title":"\u00bfD\u00f3nde encuentro un taxi en el Aeropuerto de Colombo?","middle_2_description":"<p>Encontrar un taxi en el Aeropuerto de Colombo no podr\u00eda ser m\u00e1s sencillo. Simplemente dir\u00edgete a las puertas de salida de la zona de llegadas y ver\u00e1s la parada de taxis justo delante de ti.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Comodidad","bottom_description":"<p>Ya que tomar un taxi del Aeropuerto de Colombo a Unawatuna es la \u00fanica opci\u00f3n de traslado directo disponible, es sin duda la elecci\u00f3n m\u00e1s recomendable. Tu conductor te llevar\u00e1 por la ruta m\u00e1s r\u00e1pida posible y te dejar\u00e1 directamente en la puerta de tu hotel. No tendr\u00e1s que preocuparte de traslados ni de cargar tu equipaje por diferentes estaciones de tren y autob\u00fas.<\/p>\n","bottom_description_rating":"5","timetables":false,"editors_note":"Para ahorrar dinero en tu traslado en taxi al Aeropuerto de Colombo, puedes dividir el costo entre un grupo de hasta 4 pasajeros.","useful_tips":[{"tip":"Aseg\u00farate de llevar dinero en efectivo en la moneda local para pagar el taxi."},{"tip":"Para viajes largos como \u00e9ste, es aconsejable que intentes acordar un precio fijo con el conductor si tomas un taxi en la parada de taxis del aeropuerto."},{"tip":"El trayecto del Aeropuerto de Colombo a Unawatuna es largo, as\u00ed que de ser posible lleva contigo unos refrescos."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"40","price_per_passenger_2":"40","price_per_passenger_3":"40","price_per_passenger_4":"40","price_per_passenger_5":"80","price_per_passenger_6":"80","price_per_passenger_7":"80","price_per_passenger_8":"80","price_per_passenger_9":"120","price_per_passenger_10":"120","price_per_passenger_11":"120","price_per_passenger_12":"120","waiting_duration":"10","traveling_duration":"130","availability_from":"","availability_until":"","availability_picture":false,"is_247":true,"plot_color":"taxi","pricing_table_header":"","pricing_table_":false},{"name":"Tren","title_line":"C\u00f3mo ir del Aeropuerto de Colombo a Unawatuna en Tren","top_description":"<p>Por desgracia, no hay ning\u00fan tren directo entre Unawatuna y el Aeropuerto de Colombo, ya que \u00e9ste no cuenta con estaci\u00f3n de ferrocarril. Primero deber\u00e1s tomar el autob\u00fas Colombo Express <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-ciudad\/\" title=\"Desde El Aeropuerto Hasta El Centro De La Ciudad\">desde el aeropuerto hasta el centro de la ciudad<\/a>, y luego caminar hasta la estaci\u00f3n de ferrocarril de Colombo Fort para tomar all\u00ed el tren a Unawatuna. La duraci\u00f3n total del trayecto es de unas 4 horas y 30 minutos y el costo es bastante econ\u00f3mico, \u20ac2 (LKR 720) por pasajero.<\/p>\n","fares":"\u20ac2 (LKR 720)","trip_duration":"4 h 30 min.","line_below_price_and_time":"*Hay un tiempo de espera estimado de hasta 8 horas para tomar el tren y de 30 minutos para tomar el autob\u00fas Colombo Express.","perks":[{"perk":"Comodidad","rating":"3"},{"perk":"Seguridad","rating":"3"},{"perk":"Relaci\u00f3n calidad-precio","rating":"5"}],"availability":"El tren circula de 06:50 a 18:17 y el autob\u00fas Colombo Express, de 05:30 a 20:30.","middle_description_title":"\u00bfCu\u00e1nto cuesta el billete de tren del Aeropuerto de Colombo a Unawatuna?","middle_description":"<p>El precio de un billete de ida en el autob\u00fas Colombo Express es\u00a0de \u20ac1,50 (LKR 500), mientras que el precio del billete de tren es de \u20ac0,50 (LKR 220). Eso significa que el costo total del trayecto desde el Aeropuerto de Colombo a Unawatuna es de \u20ac2 (LKR 720) por pasajero.<\/p>\n","middle_2_description_title":"\u00bfD\u00f3nde encuentro el tren en el aeropuerto de Colombo?","middle_2_description":"<p>Por desgracia, no hay estaci\u00f3n de tren en el aeropuerto de Colombo. Primero deber\u00e1s tomar el <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-ciudad\/\" title=\"Autob\u00fas Colombo Express Hacia El Centro De La Ciudad\">autob\u00fas Colombo Express hacia el centro de la ciudad<\/a> y luego caminar hasta la estaci\u00f3n de ferrocarril de Colombo Fort para tomar el tren.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Comodidad","bottom_description":"<p>Como no hay una l\u00ednea de tren directa del Aeropuerto de Colombo a Unawatuna, esta es una forma lenta y estresante de viajar. No s\u00f3lo tendr\u00e1s que hacer transbordo del autob\u00fas al tren, sino que tambi\u00e9n tendr\u00e1s que caminar con equipaje voluminoso por el centro de Colombo, lo que puede suponer todo un reto.<\/p>\n","bottom_description_rating":"3","timetables":false,"editors_note":"Si viajas en grupo o con mucho equipaje, te recomendamos encarecidamente que tomas un taxi en lugar del tren. Esta opci\u00f3n ser\u00e1 mucho menos estresante y m\u00e1s segura para tu grupo.","useful_tips":[{"tip":"El tren s\u00f3lo circula tres veces al d\u00eda, aseg\u00farate de consultar bien los horarios."},{"tip":"El tren deja de circular antes que el autob\u00fas, no hay servicio nocturno."},{"tip":"Lleva poco equipaje, ya que el tren no dispone de consigna."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"2","price_per_passenger_2":"4","price_per_passenger_3":"6","price_per_passenger_4":"8","price_per_passenger_5":"10","price_per_passenger_6":"12","price_per_passenger_7":"14","price_per_passenger_8":"16","price_per_passenger_9":"18","price_per_passenger_10":"20","price_per_passenger_11":"22","price_per_passenger_12":"24","waiting_duration":"480","traveling_duration":"270","availability_from":"06:50","availability_until":"18:17","availability_picture":false,"is_247":false,"plot_color":"train","pricing_table_header":"","pricing_table_":false}],"faq":[{"question":"\u00bfCu\u00e1nto cuesta un trayecto en taxi desde el Aeropuerto de Colombo hasta Unawatuna?","answer":"<p>El conductor de taxi local te cobrar\u00e1 unos \u20ac40 (LKR 15.000) por el trayecto hasta Unawatuna. Sin embargo, no se trata de una tarifa fija. Para una tarifa fija para su taxi del aeropuerto de Colombo a Unawatuna, puede <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Reservar Con Antelaci\u00f3n Con Welcome Pickups\">reservar con antelaci\u00f3n con Welcome Pickups<\/a>.<\/p>\n"},{"question":"\u00bfC\u00f3mo puedo llegar del Aeropuerto de Colombo a Unawatuna?","answer":"<p>Hay dos opciones para trasladarte desde el Aeropuerto de Colombo a Unawatuna: taxi o tren. Si tomas un <a href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/taxi-aeropuerto\/\" title=\"Taxi Del Aeropuerto De Colombo\">taxi del Aeropuerto de Colombo<\/a> tardar\u00e1s \u00fanicamente 2 horas y 10 minutos y el precio ser\u00e1 de \u20ac40 (LKR 15.000) en promedio. El tren tarda cerca de 4 horas y 30 minutos y cuesta tan s\u00f3lo \u20ac2 (LKR 720).<\/p>\n"},{"question":"\u00bfHay conexi\u00f3n ferroviaria entre Unawatuna y el Aeropuerto de Colombo?","answer":"<p>No hay un tren directo entre Unawatuna y el Aeropuerto de Colombo. Primero deber\u00e1s tomar el autob\u00fas Colombo Express desde el aeropuerto hasta el centro de Colombo, y despu\u00e9s tomar el tren desde la estaci\u00f3n de ferrocarril de Colombo Fort hasta Unawatuna. La duraci\u00f3n total del trayecto ser\u00e1 de 4 horas y 30 minutos y el costo ser\u00e1 de \u20ac2 (LKR 720) por pasajero.<\/p>\n"}],"detailed_comparison_title":"","detailed_comparison_subtitle":"","breadcrumbs":[{"title":"Welcome Pickups","link":"https:\/\/www.welcomepickups.com\/es\/"},{"title":"Colombo","link":"https:\/\/www.welcomepickups.com\/es\/colombo\/"},{"title":"Aeropuerto a Unawatuna","link":""}],"welcome_image":false,"taxi_image":false,"welcome_title":"","welcome_content":"","render_new_widget":false,"safety_widget_title":"","safety_widget_subtitle":"","from_id":"","to_id":"","posts_category":false,"flat_price_1_value":"","flat_price_2_value":"","is_seo_2":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Opciones de Traslado desde el Aeropuerto de Colombo a Unawatuna<\/title>\n<meta name=\"description\" content=\"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Unawatuna. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo llegar del Aeropuerto de Colombo a Unawatuna\" \/>\n<meta property=\"og:description\" content=\"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Unawatuna. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-17T12:02:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/traslado-aeropuerto-a-unawatuna\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/traslado-aeropuerto-a-unawatuna\\\/\",\"name\":\"Opciones de Traslado desde el Aeropuerto de Colombo a Unawatuna | Welcome Pickups\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/traslado-aeropuerto-a-unawatuna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/traslado-aeropuerto-a-unawatuna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Unawatuna-Sri-Lanka-.jpeg\",\"datePublished\":\"2023-05-17T11:00:05+00:00\",\"dateModified\":\"2023-05-17T12:02:09+00:00\",\"description\":\"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Unawatuna. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/traslado-aeropuerto-a-unawatuna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/traslado-aeropuerto-a-unawatuna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/traslado-aeropuerto-a-unawatuna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Unawatuna-Sri-Lanka-.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Unawatuna-Sri-Lanka-.jpeg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/traslado-aeropuerto-a-unawatuna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colombo &#8211; Punto Central\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/colombo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo llegar del Aeropuerto de Colombo a Unawatuna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Opciones de Traslado desde el Aeropuerto de Colombo a Unawatuna","description":"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Unawatuna. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo llegar del Aeropuerto de Colombo a Unawatuna","og_description":"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Unawatuna. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.","og_url":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2023-05-17T12:02:09+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka-.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/","url":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/","name":"Opciones de Traslado desde el Aeropuerto de Colombo a Unawatuna | Welcome Pickups","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka-.jpeg","datePublished":"2023-05-17T11:00:05+00:00","dateModified":"2023-05-17T12:02:09+00:00","description":"Todo lo que necesitas saber sobre tu traslado del Aeropuerto de Colombo a Unawatuna. Obt\u00e9n consejos \u00fatiles y compara tus opciones de transporte con Welcome Pickups.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka-.jpeg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/12\/Unawatuna-Sri-Lanka-.jpeg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/es\/colombo\/traslado-aeropuerto-a-unawatuna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/es\/"},{"@type":"ListItem","position":2,"name":"Colombo &#8211; Punto Central","item":"https:\/\/www.welcomepickups.com\/es\/colombo\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo llegar del Aeropuerto de Colombo a Unawatuna"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/es\/#website","url":"https:\/\/www.welcomepickups.com\/es\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/es\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/es\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.welcomepickups.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/352269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/comments?post=352269"}],"version-history":[{"count":5,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/352269\/revisions"}],"predecessor-version":[{"id":354086,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/352269\/revisions\/354086"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/pages\/351676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/media\/338229"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/es\/wp-json\/wp\/v2\/media?parent=352269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}