{"id":284738,"date":"2016-11-21T13:24:46","date_gmt":"2016-11-21T11:24:46","guid":{"rendered":"https:\/\/www.welcomepickups.com\/?page_id=284738"},"modified":"2023-08-30T18:03:04","modified_gmt":"2023-08-30T16:03:04","slug":"port-jusqua-fira","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/","title":{"rendered":"Options de Transfert du Vieux Port de Santorin jusqu&rsquo;\u00e0 Fira"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":141,"featured_media":135081,"parent":6484,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-v4.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-284738","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"posts_category":17,"from_id":"91402","to_id":"","flat_price_1_value":"","flat_price_2_value":"","to":"","welcome_image":false,"taxi_image":false,"welcome_title":"","welcome_content":"","safety_widget_title":"","safety_widget_subtitle":"","render_new_widget":false,"breadcrumbs":[{"title":"Welcome","link":"https:\/\/www.welcomepickups.com\/fr\/"},{"title":"Santorin","link":"https:\/\/www.welcomepickups.com\/santorini\/"},{"title":"Vieux port de Santorin \u00e0 Fira","link":""}],"detailed_comparison_subtitle":"Vieux port de Santorin \u00e0 Fira (t\u00e9l\u00e9ph\u00e9rique ou \u00e0 dos d'\u00e2ne)","detailed_comparison_title":"Voici votre comparatif","faq":[{"question":"Combien co\u00fbte le t\u00e9l\u00e9ph\u00e9rique du Vieux Port de Santorin \u00e0 Fira ? ","answer":"<p>Le t\u00e9l\u00e9ph\u00e9rique du Vieux Port de Santorin co\u00fbte seulement 6 \u20ac pour un billet adulte et prend 13 minutes pour atteindre le sommet (Fira).<\/p>\n"},{"question":"Comment passer du Vieux Port de Santorin \u00e0 Fira ? ","answer":"<p>Il n&rsquo;y a qu&rsquo;une seule option de transfert principale depuis le port ferry vers Fira et c&rsquo;est le t\u00e9l\u00e9ph\u00e9rique. Il ne faut que 13 minutes pour atteindre Fira et vous paierez 6 \u20ac pour un aller simple. Alternativement, des promenades \u00e0 dos d&rsquo;\u00e2ne \u00e0 Santorin sont possibles, cependant, monter un \u00e2ne \u00e0 Santorin suscite sa part de controverse. La balade est \u00e9galement dangereuse, inconfortable et lente. Nous recommandons de profiter de la vue et de monter \u00e0 pied \u00e0 la place.<\/p>\n"}],"from":"Vieux Port de Santorin","header_picture":{"ID":123741,"id":123741,"title":"Santorini Old Port (Cruises)","filename":"776868-min.jpg","filesize":97494,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","link":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/attachment\/776868-min\/","alt":"","author":"141","description":"Santorini Old Port (Cruises)","caption":"Santorini Old Port (Cruises)","name":"776868-min","status":"inherit","uploaded_to":284738,"date":"2017-02-09 11:42:17","modified":"2021-01-25 10:42:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1012,"height":383,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min-300x114.jpg","medium-width":300,"medium-height":114,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min-768x291.jpg","medium_large-width":768,"medium_large-height":291,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","large-width":960,"large-height":363,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","1536x1536-width":1012,"1536x1536-height":383,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","2048x2048-width":1012,"2048x2048-height":383,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min-672x372.jpg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min-450x225.jpg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min-290x117.jpg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","v3_gallery_3-width":290,"v3_gallery_3-height":110,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min-112x117.jpg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","sidebar_1-width":64,"sidebar_1-height":24,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","sidebar_2-width":88,"sidebar_2-height":33,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","sidebar_3-width":197,"sidebar_3-height":75,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","first_full-width":667,"first_full-height":252,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","main_thumbnail-width":340,"main_thumbnail-height":129,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","main_hero-width":1012,"main_hero-height":383,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/776868-min.jpg","sidebar_cta-width":200,"sidebar_cta-height":76}},"line_above_title":"LES MEILLEURS GUIDES DE TRANSPORT AU D\u00c9PART DES A\u00c9ROPORTS","title_line":"Se rendre du Vieux Port de Santorin \u00e0 Fira ","transportation_means":[{"name":"Le t\u00e9l\u00e9ph\u00e9rique","title_line":"Comment se rendre du Vieux-Port de Santorin \u00e0 Fira en t\u00e9l\u00e9ph\u00e9rique ?","top_description":"<p>Le <strong>mode de transport le plus s\u00fbr et le plus confortable pour rejoindre la ville de Fira depuis le Vieux Port de Santorin est le t\u00e9l\u00e9ph\u00e9rique<\/strong>. Les billets co\u00fbtent 6 \u20ac par personne et les t\u00e9l\u00e9ph\u00e9riques partent toutes les 20 minutes. Il fonctionne toute la journ\u00e9e de 06h00 \u00e0 23h00 pendant la haute saison (1er juin &#8211; 31 ao\u00fbt).<\/p>\n<p>Prendre le t\u00e9l\u00e9ph\u00e9rique jusqu&rsquo;\u00e0 Fira est un excellent moyen d&rsquo;admirer la vue incroyable des falaises de la Caldera, de la mer turquoise de l&rsquo;\u00eele et du volcan depuis une altitude de 220 m\u00e8tres. De plus, arriver en seulement 13 minutes vous donne plus de temps pour explorer la belle ville et profiter des petites boutiques qu&rsquo;elle a \u00e0 offrir.<\/p>\n<p>*Il est important de savoir que par temps tr\u00e8s venteux, les t\u00e9l\u00e9ph\u00e9riques ferment pour des raisons de s\u00e9curit\u00e9.<\/p>\n","fares":"6\u20ac","trip_duration":"13 min","line_below_price_and_time":"Le temps d'attente est d'environ 20 minutes.","perks":[{"perk":"Facilit\u00e9 d'usage","rating":"4"},{"perk":"Rapport qualit\u00e9-prix","rating":"5"},{"perk":"S\u00e9curit\u00e9","rating":"4"}],"availability":"Les t\u00e9l\u00e9ph\u00e9riques fonctionnent de 06h30 \u00e0 23h00 depuis le Vieux Port de Santorin. ","middle_description_title":"Combien co\u00fbte un aller en t\u00e9l\u00e9ph\u00e9rique du Vieux-Port de Santorin jusqu'\u00e0 Fira ?","middle_description":"<p>Un <strong>billet adulte aller simple pour le t\u00e9l\u00e9ph\u00e9rique du Vieux Port de Santorin \u00e0 Fira co\u00fbte 6 \u20ac<\/strong> et 3 \u20ac pour les enfants de moins de 5 ans. *Si vous transportez de gros bagages, vous devrez payer des frais de 3 \u20ac.<\/p>\n","middle_2_description_title":"O\u00f9 puis-je les trouver ?","middle_2_description":"<p>Lorsque vous quittez le ferry au quai du bateau de croisi\u00e8re au Vieux Port, vous devrez suivre la route et tourner \u00e0 gauche vers le Santozeum. Apr\u00e8s quelques m\u00e8tres, vous verrez la station de t\u00e9l\u00e9ph\u00e9rique en face de vous.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Facilit\u00e9 d'usage","bottom_description":"<p><strong>Prendre le t\u00e9l\u00e9ph\u00e9rique du Vieux Port de Santorin \u00e0 Fira est certainement l&rsquo;option la plus pratique<\/strong>. Le trajet est rapide et les t\u00e9l\u00e9ph\u00e9riques circulent assez fr\u00e9quemment. Cependant, pendant la haute saison en \u00e9t\u00e9, le temps d&rsquo;attente peut \u00eatre tr\u00e8s long.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Options alternatives:<\/strong><\/span><\/p>\n<p>Les seules autres options disponibles sont de monter les marches vous-m\u00eame ou de monter un \u00e2ne. Prendre <strong>un \u00e2ne du Vieux Port de Santorin \u00e0 la ville de Fira est dangereux, lent et inconfortable<\/strong> et de loin le choix de transfert le plus controvers\u00e9. Cette option n&rsquo;est \u00e9galement pas adapt\u00e9e aux enfants car la balade est raide et peut \u00eatre assez effrayante.<\/p>\n<p><strong>Plus important encore, les balades \u00e0 dos d&rsquo;\u00e2ne soul\u00e8vent certainement des probl\u00e8mes de droits des animaux<\/strong>. Cependant, c&rsquo;est une m\u00e9thode qui est utilis\u00e9e par les habitants depuis plus de 50 ans. Au lieu de cela, nous vous recommandons de monter les marches en profitant de la vue.<\/p>\n","bottom_description_rating":"4","timetables":[{"title":"Horaires du t\u00e9l\u00e9ph\u00e9rique de Santorin","description":"","view_more_url":"https:\/\/www.scc.gr\/timetable.htm "}],"editors_note":"Les vues depuis les t\u00e9l\u00e9ph\u00e9riques sont spectaculaires. C'est un excellent moyen de commencer vos vacances \u00e0 Santorin.","useful_tips":[{"tip":"Le dernier trajet en t\u00e9l\u00e9ph\u00e9rique est \u00e0 22h40 pendant les mois d'\u00e9t\u00e9."},{"tip":"Tous les revenus du t\u00e9l\u00e9ph\u00e9rique vont \u00e0 la municipalit\u00e9 de Santorin."},{"tip":"En haute saison, il peut y avoir une tr\u00e8s longue file d'attente pour les t\u00e9l\u00e9ph\u00e9riques de Fira, en raison des nombreux passagers venant des navires de croisi\u00e8re."},{"tip":"Les t\u00e9l\u00e9ph\u00e9riques circulent moins fr\u00e9quemment pendant les mois d'hiver."},{"tip":"Si vous ne pouvez pas prendre le t\u00e9l\u00e9ph\u00e9rique pour quelque raison que ce soit, votre seule autre option est de monter les marches, que ce soit \u00e0 pied ou \u00e0 dos d'\u00e2ne. "}],"photos":[{"photo":{"ID":124065,"id":124065,"title":"Cable Car from Old port of Santorini to Fira","filename":"Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","filesize":96164,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","link":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/attachment\/cable-car-from-old-port-of-santroini-to-fira-2\/","alt":"","author":"141","description":"Cable Car from Old port of Santorini to Fira","caption":"Cable Car from Old port of Santorini to Fira","name":"cable-car-from-old-port-of-santroini-to-fira-2","status":"inherit","uploaded_to":284738,"date":"2017-02-10 14:50:17","modified":"2021-01-25 10:42:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":700,"height":525,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","medium_large-width":700,"medium_large-height":525,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","large-width":700,"large-height":525,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","1536x1536-width":700,"1536x1536-height":525,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","2048x2048-width":700,"2048x2048-height":525,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1-672x372.jpg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1-450x225.jpg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1-290x117.jpg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","v3_gallery_3-width":227,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1-112x117.jpg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","sidebar_1-width":64,"sidebar_1-height":48,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","sidebar_3-width":197,"sidebar_3-height":148,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","first_full-width":555,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","main_thumbnail-width":251,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","main_hero-width":700,"main_hero-height":525,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/02\/Cable-Car-from-Old-port-of-Santroini-to-Fira-1.jpg","sidebar_cta-width":167,"sidebar_cta-height":125}},"external_video":""},{"photo":{"ID":124173,"id":124173,"title":"View from Cable Car in Santorini","filename":"IMG_0392-min.jpg","filesize":95702,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","link":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/attachment\/img_0392-min\/","alt":"","author":"141","description":"View from Cable Car in Santorini","caption":"","name":"img_0392-min","status":"inherit","uploaded_to":284738,"date":"2017-02-13 10:50:06","modified":"2021-01-25 10:42:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":700,"height":467,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","medium_large-width":700,"medium_large-height":467,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","large-width":700,"large-height":467,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","1536x1536-width":700,"1536x1536-height":467,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","2048x2048-width":700,"2048x2048-height":467,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min-672x372.jpg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min-450x225.jpg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min-290x117.jpg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","v3_gallery_3-width":255,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min-112x117.jpg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","sidebar_1-width":64,"sidebar_1-height":43,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","sidebar_2-width":88,"sidebar_2-height":59,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","sidebar_3-width":197,"sidebar_3-height":131,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","first_full-width":624,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","main_thumbnail-width":282,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","main_hero-width":700,"main_hero-height":467,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/IMG_0392-min.jpg","sidebar_cta-width":187,"sidebar_cta-height":125}},"external_video":""}],"gallery_subline":"T\u00e9l\u00e9ph\u00e9riques au Vieux Port de Santorin","infographics_only":false,"price_per_passenger_1":"6","price_per_passenger_2":"12","price_per_passenger_3":"18","price_per_passenger_4":"24","price_per_passenger_5":"30","price_per_passenger_6":"36","price_per_passenger_7":"42","price_per_passenger_8":"48","price_per_passenger_9":"54","price_per_passenger_10":"60","price_per_passenger_11":"66","price_per_passenger_12":"72","waiting_duration":"20","traveling_duration":"13","availability_from":"06:30","availability_until":"23:00","availability_picture":false,"is_247":false,"plot_color":"welcome","pricing_table_header":"","pricing_table_":false}],"description":"<p>Santorin est connue pour ses couchers de soleil et ses paysages magnifiques, ses plages de sable blanc, rouge et noir, ses maisons traditionnelles impressionnantes, ses balcons avec vue sur le volcan et sa vie nocturne anim\u00e9e. La ville de Fira est la capitale de Santorin et le plus grand et le plus cosmopolite des \u00e9tablissements de l&rsquo;\u00eele.<\/p>\n<p>Arriver sur l&rsquo;une des \u00eeles les plus populaires de Gr\u00e8ce peut \u00eatre assez accablant, surtout en haute saison. C&rsquo;est pourquoi il est important de conna\u00eetre vos options \u00e0 votre arriv\u00e9e sur l&rsquo;\u00eele afin de profiter au maximum de votre voyage. Lorsque vous voyagez <strong>du Vieux Port \u00e0 Fira, vous avez une option de transfert principale ; le t\u00e9l\u00e9ph\u00e9rique<\/strong>. Il ne faut que 13 minutes pour atteindre le sommet et cela co\u00fbte 6 \u20ac.<\/p>\n<p>Alternativement, vous pourriez monter \u00e0 dos d&rsquo;\u00e2ne jusqu&rsquo;au sommet de la montagne. Cependant, cette option plus traditionnelle est dangereuse, inconfortable et assez controvers\u00e9e. Cela \u00e9tant dit, c&rsquo;est une m\u00e9thode utilis\u00e9e par les habitants depuis plus de 50 ans. Quoi qu&rsquo;il en soit, il est g\u00e9n\u00e9ralement recommand\u00e9 de monter les marches \u00e0 la place.<\/p>\n","main_title":"Se rendre du Vieux Port de Santorin \u00e0 Fira ","brushed_up_on":"08-30-23","is_seo_2":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Options de transfert du Vieux Port de Santorin \u00e0 Fira<\/title>\n<meta name=\"description\" content=\"Tout ce que vous devez savoir sur votre transfert depuis le Vieux Port de Santorin - Comparez toutes les options de transfert disponibles depuis le Vieux Port de Santorin jusqu&#039;\u00e0 Fira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informations sur votre Transfert \u00e0 l&#039;A\u00e9roport de Santorin - Welcome\" \/>\n<meta property=\"og:description\" content=\"Trouvez toutes les Informations dont vous pourriez avoir besoin pour votre Transfert depuis le Vieux-Port (Croisi\u00e8res) jusqu&#039;\u00e0 Fira. Comparez toutes vos Options - Transfert par T\u00e9l\u00e9ph\u00e9rique, Dos d&#039;\u00c2ne, Liste de Comparaison.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T16:03:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/01\/Santorini-Og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Informations sur votre Transfert \u00e0 l&#039;A\u00e9roport de Santorin - Welcome\" \/>\n<meta name=\"twitter:description\" content=\"Trouvez toutes les Informations dont vous pourriez avoir besoin pour votre Transfert depuis le Vieux-Port (Croisi\u00e8res) jusqu&#039;\u00e0 Fira. Comparez toutes vos Options - Transfert par T\u00e9l\u00e9ph\u00e9rique, Dos d&#039;\u00c2ne, Liste de Comparaison.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/05\/Rome-Og.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/port-jusqua-fira\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/port-jusqua-fira\\\/\",\"name\":\"Options de transfert du Vieux Port de Santorin \u00e0 Fira | Welcome Pickups\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/port-jusqua-fira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/port-jusqua-fira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Santorini-old-port-view.jpg\",\"datePublished\":\"2016-11-21T11:24:46+00:00\",\"dateModified\":\"2023-08-30T16:03:04+00:00\",\"description\":\"Tout ce que vous devez savoir sur votre transfert depuis le Vieux Port de Santorin - Comparez toutes les options de transfert disponibles depuis le Vieux Port de Santorin jusqu'\u00e0 Fira.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/port-jusqua-fira\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/port-jusqua-fira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/port-jusqua-fira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Santorini-old-port-view.jpg\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Santorini-old-port-view.jpg\",\"width\":316,\"height\":200,\"caption\":\"View of Santorini Old Port with the cliffs behind.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/port-jusqua-fira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santorini &#8211; Hub\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/santorini\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Options de Transfert du Vieux Port de Santorin jusqu&rsquo;\u00e0 Fira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Options de transfert du Vieux Port de Santorin \u00e0 Fira","description":"Tout ce que vous devez savoir sur votre transfert depuis le Vieux Port de Santorin - Comparez toutes les options de transfert disponibles depuis le Vieux Port de Santorin jusqu'\u00e0 Fira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/","og_locale":"fr_FR","og_type":"article","og_title":"Informations sur votre Transfert \u00e0 l'A\u00e9roport de Santorin - Welcome","og_description":"Trouvez toutes les Informations dont vous pourriez avoir besoin pour votre Transfert depuis le Vieux-Port (Croisi\u00e8res) jusqu'\u00e0 Fira. Comparez toutes vos Options - Transfert par T\u00e9l\u00e9ph\u00e9rique, Dos d'\u00c2ne, Liste de Comparaison.","og_url":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2023-08-30T16:03:04+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/01\/Santorini-Og.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Informations sur votre Transfert \u00e0 l'A\u00e9roport de Santorin - Welcome","twitter_description":"Trouvez toutes les Informations dont vous pourriez avoir besoin pour votre Transfert depuis le Vieux-Port (Croisi\u00e8res) jusqu'\u00e0 Fira. Comparez toutes vos Options - Transfert par T\u00e9l\u00e9ph\u00e9rique, Dos d'\u00c2ne, Liste de Comparaison.","twitter_image":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/05\/Rome-Og.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/","url":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/","name":"Options de transfert du Vieux Port de Santorin \u00e0 Fira | Welcome Pickups","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/Santorini-old-port-view.jpg","datePublished":"2016-11-21T11:24:46+00:00","dateModified":"2023-08-30T16:03:04+00:00","description":"Tout ce que vous devez savoir sur votre transfert depuis le Vieux Port de Santorin - Comparez toutes les options de transfert disponibles depuis le Vieux Port de Santorin jusqu'\u00e0 Fira.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/Santorini-old-port-view.jpg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/11\/Santorini-old-port-view.jpg","width":316,"height":200,"caption":"View of Santorini Old Port with the cliffs behind."},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/fr\/santorini\/port-jusqua-fira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Santorini &#8211; Hub","item":"https:\/\/www.welcomepickups.com\/fr\/santorini\/"},{"@type":"ListItem","position":3,"name":"Options de Transfert du Vieux Port de Santorin jusqu&rsquo;\u00e0 Fira"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/fr\/#website","url":"https:\/\/www.welcomepickups.com\/fr\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/fr\/#organization"},"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/fr\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.welcomepickups.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages\/284738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/comments?post=284738"}],"version-history":[{"count":3,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages\/284738\/revisions"}],"predecessor-version":[{"id":367843,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages\/284738\/revisions\/367843"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages\/6484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/media\/135081"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/media?parent=284738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}