{"id":60255,"date":"2018-03-10T03:05:20","date_gmt":"2018-03-10T01:05:20","guid":{"rendered":"https:\/\/www.welcomepickups.com\/corfu\/airport-transfer-to-city\/"},"modified":"2018-11-08T16:04:31","modified_gmt":"2018-11-08T14:04:31","slug":"transfert-aeroport-vers-la-ville","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/","title":{"rendered":"Moyens de transfert de l&rsquo;a\u00e9roport de Corfou \u00e0 la ville de Corfou"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":68,"featured_media":22601,"parent":37331,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-v4.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-60255","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"from":"A\u00e9roport international de Corfou","to":"port de Corfou","header_picture":{"ID":166041,"id":166041,"title":"corfu welcome pickups","filename":"amphora-1690_640.jpg","filesize":35343,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","link":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/attachment\/amphora-1690_640\/","alt":"corfu welcome pickups","author":"68","description":"","caption":"Corfu Airport to Corfu Town","name":"amphora-1690_640","status":"inherit","uploaded_to":60255,"date":"2018-03-10 09:56:59","modified":"2024-12-31 12:36:37","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":640,"height":426,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","medium_large-width":640,"medium_large-height":426,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","large-width":640,"large-height":426,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","1536x1536-width":640,"1536x1536-height":426,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","2048x2048-width":640,"2048x2048-height":426,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-640x372.jpg","post-thumbnail-width":640,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-450x225.jpg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-290x117.jpg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-290x170.jpg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-112x117.jpg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-64x64.jpg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-88x66.jpg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-197x151.jpg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-640x416.jpg","first_full-width":640,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-340x188.jpg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","main_hero-width":640,"main_hero-height":426,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640-200x125.jpg","sidebar_cta-width":200,"sidebar_cta-height":125}},"line_above_title":"LES MEILLEURS GUIDES DE TRANSPORT D'A\u00c9ROPORT","title_line":"Comment se rendre de l'a\u00e9roport de Corfou \u00e0 la ville de Corfou","description":"<p>L&rsquo;a\u00e9roport international de Corfou propose deux moyens de transport vers le centre-ville de Corfou. En raison de la pl\u00e9thore de <a href=\"https:\/\/www.welcomepickups.com\/fr\/corfu\/airport-taxi\/\" title=\"Taxis \u00e0 L&#039;a\u00e9roport De Corfou\"> taxis \u00e0 l&rsquo;a\u00e9roport de Corfou<\/a>.Les taxis sont le choix le plus courant de transport de l&rsquo;a\u00e9roport. D&rsquo;autre part, un r\u00e9seau de transports en commun efficace (ligne bleue n \u00b0 15) est \u00e9galement disponible, reliant l&rsquo;a\u00e9roport \u00e0 la ville de Corfou. Les trajets en taxi de l&rsquo;a\u00e9roport \u00e0 la ville de Corfou prennent un peu moins de 10 minutes et co\u00fbtent environ 15 \u00e0 20 \u20ac. Enfin, le trajet en bus jusqu&rsquo;\u00e0 la gare de San Rocco, dans le centre-ville, dure environ 15 minutes et l&rsquo;aller simple co\u00fbte 1,2 \u20ac.<\/p>\n","transportation_means":[{"name":"Welcome","title_line":"","top_description":"","fares":"","trip_duration":"","line_below_price_and_time":"","perks":false,"availability":"","middle_description_title":"","middle_description":"","middle_2_description_title":"","middle_2_description":"","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"","bottom_description":"","bottom_description_rating":"5","timetables":false,"editors_note":"","useful_tips":false,"photos":false,"gallery_subline":"","infographics_only":true,"price_per_passenger_1":"20","price_per_passenger_2":"20","price_per_passenger_3":"20","price_per_passenger_4":"20","price_per_passenger_5":"40","price_per_passenger_6":"40","price_per_passenger_7":"40","price_per_passenger_8":"40","price_per_passenger_9":"60","price_per_passenger_10":"60","price_per_passenger_11":"60","price_per_passenger_12":"60","waiting_duration":"0","traveling_duration":"10","availability_from":"","availability_until":"","availability_picture":{"ID":162873,"id":162873,"title":"icn-rankings-welcome","filename":"icn-rankings-welcome.svg","filesize":2870,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","link":"https:\/\/www.welcomepickups.com\/fr\/athens\/aeroport-au-centre-ville\/attachment\/icn-rankings-welcome\/","alt":"icn-rankings-welcome","author":"141","description":"","caption":"","name":"icn-rankings-welcome","status":"inherit","uploaded_to":8590,"date":"2018-02-12 11:55:53","modified":"2018-02-12 11:55:53","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","2048x2048-width":1,"2048x2048-height":1,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","post-thumbnail-width":1,"post-thumbnail-height":1,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","slider-thumb-width":1,"slider-thumb-height":1,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","v3_gallery_1-width":1,"v3_gallery_1-height":1,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","v3_gallery_3-width":1,"v3_gallery_3-height":1,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","v3_gallery_2-width":1,"v3_gallery_2-height":1,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","sidebar_1-width":1,"sidebar_1-height":1,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","sidebar_2-width":1,"sidebar_2-height":1,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","sidebar_3-width":1,"sidebar_3-height":1,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","first_full-width":1,"first_full-height":1,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","main_thumbnail-width":1,"main_thumbnail-height":1,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","main_hero-width":1,"main_hero-height":1,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/icn-rankings-welcome.svg","sidebar_cta-width":1,"sidebar_cta-height":1}},"is_247":true,"plot_color":"welcome","pricing_table_header":"","pricing_table_":false},{"name":"Taxi","title_line":"Comment se rendre de l'a\u00e9roport de Corfou au centre-ville en taxi","top_description":"<p>Les taxis \u00e0 l&rsquo;a\u00e9roport et sur l&rsquo;\u00eele de Corfou en g\u00e9n\u00e9ral sont bleu fonc\u00e9. En outre, ils portent tous le signe distinctif sur le toit du taxi, qui peut \u00eatre vu en noir et jaune ou en noir et blanc. Dans des conditions de circulation normales, une course en taxi pour se rendre \u00e0 la ville de Corfou prend g\u00e9n\u00e9ralement un peu moins de 10 minutes, tandis que le tarif normal du trajet est d&rsquo;environ 15 \u20ac. En raison de la nature touristique de l&rsquo;\u00eele, il existe g\u00e9n\u00e9ralement une vari\u00e9t\u00e9 de soci\u00e9t\u00e9s de service de taxi dans l&rsquo;a\u00e9roport offrant des trajets vers la ville de Corfou et d&rsquo;autres destinations populaires \u00e0 des prix comp\u00e9titifs.<\/p>\n","fares":"15\u20ac","trip_duration":"10 Min.","line_below_price_and_time":"*Les tarifs peuvent varier sauf si vous r\u00e9servez votre taxi \u00e0 l'avance.","perks":[{"perk":"Confort","rating":"5"},{"perk":"S\u00e9curit\u00e9","rating":"5"},{"perk":"Rapport qualit\u00e9 prix","rating":"4"}],"availability":"Des taxis \u00e0 l'a\u00e9roport sont disponibles toute la journ\u00e9e","middle_description_title":"Tarif du taxi de l'a\u00e9roport de Corfou au centre-ville","middle_description":"<p>En fonction du <a href=\"https:\/\/www.welcomepickups.com\/fr\/corfu\/airport-taxi\/\" title=\"Service De Taxi De L&#039;a\u00e9roport De Corfou\"> service de taxi de l&rsquo;a\u00e9roport de Corfou <\/a>, mais surtout de la p\u00e9riode de l&rsquo;ann\u00e9e, le tarif le plus courant \u00e0 l&rsquo;a\u00e9roport de Corfou \u00e0 la ville co\u00fbte environ 15 \u20ac. Avec les taxis de ville classiques, le tarif varie en fonction de la distance et de la dur\u00e9e du trajet. Par ailleurs, les compagnies de taxi priv\u00e9es proposent g\u00e9n\u00e9ralement des tarifs fixes afin d&rsquo;attirer les touristes.<\/p>\n","middle_2_description_title":"O\u00f9 puis-je le prendre ?","middle_2_description":"<p>En raison de la petite taille de l&rsquo;a\u00e9roport de Corfou, il est facile de trouver des taxis avec licence juste devant le terminal des arriv\u00e9es.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Confort","bottom_description":"<p>Les taxis de l&rsquo;a\u00e9roport de Corfou sont g\u00e9n\u00e9ralement consid\u00e9r\u00e9s comme le moyen le plus rapide et le plus confortable, quelle que soit leur destination. Bien que les tarifs de taxi puissent \u00eatre assez co\u00fbteux, louer un taxi avec un groupe peut s&rsquo;av\u00e9rer \u00eatre tr\u00e8s efficace car le prix sera divis\u00e9 par deux.<\/p>\n","bottom_description_rating":"5","timetables":false,"editors_note":"Il est g\u00e9n\u00e9ralement recommand\u00e9 d'\u00e9viter les personnes au hasard qui pourraient vous proposer des services de taxi, car elles cherchent g\u00e9n\u00e9ralement \u00e0 surcharger les voyageurs qui ne connaissent pas bien l'\u00eele.","useful_tips":[{"tip":"Un suppl\u00e9ment de 25% \u00e0 50% devrait toujours \u00eatre pr\u00e9vu si vous prenez un taxi apr\u00e8s minuit."},{"tip":"Il est important d'\u00e9valuer les chauffeurs de taxi pour maintenir et mettre \u00e0 jour la cr\u00e9dibilit\u00e9 les entreprises de taxi priv\u00e9s de l'\u00eele de Corfou."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"15","price_per_passenger_2":"15","price_per_passenger_3":"15","price_per_passenger_4":"15","price_per_passenger_5":"30","price_per_passenger_6":"30","price_per_passenger_7":"30","price_per_passenger_8":"30","price_per_passenger_9":"45","price_per_passenger_10":"45","price_per_passenger_11":"45","price_per_passenger_12":"45","waiting_duration":"10","traveling_duration":"10","availability_from":"","availability_until":"","availability_picture":{"ID":129105,"id":129105,"title":"icn-rankings-taxi","filename":"icn-rankings-taxi.svg","filesize":3270,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","link":"https:\/\/www.welcomepickups.com\/fr\/paris\/aeroport-orly-au-centre-ville\/attachment\/icn-rankings-taxi\/","alt":"icn-rankings-taxi","author":"1","description":"","caption":"","name":"icn-rankings-taxi","status":"inherit","uploaded_to":534667,"date":"2017-06-14 15:41:30","modified":"2020-10-09 13:03:44","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","2048x2048-width":1,"2048x2048-height":1,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","post-thumbnail-width":1,"post-thumbnail-height":1,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","slider-thumb-width":1,"slider-thumb-height":1,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","v3_gallery_1-width":1,"v3_gallery_1-height":1,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","v3_gallery_3-width":1,"v3_gallery_3-height":1,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","v3_gallery_2-width":1,"v3_gallery_2-height":1,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","sidebar_1-width":1,"sidebar_1-height":1,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","sidebar_2-width":1,"sidebar_2-height":1,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","sidebar_3-width":1,"sidebar_3-height":1,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","first_full-width":1,"first_full-height":1,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","main_thumbnail-width":1,"main_thumbnail-height":1,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","main_hero-width":1,"main_hero-height":1,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-taxi.svg","sidebar_cta-width":1,"sidebar_cta-height":1}},"is_247":true,"plot_color":"taxi","pricing_table_header":"COMBIEN CO\u00dbTE UN TAXI \u00c0 L\u2019A\u00c9ROPORT INTERNATIONAL DE CORFU?","pricing_table_":[{"destination":"DE LA CFU - AUX H\u00d4TELS DU CENTRE VILLE","price_day_time":"15","price_night_time":"20","time":"10 MIN"},{"destination":"DE LA CFU - AU CENTRE VILLE","price_day_time":"15","price_night_time":"20","time":"10 MIN"},{"destination":"DE LA CFU - AU PORT DE CORFU","price_day_time":"15","price_night_time":"20","time":"15 MIN"},{"destination":"DE LA CFU - \u00c0 KAVOS","price_day_time":"91","price_night_time":"101","time":"60 MIN"}]},{"name":"Bus","title_line":"Comment se rendre de l'a\u00e9roport de Corfou au centre-ville en bus","top_description":"<p>L&rsquo;a\u00e9roport de Corfou offre un r\u00e9seau de bus tr\u00e8s efficace pour la ville de Corfou. Le bus n \u00b0 15 de la ligne bleue est disponible toutes les heures \u00e0 la gare routi\u00e8re situ\u00e9e \u00e0 l&rsquo;ext\u00e9rieur de l&rsquo;a\u00e9roport. La dur\u00e9e totale du trajet est g\u00e9n\u00e9ralement d\u2019environ 15 minutes dans des conditions de circulation normales, alors que le billet co\u00fbte 1,20 \u20ac.<\/p>\n","fares":"1.20\u20ac","trip_duration":"15 Min.","line_below_price_and_time":"Le temps d'attente est de 60 minutes.","perks":[{"perk":"Confort","rating":"4"},{"perk":"S\u00e9curit\u00e9","rating":"4"},{"perk":"Rapport qualit\u00e9-prix","rating":"5"}],"availability":"La Ligne Bleue No 15 est disponible de 7h50 \u00e0 21h50.","middle_description_title":"Combien co\u00fbte le bus de l'a\u00e9roport de Corfou au centre-ville?","middle_description":"<p>Les billets aller simple pour la Ligne Bleue No. 15 co\u00fbtent 1,20 \u20ac pour les adultes, 0,90 \u20ac et 0,60 \u20ac pour les \u00e9tudiants et les enfants. Les billets doivent \u00eatre achet\u00e9s dans des distributeurs automatiques \u00e0 l&rsquo;a\u00e9roport ou directement aupr\u00e8s du chauffeur pour 0,50 \u20ac suppl\u00e9mentaire.<\/p>\n","middle_2_description_title":"O\u00f9 puis-je le prendre ?","middle_2_description":"<p>La gare routi\u00e8re est situ\u00e9e juste en face de la porte de sortie du terminal principal. Pour arriver \u00e0 la gare, suivez les panneaux ou demandez conseil au personnel en service.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Confort","bottom_description":"<p>La ligne bleue n \u00b0 15 est une excellente alternative au taxi, surtout si vous voyagez seul avec un budget limit\u00e9. \u00c9tant donn\u00e9 que l&rsquo;a\u00e9roport est \u00e0 seulement 3,5 km de la ville de Corfou, la dur\u00e9e du trajet en bus a tr\u00e8s peu de diff\u00e9rence avec un trajet en taxi. Bien que l&rsquo;espace limit\u00e9 pour les passagers et les bagages reste un probl\u00e8me.<\/p>\n","bottom_description_rating":"4","timetables":[{"title":"Ligne Bleue No15","description":"A\u00e9roport de Corfou - Gare routi\u00e8re de San Rocco","view_more_url":"http:\/\/www.astikoktelkerkyras.gr\/img\/15_7.16.pdf"}],"editors_note":"Rappelez-vous que le bus n'est disponible qu'une fois par heure. Par cons\u00e9quent, envisagez toujours des solutions de rechange avant de voyager en cas de retard de vol.","useful_tips":[{"tip":"Il est recommand\u00e9 de faire la queue d\u00e8s que vous le pouvez afin de vous assurer une place dans le bus car celui-ci n'est disponible qu'une fois par heure."},{"tip":"L'achat de billets aupr\u00e8s du chauffeur de bus co\u00fbtera 0,50 \u20ac suppl\u00e9mentaire. Les prix pour les \u00e9tudiants et les enfants sont respectivement de 0,90 \u20ac et 0,60 \u20ac."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"1.20","price_per_passenger_2":"2.40","price_per_passenger_3":"3.60","price_per_passenger_4":"4.80","price_per_passenger_5":"6","price_per_passenger_6":"7.20","price_per_passenger_7":"8.40","price_per_passenger_8":"9.60","price_per_passenger_9":"10.80","price_per_passenger_10":"12","price_per_passenger_11":"13.20","price_per_passenger_12":"14.40","waiting_duration":"60","traveling_duration":"15","availability_from":"07:50","availability_until":"21:50","availability_picture":{"ID":129177,"id":129177,"title":"icn-rankings-bus","filename":"icn-rankings-bus.svg","filesize":2526,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","link":"https:\/\/www.welcomepickups.com\/fr\/barcelona\/aeroport-au-centre-ville\/attachment\/icn-rankings-bus\/","alt":"icn-rankings-bus","author":"1","description":"","caption":"","name":"icn-rankings-bus","status":"inherit","uploaded_to":8840,"date":"2017-06-14 15:41:32","modified":"2017-06-14 15:41:32","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","2048x2048-width":1,"2048x2048-height":1,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","post-thumbnail-width":1,"post-thumbnail-height":1,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","slider-thumb-width":1,"slider-thumb-height":1,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","v3_gallery_1-width":1,"v3_gallery_1-height":1,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","v3_gallery_3-width":1,"v3_gallery_3-height":1,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","v3_gallery_2-width":1,"v3_gallery_2-height":1,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","sidebar_1-width":1,"sidebar_1-height":1,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","sidebar_2-width":1,"sidebar_2-height":1,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","sidebar_3-width":1,"sidebar_3-height":1,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","first_full-width":1,"first_full-height":1,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","main_thumbnail-width":1,"main_thumbnail-height":1,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","main_hero-width":1,"main_hero-height":1,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2017\/06\/icn-rankings-bus.svg","sidebar_cta-width":1,"sidebar_cta-height":1}},"is_247":false,"plot_color":"bus","pricing_table_header":"","pricing_table_":false}],"faq":[{"question":"Combien co\u00fbte un taxi de l'a\u00e9roport de Corfou au centre-ville?","answer":"<p>Le prix moyen d&rsquo;un trajet en taxi entre l&rsquo;a\u00e9roport de Corfou et le centre-ville est de 15 \u20ac. Des facteurs tels que l&rsquo;heure du jour et le type de v\u00e9hicule peuvent \u00e9galement affecter les tarifs de taxi.<\/p>\n"},{"question":"Quelle est la distance entre l'a\u00e9roport de Corfou et le centre-ville?","answer":"<p>La distance totale entre l&rsquo;a\u00e9roport de Corfou et la ville de Corfou est de 3,5 km. Le trajet total en voiture dure g\u00e9n\u00e9ralement entre 7 et 10 minutes.<\/p>\n"},{"question":"Combien co\u00fbte le bus de l'a\u00e9roport de Corfou au centre-ville?","answer":"<p>Les tickets de bus co\u00fbtent 1,20 \u20ac pour les adultes, 0,90 \u20ac pour les \u00e9tudiants et 0,60 \u20ac pour les enfants. Les billets peuvent \u00eatre achet\u00e9s aupr\u00e8s du chauffeur ou des guichets automatiques \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;a\u00e9roport.<\/p>\n"}],"detailed_comparison_title":"","detailed_comparison_subtitle":"","breadcrumbs":[{"title":"Welcome","link":"https:\/\/www.welcomepickups.com\/fr\/"},{"title":"Corfu","link":"https:\/\/www.welcomepickups.com\/fr\/corfu\/"},{"title":"A\u00e9roport de Corfou au centre-ville","link":""}],"posts_category":false,"from_id":"52452","to_id":"","flat_price_1_value":"20","flat_price_2_value":"20","welcome_image":{"ID":166437,"id":166437,"title":"Corfu OG","filename":"Corfu-OG-2-e1521120715883.jpg","filesize":69110,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-e1521120715883.jpg","link":"https:\/\/www.welcomepickups.com\/fr\/homepage\/attachment\/corfu-og-3\/","alt":"Corfu OG","author":"141","description":"","caption":"","name":"corfu-og-3","status":"inherit","uploaded_to":6418,"date":"2018-03-15 12:30:26","modified":"2018-03-15 12:30:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":640,"height":334,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-300x157.jpg","medium-width":300,"medium-height":157,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-768x401.jpg","medium_large-width":768,"medium_large-height":401,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-1024x535.jpg","large-width":960,"large-height":502,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-e1521120715883.jpg","1536x1536-width":640,"1536x1536-height":334,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-e1521120715883.jpg","2048x2048-width":640,"2048x2048-height":334,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-672x372.jpg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-450x225.jpg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-290x117.jpg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-290x170.jpg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-112x117.jpg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-64x64.jpg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-88x66.jpg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-208x106.jpg","sidebar_3-width":197,"sidebar_3-height":100,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-e1521120715883.jpg","first_full-width":640,"first_full-height":334,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-e1521120715883.jpg","main_thumbnail-width":340,"main_thumbnail-height":177,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-e1521120715883.jpg","main_hero-width":640,"main_hero-height":334,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG-2-e1521120715883.jpg","sidebar_cta-width":200,"sidebar_cta-height":104}},"taxi_image":false,"welcome_title":"","welcome_content":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u2708 Moyens de transfert de l&#039;a\u00e9roport de Corfou \u00e0 la ville<\/title>\n<meta name=\"description\" content=\"Tout ce que vous devez savoir sur votre transfert \u00e0 l&#039;a\u00e9roport de Corfou - Comparez tous les moyens de transfert disponibles de l&#039;a\u00e9roport de Corfou \u00e0 la ville ou \u00e0 votre h\u00f4tel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informations sur le transfert de l&#039;a\u00e9roport de Corfou - Welcome\" \/>\n<meta property=\"og:description\" content=\"Trouvez toutes les informations dont vous pourriez avoir besoin pour votre transfert depuis l&#039;a\u00e9roport de Corfou apr\u00e8s avoir atterri \u00e0 l&#039;a\u00e9roport de Corfou. Taxi, bus, train. Voir toutes les options.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-08T14:04:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Informations sur le transfert de l&#039;a\u00e9roport de Corfou - Welcome\" \/>\n<meta name=\"twitter:description\" content=\"Trouvez toutes les informations dont vous pourriez avoir besoin pour votre transfert depuis l&#039;a\u00e9roport de Corfou apr\u00e8s avoir atterri \u00e0 l&#039;a\u00e9roport de Corfou. Taxi, bus, train. Voir toutes les options.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/transfert-aeroport-vers-la-ville\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/transfert-aeroport-vers-la-ville\\\/\",\"name\":\"\u2708 Moyens de transfert de l'a\u00e9roport de Corfou \u00e0 la ville | Welcome Pickups\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/transfert-aeroport-vers-la-ville\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/transfert-aeroport-vers-la-ville\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/amphora-1690_640.jpg\",\"datePublished\":\"2018-03-10T01:05:20+00:00\",\"dateModified\":\"2018-11-08T14:04:31+00:00\",\"description\":\"Tout ce que vous devez savoir sur votre transfert \u00e0 l'a\u00e9roport de Corfou - Comparez tous les moyens de transfert disponibles de l'a\u00e9roport de Corfou \u00e0 la ville ou \u00e0 votre h\u00f4tel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/transfert-aeroport-vers-la-ville\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/transfert-aeroport-vers-la-ville\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/transfert-aeroport-vers-la-ville\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/amphora-1690_640.jpg\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/amphora-1690_640.jpg\",\"width\":640,\"height\":426,\"caption\":\"Corfu Airport to Corfu Town\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/transfert-aeroport-vers-la-ville\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corfu &#8211; Hub\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/corfu\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Moyens de transfert de l&rsquo;a\u00e9roport de Corfou \u00e0 la ville de Corfou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u2708 Moyens de transfert de l'a\u00e9roport de Corfou \u00e0 la ville","description":"Tout ce que vous devez savoir sur votre transfert \u00e0 l'a\u00e9roport de Corfou - Comparez tous les moyens de transfert disponibles de l'a\u00e9roport de Corfou \u00e0 la ville ou \u00e0 votre h\u00f4tel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/","og_locale":"fr_FR","og_type":"article","og_title":"Informations sur le transfert de l'a\u00e9roport de Corfou - Welcome","og_description":"Trouvez toutes les informations dont vous pourriez avoir besoin pour votre transfert depuis l'a\u00e9roport de Corfou apr\u00e8s avoir atterri \u00e0 l'a\u00e9roport de Corfou. Taxi, bus, train. Voir toutes les options.","og_url":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2018-11-08T14:04:31+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Informations sur le transfert de l'a\u00e9roport de Corfou - Welcome","twitter_description":"Trouvez toutes les informations dont vous pourriez avoir besoin pour votre transfert depuis l'a\u00e9roport de Corfou apr\u00e8s avoir atterri \u00e0 l'a\u00e9roport de Corfou. Taxi, bus, train. Voir toutes les options.","twitter_image":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/Corfu-OG.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/","url":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/","name":"\u2708 Moyens de transfert de l'a\u00e9roport de Corfou \u00e0 la ville | Welcome Pickups","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","datePublished":"2018-03-10T01:05:20+00:00","dateModified":"2018-11-08T14:04:31+00:00","description":"Tout ce que vous devez savoir sur votre transfert \u00e0 l'a\u00e9roport de Corfou - Comparez tous les moyens de transfert disponibles de l'a\u00e9roport de Corfou \u00e0 la ville ou \u00e0 votre h\u00f4tel.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/03\/amphora-1690_640.jpg","width":640,"height":426,"caption":"Corfu Airport to Corfu Town"},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/fr\/corfu\/transfert-aeroport-vers-la-ville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Corfu &#8211; Hub","item":"https:\/\/www.welcomepickups.com\/fr\/corfu\/"},{"@type":"ListItem","position":3,"name":"Moyens de transfert de l&rsquo;a\u00e9roport de Corfou \u00e0 la ville de Corfou"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/fr\/#website","url":"https:\/\/www.welcomepickups.com\/fr\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/fr\/#organization"},"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/fr\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.welcomepickups.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages\/60255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/comments?post=60255"}],"version-history":[{"count":0,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages\/60255\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/pages\/37331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/media\/22601"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/fr\/wp-json\/wp\/v2\/media?parent=60255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}