{"id":324258,"date":"2022-08-16T16:22:53","date_gmt":"2022-08-16T14:22:53","guid":{"rendered":"https:\/\/www.welcomepickups.com\/?page_id=324258&#038;preview_id=324258"},"modified":"2022-12-23T11:51:46","modified_gmt":"2022-12-23T09:51:46","slug":"zagreb","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/it\/zagreb\/","title":{"rendered":"Zagabria &#8211; Hub"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":141,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-hub-v3.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-324258","page","type-page","status-publish","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"destination_image":{"ID":119034,"id":119034,"title":"new_bg_v6","filename":"new_bg_v6.jpg","filesize":71659,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","link":"https:\/\/www.welcomepickups.com\/it\/rome\/attachment\/new_bg_v6-2\/","alt":"new_bg_v6","author":"1","description":"","caption":"","name":"new_bg_v6-2","status":"inherit","uploaded_to":6833,"date":"2016-03-21 18:44:40","modified":"2021-03-05 13:44:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1416,"height":720,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6-300x153.jpg","medium-width":300,"medium-height":153,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6-768x391.jpg","medium_large-width":768,"medium_large-height":391,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6-1024x521.jpg","large-width":960,"large-height":488,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","1536x1536-width":1416,"1536x1536-height":720,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","2048x2048-width":1416,"2048x2048-height":720,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6-672x372.jpg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6-450x225.jpg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","v3_gallery_1-width":230,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","v3_gallery_3-width":290,"v3_gallery_3-height":147,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","v3_gallery_2-width":112,"v3_gallery_2-height":57,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","sidebar_1-width":64,"sidebar_1-height":33,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","sidebar_2-width":88,"sidebar_2-height":45,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","sidebar_3-width":197,"sidebar_3-height":100,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","first_full-width":667,"first_full-height":339,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","main_thumbnail-width":340,"main_thumbnail-height":173,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","main_hero-width":1298,"main_hero-height":660,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2016\/02\/new_bg_v6.jpg","sidebar_cta-width":200,"sidebar_cta-height":102}},"destination_name":"Zagabria","destination_tagline":"","destination_description":"","local_phone":"","local_address":"","local_name":"","local_website":"","local_address_map_url":"","change_all_seo6_children_to_gosafe":false,"viber":"","whatsapp":"","messenger":"","chat":"","drivers_title":"","drivers_subtitle":"","safety_title":"","render_new_widget":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zagabria, Croazia - Welcome<\/title>\n<meta name=\"description\" content=\"Servizi Welcome a Zagabria. Prenota il tuo trasferimento aeroportuale e avrai molto di pi\u00f9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/it\/zagreb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zagabria - Hub\" \/>\n<meta property=\"og:description\" content=\"Servizi Welcome a Zagabria. Prenota il tuo trasferimento aeroportuale e avrai molto di pi\u00f9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/it\/zagreb\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-23T09:51:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2015\/12\/welcome_open_graph_home.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/zagreb\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/zagreb\\\/\",\"name\":\"Zagabria, Croazia - Welcome\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#website\"},\"datePublished\":\"2022-08-16T14:22:53+00:00\",\"dateModified\":\"2022-12-23T09:51:46+00:00\",\"description\":\"Servizi Welcome a Zagabria. Prenota il tuo trasferimento aeroportuale e avrai molto di pi\u00f9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/zagreb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/zagreb\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/zagreb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zagabria &#8211; Hub\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#organization\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zagabria, Croazia - Welcome","description":"Servizi Welcome a Zagabria. Prenota il tuo trasferimento aeroportuale e avrai molto di pi\u00f9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/it\/zagreb\/","og_locale":"it_IT","og_type":"article","og_title":"Zagabria - Hub","og_description":"Servizi Welcome a Zagabria. Prenota il tuo trasferimento aeroportuale e avrai molto di pi\u00f9.","og_url":"https:\/\/www.welcomepickups.com\/it\/zagreb\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2022-12-23T09:51:46+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2015\/12\/welcome_open_graph_home.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/it\/zagreb\/","url":"https:\/\/www.welcomepickups.com\/it\/zagreb\/","name":"Zagabria, Croazia - Welcome","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/it\/#website"},"datePublished":"2022-08-16T14:22:53+00:00","dateModified":"2022-12-23T09:51:46+00:00","description":"Servizi Welcome a Zagabria. Prenota il tuo trasferimento aeroportuale e avrai molto di pi\u00f9.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/it\/zagreb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/it\/zagreb\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/it\/zagreb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/it\/"},{"@type":"ListItem","position":2,"name":"Zagabria &#8211; Hub"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/it\/#website","url":"https:\/\/www.welcomepickups.com\/it\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/it\/#organization"},"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/it\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.welcomepickups.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/324258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/comments?post=324258"}],"version-history":[{"count":1,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/324258\/revisions"}],"predecessor-version":[{"id":337779,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/324258\/revisions\/337779"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/media?parent=324258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}