{"id":355460,"date":"2023-05-25T16:16:48","date_gmt":"2023-05-25T14:16:48","guid":{"rendered":"https:\/\/www.welcomepickups.com\/dar-es-salaam\/taxi\/"},"modified":"2023-05-25T18:59:42","modified_gmt":"2023-05-25T16:59:42","slug":"taxi","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/","title":{"rendered":"Taxi a Dar es Salaam"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":68,"featured_media":332068,"parent":355446,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-transfer-v1.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-355460","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"show_in_frontpage":false,"is_seo_five":false,"second_destination":false,"title":"Taxi a Dar es Salaam","small_title":"","heading_title":"h1","subtitle":"Consigli utili sui taxi a Dar es Salaam","heading_subtitle":"h2","background":{"ID":332068,"id":332068,"title":"Dar Es Salaam","filename":"Dar-Es-Salaam.jpeg","filesize":419781,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam.jpeg","link":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/attachment\/dar-es-salaam-2\/","alt":"","author":"176","description":"","caption":"","name":"dar-es-salaam-2","status":"inherit","uploaded_to":355460,"date":"2022-10-14 14:39:46","modified":"2022-10-14 14:39:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1920,"height":1081,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-300x169.jpeg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-768x432.jpeg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-1024x577.jpeg","large-width":960,"large-height":541,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-1536x865.jpeg","1536x1536-width":1536,"1536x1536-height":865,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam.jpeg","2048x2048-width":1920,"2048x2048-height":1081,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-672x372.jpeg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-450x225.jpeg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-290x117.jpeg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-290x170.jpeg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-112x117.jpeg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-64x64.jpeg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-88x66.jpeg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-197x151.jpeg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-667x416.jpeg","first_full-width":667,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-340x188.jpeg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-1920x660.jpeg","main_hero-width":1920,"main_hero-height":660,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam-200x125.jpeg","sidebar_cta-width":200,"sidebar_cta-height":125}},"tts_title":"Taxi a Dar es Salaam","tts__title_heading":"h2","tts_text":"<p>Dar es Salaam \u00e8 una grande citt\u00e0 portuale industriale che si affaccia sull&#8217;Oceano Indiano. La maggior parte dei turisti di solito sceglie la Tanzania per fare un safari, ma si riserva sempre di lasciare un po&#8217; di tempo per esplorare questa citt\u00e0 costiera che in principio era un piccolo villaggio di pescatori. A Dar es Salaam \u00e8 possibile immergersi nella storia del paese visitando il National Museum, mentre al Village Museum si possono scoprire le ricostruzioni delle abitazioni tradizionali di alcune trib\u00f9 della Tanzania. Dar es Salaam \u00e8 una culla di culture ed etnie diverse ed \u00e8 famosa anche per i suoi piatti a base di pesce, la musica e la sua vicinanza a isole meravigliose, tutte da esplorare.<\/p>\n<p>Il modo pi\u00f9 semplice di muoversi a Dar es Salaam \u00e8 di farlo con il taxi, non solo ti far\u00e0 risparmiare molto tempo, ma ti permetter\u00e0 anche di andare direttamente da un luogo all&#8217;altro. Ci sono diverse compagnie di taxi a Dar es Salaam e i taxi puoi trovarli un po&#8217; ovunque vicino alle pi\u00f9 importanti attrazioni turistiche o per strada. Puoi anche prenotare il taxi per telefono. Il prezzo della corsa va sempre contrattato con il tassista prima di salire a bordo. Un&#8217;altra opzione \u00e8 quella di prenotare il taxi in anticipo a prezzo fisso con <a href=\"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi-aeroporto\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a>, in questo modo potrai godere dei servizi di un autista professionista che parla inglese e di prezzi convenienti.<\/p>\n","tts_photo":{"ID":348982,"id":348982,"title":"Dar Es Salaam Taxi","filename":"Dar-Es-Salaam-Taxi.png","filesize":428245,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi.png","link":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/attachment\/dar-es-salaam-taxi-2\/","alt":"","author":"176","description":"","caption":"","name":"dar-es-salaam-taxi-2","status":"inherit","uploaded_to":355460,"date":"2023-04-07 13:55:20","modified":"2023-04-07 13:55:20","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1686,"height":900,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-300x160.png","medium-width":300,"medium-height":160,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-768x410.png","medium_large-width":768,"medium_large-height":410,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-1024x547.png","large-width":960,"large-height":513,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-1536x820.png","1536x1536-width":1536,"1536x1536-height":820,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi.png","2048x2048-width":1686,"2048x2048-height":900,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-672x372.png","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-450x225.png","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-290x117.png","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-290x170.png","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-112x117.png","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-64x64.png","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-88x66.png","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-197x151.png","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-667x416.png","first_full-width":667,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-340x188.png","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-1686x660.png","main_hero-width":1686,"main_hero-height":660,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/04\/Dar-Es-Salaam-Taxi-200x125.png","sidebar_cta-width":200,"sidebar_cta-height":125}},"photo_captions":"","tts_title_2":"Costo del taxi a Dar es Salaam","tts__title_2_heading":"h2","tts_text_2":"<p>A Dar es Salaam la tariffa del taxi si contratta con il tassista prima di salire a bordo. Le tariffe variano da compagnia a compagnia e da tassista a tassista, ma in media la tariffa di base \u00e8 di circa 1,60 \u20ac (3.750 TZS) e quella a chilometro di circa 1,70 \u20ac (4.000 TZS). Di notte molti tassisti applicano la tariffa notturna che \u00e8 leggermente superiore. Il costo di una corsa dall&#8217;aeroporto di Dar es Salaam al centro citt\u00e0 in genere \u00e8 circa 17,40 \u20ac (40.000 TZS), se preferisci pagare un prezzo fisso e conveniente senza costi nascosti, puoi prenotare il tuo trasferimento in anticipo con <a href=\"https:\/\/www.welcomepickups.com\/dar-es-salaam\/airport-taxi\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a>.<\/p>\n","car_type":false,"cb_title":"Come prendere il taxi a Dar es Salaam","cb_text":"<p>Ci sono diverse compagnie di taxi a Dar es Salaam. In genere i taxi si trovano vicino alle attrazioni turistiche e per strada, dove puoi chiamarli con un cenno della mano. I taxi a Dar es Salaam si riconoscono, perch\u00e9 sono tutti veicoli di colore bianco. \u00c8 anche possibile chiamare un taxi per telefono per farsi venire a prendere. Questi sono i numeri di alcune delle compagnie pi\u00f9 fidate: <strong>Tanzania Rent A Car LTD <\/strong>(+2 (557) 5478 0876 o +2 (557) 7370 0400) e <strong>Tan Taxi<\/strong> (+2 (557) 7711 5054). Se non vuoi aspettare che arrivi il taxi o non vuoi perdere tempo a cercarne uno per strada, puoi <a href=\"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi-aeroporto\/\" title=\"Prenotare Un Servizio Di Trasferimento Privato In Anticipo\">prenotare un servizio di trasferimento privato in anticipo<\/a> con Welcome che ti metter\u00e0 a disposizione tutti tassisti professionisti.<\/p>\n","content_below_car_title_heading":"h3","content_below_car_type":[{"title":"Prenota il trasferimento a Dar es Salaam in anticipo","content_below_type_heading":"h2","text":"<p>Se sai gi\u00e0 dove devi andare e da dove devono venirti a prendere, puoi risparmiare tempo e fastidi prenotando il taxi a Dar es Salaam in anticipo. Prenotando con <a href=\"https:\/\/www.welcomepickups.com\/dar-es-salaam\/airport-taxi\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a> sai che avrai la garanzia di un servizio rapido e puntuale operato da autisti professionisti. Inoltre pagherai un prezzo molto conveniente e non dovrai preoccuparti di contrattare il costo della corsa con il tassista.<\/p>\n","list":false},{"title":"Consigli per i taxi a Dar es Salaam","content_below_type_heading":"h2","text":"","list":false},{"title":"Taxi accessibili ai disabili in sedia a rotelle a Dar es Salaam","content_below_type_heading":"h2","text":"<p>Dar es Salaam \u00e8 ancora un po&#8217; indietro per quanto riguarda l&#8217;accessibilit\u00e0 e prendere i mezzi pubblici pu\u00f2 risultare un&#8217;esperienza non poco faticosa per coloro che hanno ridotta mobilit\u00e0. Se ti occorre prenotare un taxi accessibile per i disabili su sedia a rotelle, puoi contattare Viator (sia online che per telefono) al numero +1 (702) 648 5873. Inoltre, molte compagnie di taxi offrono veicoli pi\u00f9 grandi che possono caricare la sedia a rotelle chiusa nel bagagliaio.<\/p>\n","list":false},{"title":"Sicurezza e reclami sui taxi di Dar es Salaam","content_below_type_heading":"h2","text":"<p>A Dar es Salaam i taxi sono comodi e sono il mezzo pi\u00f9 veloce per esplorare la citt\u00e0 e i suoi dintorni. Sono considerati anche i mezzi di trasporto pi\u00f9 sicuri. Nel caso in cui dovessi avere dei problemi durante la corsa, prendi nota dell&#8217;incidente, dell&#8217;ora, della licenza e della targa del taxi che ti serviranno in caso di reclamo. Puoi fare reclamo direttamente alla compagnia del taxi o, in casi pi\u00f9 gravi, puoi rivolgerti alla polizia.<\/p>\n","list":false}],"faq_2":[{"title":"Come viene calcolato il prezzo della corsa sui taxi di Dar es Salaam?","response":"<p>Il prezzo della corsa in taxi si contratta con il tassista prima di salire a bordo. In genere la tariffa a chilometro \u00e8 di circa 1,70 \u20ac (4.000 TZS). Il costo di un trasferimento in taxi dall&#8217;aeroporto di Dar es Salaam al centro citt\u00e0 \u00e8 di circa 17,40 \u20ac (40.000 TZS).<\/p>\n"},{"title":"Quali numeri posso chiamare per prenotare un taxi a Dar es Salaam?","response":"<p>Per chiamare un taxi per telefono puoi rivolgerti a una della seguenti compagnie: Tanzania Rent A Car LTD (+255 (754) 780 876 e Tan Taxi (+255 (777) 115 054). Puoi anche prenotare un trasferimento in anticipo con Welcome Pickups per godere della professionalit\u00e0 dei suoi autisti che parlano inglese e di prezzi fissi molto convenienti.<\/p>\n"},{"title":"I taxi di Dar es Salaam sono affidabili?","response":"<p>I taxi a Dar es Salaam sono considerati i mezzi pi\u00f9 sicuri su cui viaggiare per spostarsi in citt\u00e0 e visitarne i dintorni. Se vuoi essere sicuro di ricevere sempre il servizio migliore prenota il tuo taxi in anticipo con una compagnia quotata oppure con <a href=\"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi-aeroporto\/\" title=\"Welcome Pickups\">Welcome Pickups<\/a>.<\/p>\n"}],"pricing_table_header":"","pricing_table":[{"destination":"DALL'AEROPORTO DI DAR ES SALAAM AL CENTRO CITT\u00c0","price_day_time":"17,40","price_night_time":"17,40","time":"20 MIN."},{"destination":"DA DAR ES SALAAM CENTRO CITT\u00c0 AL VILLAGE MUSEUM","price_day_time":"13","price_night_time":"13","time":"15 MIN."},{"destination":"DA DAR ES SALAAM CENTRO CITT\u00c0 AL VILLAGE MUSEUM\t13 \u20ac 15 Min. DA DAR ES SALAAM AL MERCATO KARIAKOO  ","price_day_time":"5","price_night_time":"5","time":"10 MIN."}],"is_mozio_destination":false,"city_center_coords":{"address":"Dar es Salaam, Tanzania","lat":-6.7923539999999996,"lng":39.208328399999999,"zoom":14,"place_id":"ChIJ8dabFq5LXBgR3aGGoCZrD5Q","name":"Dar es Salaam","city":"Dar es Salaam","city_short":"DSM","state":"Dar es Salam","country":"Tanzania","country_short":"TZ"},"pdf_guide_url":"","download_and_read_later_title":"","below_contact_form":"","faq":false,"traveling_with_friends":false,"render_new_widget":false,"from_id":"","is_seo_6":false,"posts_category":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Taxi a Dar es Salaam - Prezzi e consigli utili per i taxi a taxi a Dar es Salaam<\/title>\n<meta name=\"description\" content=\"Ottieni tutte le informazioni di cui hai bisogno sui taxi a Dar es Salaam prima di visitare la citt\u00e0, dai prezzi ai consigli utili sui trasferimenti privati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taxi a Dar es Salaam\" \/>\n<meta property=\"og:description\" content=\"Ottieni tutte le informazioni di cui hai bisogno sui taxi a Dar es Salaam prima di visitare la citt\u00e0, dai prezzi ai consigli utili sui trasferimenti privati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-25T16:59:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/taxi\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/taxi\\\/\",\"name\":\"Taxi a Dar es Salaam - Prezzi e consigli utili per i taxi a taxi a Dar es Salaam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/taxi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/taxi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Dar-Es-Salaam.jpeg\",\"datePublished\":\"2023-05-25T14:16:48+00:00\",\"dateModified\":\"2023-05-25T16:59:42+00:00\",\"description\":\"Ottieni tutte le informazioni di cui hai bisogno sui taxi a Dar es Salaam prima di visitare la citt\u00e0, dai prezzi ai consigli utili sui trasferimenti privati.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/taxi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/taxi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/taxi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Dar-Es-Salaam.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Dar-Es-Salaam.jpeg\",\"width\":1920,\"height\":1081},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/taxi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dar es Salaam &#8211; Hub\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/dar-es-salaam\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Taxi a Dar es Salaam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#organization\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Taxi a Dar es Salaam - Prezzi e consigli utili per i taxi a taxi a Dar es Salaam","description":"Ottieni tutte le informazioni di cui hai bisogno sui taxi a Dar es Salaam prima di visitare la citt\u00e0, dai prezzi ai consigli utili sui trasferimenti privati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/","og_locale":"it_IT","og_type":"article","og_title":"Taxi a Dar es Salaam","og_description":"Ottieni tutte le informazioni di cui hai bisogno sui taxi a Dar es Salaam prima di visitare la citt\u00e0, dai prezzi ai consigli utili sui trasferimenti privati.","og_url":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2023-05-25T16:59:42+00:00","og_image":[{"width":1920,"height":1081,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/","url":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/","name":"Taxi a Dar es Salaam - Prezzi e consigli utili per i taxi a taxi a Dar es Salaam","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam.jpeg","datePublished":"2023-05-25T14:16:48+00:00","dateModified":"2023-05-25T16:59:42+00:00","description":"Ottieni tutte le informazioni di cui hai bisogno sui taxi a Dar es Salaam prima di visitare la citt\u00e0, dai prezzi ai consigli utili sui trasferimenti privati.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam.jpeg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2022\/10\/Dar-Es-Salaam.jpeg","width":1920,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/taxi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/it\/"},{"@type":"ListItem","position":2,"name":"Dar es Salaam &#8211; Hub","item":"https:\/\/www.welcomepickups.com\/it\/dar-es-salaam\/"},{"@type":"ListItem","position":3,"name":"Taxi a Dar es Salaam"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/it\/#website","url":"https:\/\/www.welcomepickups.com\/it\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/it\/#organization"},"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/it\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.welcomepickups.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/355460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/comments?post=355460"}],"version-history":[{"count":2,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/355460\/revisions"}],"predecessor-version":[{"id":355499,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/355460\/revisions\/355499"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/355446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/media\/332068"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/media?parent=355460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}