{"id":38267,"date":"2018-02-11T11:07:08","date_gmt":"2018-02-11T09:07:08","guid":{"rendered":"https:\/\/www.welcomepickups.com\/tel-aviv\/airport-transfer-book\/"},"modified":"2019-09-09T11:59:30","modified_gmt":"2019-09-09T09:59:30","slug":"airport-transfer-book","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/it\/tel-aviv\/airport-transfer-book\/","title":{"rendered":"Tel Aviv &#8211; Conversion &#8211; V2"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":141,"featured_media":0,"parent":31232,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-conversion-v2.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-38267","page","type-page","status-publish","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"booking_form_js":"","city_small":"tel aviv","city_title":"Tel Aviv","city_capital":"TEL AVIV","subtitle":"<p>Scegli un autista esperto che parla inglese che ti viene a prendere <br \/> all'aeroporto di Tel Aviv al <strong>prezzo migliore possibile.<\/strong><\/p>\n","flat_price_1_title":"Dall'aeroporto di Tel Aviv al centro citt\u00e0","flat_price_1_value":"39","flat_price_1_subtitle":"Include tasse, pedaggi e mance","flat_price_2_title":"Dall'aeroporto di Tel Aviv a Gerusalemme","flat_price_2_value":"70","flat_price_2_subtitle":"Include tasse, pedaggi e mance","flat_prices_highlight_tooltip":"<p>Allo stesso prezzo del taxi tradizionale<\/p>\n","render_new_widget":false,"title_1":"","title_1_heading":"h1","title_2":"","title_2_heading":"h1","title_3":"","title_3_heading":"h1","title_4":"","title_4_heading":"h1","subtitle_heading":"h1"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prenota il tuo trasferimento dall&#039;aeroporto di Tel Aviv - Welcome Pickups<\/title>\n<meta name=\"description\" content=\"Scegli un autista locale fidato che ti viene a prendere all&#039;aeroporto di Tel Aviv allo stesso prezzo di un taxi tradizionale. Prenota in anticipo ed evita i sovrapprezzi.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welcome Pickups - Trasferimenti dall&#039;aeroporto di Tel Aviv\" \/>\n<meta property=\"og:description\" content=\"Scegli un autista locale esperto che parla inglese e che ti viene a prendere all&#039;aeroporto allo stesso prezzo di un taxi tradizionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/it\/tel-aviv\/trasferimenti-aeroporto-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-09T09:59:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/OG-IMAGE-Tel-Aviv-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Welcome Pickups - Trasferimenti dall&#039;aeroporto di Tel Aviv\" \/>\n<meta name=\"twitter:description\" content=\"Scegli un autista locale esperto che parla inglese e che ti viene a prendere all&#039;aeroporto allo stesso prezzo di un taxi tradizionale.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/OG-IMAGE-Tel-Aviv-2.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/tel-aviv\\\/airport-transfer-book\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/tel-aviv\\\/trasferimenti-aeroporto-citta\\\/\",\"name\":\"Prenota il tuo trasferimento dall'aeroporto di Tel Aviv - Welcome Pickups\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#website\"},\"datePublished\":\"2018-02-11T09:07:08+00:00\",\"dateModified\":\"2019-09-09T09:59:30+00:00\",\"description\":\"Scegli un autista locale fidato che ti viene a prendere all'aeroporto di Tel Aviv allo stesso prezzo di un taxi tradizionale. Prenota in anticipo ed evita i sovrapprezzi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/tel-aviv\\\/trasferimenti-aeroporto-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/tel-aviv\\\/trasferimenti-aeroporto-citta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/tel-aviv\\\/trasferimenti-aeroporto-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tel Aviv &#8211; Hub\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/tel-aviv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tel Aviv &#8211; Conversion &#8211; V2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#organization\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prenota il tuo trasferimento dall'aeroporto di Tel Aviv - Welcome Pickups","description":"Scegli un autista locale fidato che ti viene a prendere all'aeroporto di Tel Aviv allo stesso prezzo di un taxi tradizionale. Prenota in anticipo ed evita i sovrapprezzi.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"it_IT","og_type":"article","og_title":"Welcome Pickups - Trasferimenti dall'aeroporto di Tel Aviv","og_description":"Scegli un autista locale esperto che parla inglese e che ti viene a prendere all'aeroporto allo stesso prezzo di un taxi tradizionale.","og_url":"https:\/\/www.welcomepickups.com\/it\/tel-aviv\/trasferimenti-aeroporto-citta\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2019-09-09T09:59:30+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/OG-IMAGE-Tel-Aviv-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Welcome Pickups - Trasferimenti dall'aeroporto di Tel Aviv","twitter_description":"Scegli un autista locale esperto che parla inglese e che ti viene a prendere all'aeroporto allo stesso prezzo di un taxi tradizionale.","twitter_image":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2018\/02\/OG-IMAGE-Tel-Aviv-2.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/it\/tel-aviv\/airport-transfer-book\/","url":"https:\/\/www.welcomepickups.com\/it\/tel-aviv\/trasferimenti-aeroporto-citta\/","name":"Prenota il tuo trasferimento dall'aeroporto di Tel Aviv - Welcome Pickups","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/it\/#website"},"datePublished":"2018-02-11T09:07:08+00:00","dateModified":"2019-09-09T09:59:30+00:00","description":"Scegli un autista locale fidato che ti viene a prendere all'aeroporto di Tel Aviv allo stesso prezzo di un taxi tradizionale. Prenota in anticipo ed evita i sovrapprezzi.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/it\/tel-aviv\/trasferimenti-aeroporto-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/it\/tel-aviv\/trasferimenti-aeroporto-citta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/it\/tel-aviv\/trasferimenti-aeroporto-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tel Aviv &#8211; Hub","item":"https:\/\/www.welcomepickups.com\/it\/tel-aviv\/"},{"@type":"ListItem","position":3,"name":"Tel Aviv &#8211; Conversion &#8211; V2"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/it\/#website","url":"https:\/\/www.welcomepickups.com\/it\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/it\/#organization"},"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/it\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.welcomepickups.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/38267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/comments?post=38267"}],"version-history":[{"count":0,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/38267\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/pages\/31232"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/it\/wp-json\/wp\/v2\/media?parent=38267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}