{"id":384774,"date":"2023-12-08T10:40:20","date_gmt":"2023-12-08T08:40:20","guid":{"rendered":"https:\/\/www.welcomepickups.com\/boston\/airport-to-worcester\/"},"modified":"2023-12-16T16:13:59","modified_gmt":"2023-12-16T14:13:59","slug":"aeroporto-para-worcester","status":"publish","type":"page","link":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/","title":{"rendered":"Como ir do Aeroporto Boston Logan a Worcester"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":209,"featured_media":372592,"parent":380320,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-destination-ranking-v61.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-384774","page","type-page","status-publish","has-post-thumbnail","hentry"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":{"to":"","detailed_comparison_title":"","detailed_comparison_subtitle":"","welcome_image":false,"taxi_image":false,"welcome_title":"","welcome_content":"","safety_widget_title":"","safety_widget_subtitle":"","render_new_widget":false,"breadcrumbs":[{"title":"Welcome Pickups","link":"https:\/\/www.welcomepickups.com\/pt-pt\/"},{"title":"Boston","link":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/"},{"title":"Aeroporto para Worcester","link":""}],"faq":[{"question":"Como fa\u00e7o para ir do Aeroporto Logan a Worcester?","answer":"<p>Existem v\u00e1rias op\u00e7\u00f5es de transporte do Aeroporto Logan para Worcester, incluindo t\u00e1xi, transfer privado, \u00f4nibus e metr\u00f4. A op\u00e7\u00e3o mais r\u00e1pida e f\u00e1cil \u00e9 de t\u00e1xi ou <a href=\"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/taxi-aeroporto\/\" title=\"Transfer\u00eancia Privada\">transfer\u00eancia privada<\/a>, que pode levar apenas 55 minutos e a op\u00e7\u00e3o mais barata \u00e9 usar o transporte gratuito para o aeroporto (SL1) e a transfer\u00eancia para o Commuter Rail, com um tempo de viagem de mais de 2 horas.<\/p>\n"},{"question":"Qual \u00e9 a dist\u00e2ncia do Aeroporto Logan at\u00e9 Worcester?","answer":"<p>A rota mais direta do Aeroporto Logan para Worcester ao viajar de carro \u00e9 cobrir uma dist\u00e2ncia de cerca de 80 km (50 mi).<\/p>\n"},{"question":"Qual \u00e9 o custo de um t\u00e1xi do Aeroporto de Boston para Worcester?","answer":"<p>Todos os t\u00e1xis do Aeroporto de Boston s\u00e3o medidos e as tarifas s\u00e3o calculadas pela dist\u00e2ncia percorrida. Para um t\u00e1xi que pode acomodar at\u00e9 4 passageiros, a viagem de aproximadamente 80 km do Aeroporto Logan para Worcester custa US$154 (\u20ac146,70), incluindo a sobretaxa do aeroporto de US$ 2,25 (2,15). O custo pode variar se uma rota mais longa for tomada devido \u00e0s condi\u00e7\u00f5es de tr\u00e1fego.<\/p>\n"}],"from":"Aeroporto Boston Logan ","header_picture":{"ID":372592,"id":372592,"title":"Worcester, Massachusetts","filename":"Worcester-Massachusetts.jpeg","filesize":365053,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts.jpeg","link":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/attachment\/worcester-massachusetts-2\/","alt":"A group of cars stopped at a set of traffic lights on a city street surrounded by buildings.","author":"176","description":"Logan Airport to Worcester","caption":"Logan Airport to Worcester","name":"worcester-massachusetts-2","status":"inherit","uploaded_to":380320,"date":"2023-09-27 08:45:08","modified":"2023-10-04 21:59:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.welcomepickups.com\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-300x200.jpeg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-768x512.jpeg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-1024x683.jpeg","large-width":960,"large-height":640,"1536x1536":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-1536x1024.jpeg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts.jpeg","2048x2048-width":1920,"2048x2048-height":1280,"post-thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-672x372.jpeg","post-thumbnail-width":672,"post-thumbnail-height":372,"slider-thumb":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-450x225.jpeg","slider-thumb-width":450,"slider-thumb-height":225,"v3_gallery_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-290x117.jpeg","v3_gallery_1-width":290,"v3_gallery_1-height":117,"v3_gallery_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-290x170.jpeg","v3_gallery_3-width":290,"v3_gallery_3-height":170,"v3_gallery_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-112x117.jpeg","v3_gallery_2-width":112,"v3_gallery_2-height":117,"sidebar_1":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-64x64.jpeg","sidebar_1-width":64,"sidebar_1-height":64,"sidebar_2":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-88x66.jpeg","sidebar_2-width":88,"sidebar_2-height":66,"sidebar_3":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-197x151.jpeg","sidebar_3-width":197,"sidebar_3-height":151,"first_full":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-667x416.jpeg","first_full-width":667,"first_full-height":416,"main_thumbnail":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-340x188.jpeg","main_thumbnail-width":340,"main_thumbnail-height":188,"main_hero":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-1920x660.jpeg","main_hero-width":1920,"main_hero-height":660,"sidebar_cta":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts-200x125.jpeg","sidebar_cta-width":200,"sidebar_cta-height":125}},"line_above_title":"OS MELHORES GUIAS DE TRANSPORTE DO AEROPORTO","title_line":"Como ir do Aeroporto Logan a Worcester","transportation_means":[{"name":"Welcome","title_line":"","top_description":"","fares":"","trip_duration":"","line_below_price_and_time":"","perks":false,"availability":"","middle_description_title":"","middle_description":"","middle_2_description_title":"","middle_2_description":"","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"","bottom_description":"","bottom_description_rating":"5","timetables":false,"editors_note":"","useful_tips":false,"photos":false,"gallery_subline":"","infographics_only":true,"price_per_passenger_1":"235","price_per_passenger_2":"235","price_per_passenger_3":"235","price_per_passenger_4":"265","price_per_passenger_5":"265","price_per_passenger_6":"265","price_per_passenger_7":"500","price_per_passenger_8":"500","price_per_passenger_9":"500","price_per_passenger_10":"530","price_per_passenger_11":"530","price_per_passenger_12":"530","waiting_duration":"0","traveling_duration":"55","availability_from":"","availability_until":"","availability_picture":false,"is_247":true,"plot_color":"welcome","pricing_table_header":"","pricing_table_":false},{"name":"T\u00e1xi","title_line":"Como ir do Aeroporto Logan para Worcester de t\u00e1xi","top_description":"<p>A maneira mais r\u00e1pida e conveniente de ir do Aeroporto de Boston para Worcester \u00e9 pegando um t\u00e1xi do aeroporto. Os t\u00e1xis est\u00e3o dispon\u00edveis 24 horas por dia, 7 dias por semana, e as tarifas s\u00e3o calculadas usando um tax\u00edmetro. Ir do aeroporto a Worcester de t\u00e1xi levar\u00e1 cerca de 55 minutos, dependendo das condi\u00e7\u00f5es do tr\u00e1fego.<\/p>\n","fares":"$154 (\u20ac146.70)","trip_duration":"55 Min.","line_below_price_and_time":"Dependendo da hora do dia e das condi\u00e7\u00f5es do tr\u00e2nsito, uma viagem de t\u00e1xi levar\u00e1 entre 55 e 70 minutos.","perks":[{"perk":"Conveni\u00eancia","rating":"5"},{"perk":"Seguran\u00e7a","rating":"5"},{"perk":"Rela\u00e7\u00e3o custo-benef\u00edcio","rating":"4"}],"availability":"Os t\u00e1xis est\u00e3o dispon\u00edveis no Aeroporto Logan de Boston 24 horas por dia, 7 dias por semana.","middle_description_title":"Quanto custa a tarifa de t\u00e1xi do Aeroporto Logan para Worcester?","middle_description":"<p>Todos os t\u00e1xis do Aeroporto de Boston s\u00e3o medidos e as tarifas s\u00e3o calculadas pela dist\u00e2ncia percorrida. A primeira 1\/7 milha \u00e9 cobrada em US$ 2,60 (\u20ac 2,50) e, em seguida, cada milha depois \u00e9 cobrada US$ 2,80 (\u20ac 2,70), at\u00e9 uma dist\u00e2ncia de 20 milhas. Al\u00e9m de 20 milhas, cada milha \u00e9 cobrada a uma taxa fixa de US$ 3,20 (\u20ac3).<\/p>\n<p>Com base nisso, a viagem de t\u00e1xi de aproximadamente 80 km (50 mi) do Aeroporto Logan para Worcester custa US$154 (\u20ac146,70) para at\u00e9 4 passageiros, incluindo a sobretaxa de aeroporto de US$ 2,25 (\u20ac2,15), mas o custo pode variar se uma rota mais longa for tomada devido \u00e0s condi\u00e7\u00f5es de tr\u00e2nsito.<\/p>\n<p>Para uma tarifa definida que n\u00e3o muda, uma <a title=\"Transfer\u00eancia Privada do Aeroporto\" href=\"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/taxi-aeroporto\/\">transfer\u00eancia privada do aeroporto de Boston<\/a> diretamente para o seu destino em Worcester pode ser pr\u00e9-organizada com a Welcome Pickups.<\/p>\n","middle_2_description_title":"De onde eu pego um t\u00e1xi?","middle_2_description":"<div class=\"article-with-map\">\n<div class=\"to-city-by-buss__text\">Os t\u00e1xis est\u00e3o dispon\u00edveis 24 horas por dia, 7 dias por semana, no n\u00edvel de chegadas de cada terminal. No Terminal C, voc\u00ea encontrar\u00e1 a pra\u00e7a de t\u00e1xis no t\u00e9rreo da Garagem Central.<\/div>\n<\/div>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Conveni\u00eancia","bottom_description":"<p>Pegar um t\u00e1xi do Aeroporto Logan para Worcester \u00e9 a op\u00e7\u00e3o de transporte mais f\u00e1cil e r\u00e1pida para esta viagem. A viagem geralmente leva cerca de 55 minutos, mas pode aumentar para at\u00e9 70 minutos no tr\u00e1fego intenso. Isso tamb\u00e9m pode aumentar o custo final, a menos que sua transfer\u00eancia seja <a href=\"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/taxi-aeroporto\/\" title=\"Pr\u00e9-reservada\">pr\u00e9-reservada<\/a> com um pre\u00e7o fechado.<\/p>\n","bottom_description_rating":"5","timetables":false,"editors_note":"Gorjetas, taxas de ped\u00e1gio e a sobretaxa do aeroporto ser\u00e3o adicionadas \u00e0 sua tarifa.","useful_tips":[{"tip":"Dar gorjeta ao seu motorista de 15 a 20% da sua tarifa total de viagem \u00e9 habitual."},{"tip":"A maioria dos taxistas aceita pagamentos em dinheiro e com cart\u00e3o, mas vale a pena verificar novamente antes de partir."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"146,70","price_per_passenger_2":"146,70","price_per_passenger_3":"146,70","price_per_passenger_4":"146,70","price_per_passenger_5":"293,40","price_per_passenger_6":"293,40","price_per_passenger_7":"293,40","price_per_passenger_8":"293,40","price_per_passenger_9":"440,10","price_per_passenger_10":"440,10","price_per_passenger_11":"440,10","price_per_passenger_12":"440,10","waiting_duration":"5","traveling_duration":"55","availability_from":"","availability_until":"","availability_picture":false,"is_247":true,"plot_color":"taxi","pricing_table_header":"","pricing_table_":false},{"name":"\u00d4nibus","title_line":"Como ir do Aeroporto de Boston a Worcester de \u00f4nibus","top_description":"<p>Embora n\u00e3o haja uma rota de \u00f4nibus direta do Aeroporto Logan para Worcester, ainda \u00e9 f\u00e1cil chegar a Worcester de \u00f4nibus, voc\u00ea s\u00f3 precisar\u00e1 pegar duas linhas de \u00f4nibus diferentes. Em primeiro lugar, pegue o \u00f4nibus Silver Line SL1 do terminal do aeroporto para a Esta\u00e7\u00e3o Sul. Esta parte da viagem leva at\u00e9 26 minutos, mais ou menos, dependendo de qual terminal voc\u00ea parte. Uma vez na Esta\u00e7\u00e3o Sul, caminhe ao lado do Terminal Rodovi\u00e1rio da Esta\u00e7\u00e3o Sul para pegar o \u00f4nibus Greyhound para a Esta\u00e7\u00e3o Worcester Union, que leva 1 hora, elevando o tempo total da viagem para pouco menos de 1 hora e 30 minutos. <span style=\"font-weight: 400;\">Tenha em mente que este servi\u00e7o opera em um hor\u00e1rio restrito, com apenas dois servi\u00e7os por dia \u00e0s 13:00hs e 17:30hs. <\/span><\/p>\n","fares":"$13.98 (\u20ac13.30)","trip_duration":"86 Min.","line_below_price_and_time":"O \u00f4nibus Greyhound tem uma taxa de reserva adicional de US$ 3,99 (\u20ac3,80).","perks":[{"perk":"Conveni\u00eancia","rating":"4"},{"perk":"Seguran\u00e7a","rating":"4"},{"perk":"Rela\u00e7\u00e3o custo-benef\u00edcio","rating":"5"}],"availability":"O SL1 opera nos dias \u00fateis entre 05:39hs e 01:20hs, aos s\u00e1bados entre 05:48hs e 01:12hs e aos domingos das 05:50hs e 01:06hs. O servi\u00e7o de \u00f4nibus Greyhound funciona duas vezes por dia \u00e0s 13:00hs e 17:30hs, todos os dias da semana.","middle_description_title":"Quanto custa o \u00f4nibus do Aeroporto Logan para Worcester?","middle_description":"<p>O SL1 do Aeroporto Logan \u00e9 sempre gratuito, ent\u00e3o voc\u00ea s\u00f3 precisa cobrir o custo da sua viagem de <a href=\"https:\/\/www.greyhound.com\/\" title=\"\u00f4nibus Greyhound\">\u00f4nibus Greyhound<\/a>. Uma passagem s\u00f3 de ida do Terminal Rodovi\u00e1rio da Esta\u00e7\u00e3o Sul para a Esta\u00e7\u00e3o Union de Worcester custa US$ 10,99 (10,50 euros) mais uma taxa de reserva de US$ 3,99 (\u20ac 3,80), elevando o pre\u00e7o total para US$ 13,98 (\u20ac 13,30) por viajante.<\/p>\n","middle_2_description_title":"De onde eu pego o \u00f4nibus?","middle_2_description":"<p>O SL1 parte do n\u00edvel de Chegadas e pode ser pego em cada um dos terminais do aeroporto. Na Esta\u00e7\u00e3o Sul, voc\u00ea precisar\u00e1 se transferir para o Terminal Rodovi\u00e1rio da Esta\u00e7\u00e3o Sul, que fica a 4 minutos a p\u00e9. O \u00f4nibus Greyhound para Worcester parte do Port\u00e3o 5.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Conveni\u00eancia ","bottom_description":"<p>Embora o \u00f4nibus ofere\u00e7a transporte confort\u00e1vel do Aeroporto Logan para Worcester, os servi\u00e7os limitados fornecidos pela Greyhound s\u00f3 o tornam conveniente se voc\u00ea estiver chegando dentro de um prazo restrito. Para um amigo que estar\u00e1 l\u00e1 para encontr\u00e1-lo quando seu voo pousar e at\u00e9 mesmo lhe dar um mini passeio pela cidade para se orientar, uma viagem <a href=\"https:\/\/www.welcomepickups.com\/boston\/airport-taxi\/\" title=\"Pr\u00e9-agendada Com A A Welcome Pickups\">pr\u00e9-agendada com a a Welcome Pickups<\/a> \u00e9 uma \u00f3tima op\u00e7\u00e3o se voc\u00ea n\u00e3o quiser se preocupar com atrasos de voo e conex\u00f5es de \u00f4nibus.<\/p>\n","bottom_description_rating":"3","timetables":[{"title":"\u00d4nibus do Aeroporto Logan - Esta\u00e7\u00e3o Sul","description":"Hor\u00e1rios do \u00f4nibus da Silver Line (SL1)","view_more_url":"https:\/\/www.mbta.com\/schedules\/741\/line?schedule_direction%5Bdirection_id%5D=1&schedule_direction%5Bvariant%5D=741-_-1"}],"editors_note":"Os bilhetes do Greyhound tamb\u00e9m podem ser comprados no dia na esta\u00e7\u00e3o no quiosque de autoatendimento. ","useful_tips":[{"tip":"Os \u00f4nibus Greyhound fornecem Wi-Fi gratuito e tomadas para carregar o seu telefone."},{"tip":"O entretenimento a bordo - incluindo acesso a dezenas de filmes, programas de TV e jogos, est\u00e1 inclu\u00eddo no seu bilhete."},{"tip":"Enquanto houver espa\u00e7o no \u00f4nibus, n\u00e3o h\u00e1 limita\u00e7\u00f5es de bagagem. No entanto, se voc\u00ea tiver excesso de bagagem, \u00e9 melhor reservar com anteced\u00eancia online."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"13,30","price_per_passenger_2":"26,60","price_per_passenger_3":"39,90","price_per_passenger_4":"53,20","price_per_passenger_5":"66,5","price_per_passenger_6":"79,80","price_per_passenger_7":"93,10","price_per_passenger_8":"106,40","price_per_passenger_9":"119,70","price_per_passenger_10":"133","price_per_passenger_11":"146,30","price_per_passenger_12":"159,60","waiting_duration":"15","traveling_duration":"86","availability_from":"11:15","availability_until":"17:30","availability_picture":false,"is_247":false,"plot_color":"bus","pricing_table_header":"","pricing_table_":false},{"name":"\u00d4nibus e trem Logan Express","title_line":"Como ir do Aeroporto Logan para Worcester de \u00f4nibus e trem","top_description":"<p>Outra op\u00e7\u00e3o de \u00f4nibus que opera mais regularmente \u00e9 o \u00f4nibus Logan Express do aeroporto para Framingham, onde voc\u00ea pode pegar a Framingham\/Worcester Commuter Rail Line para Worcester. Embora isso seja um pouco mais caro se reservado no dia, tem um tempo de viagem mais curto de 72 minutos, excluindo os tempos de espera.<\/p>\n","fares":"$13.25 (\u20ac12.60)","trip_duration":"72 Min.","line_below_price_and_time":"Os trens de Framingham funcionam a cada 45 a 60 minutos at\u00e9 as 20:25hs nos dias de semana, onde podem se tornar menos frequentes.  Nos fins de semana, o trem parte a cada 2 horas.","perks":[{"perk":"Conveni\u00eancia","rating":"4"},{"perk":"Seguran\u00e7a","rating":"5"},{"perk":"Rela\u00e7\u00e3o custo-benef\u00edcio","rating":"5"}],"availability":"O Logan Express funciona a cada meia hora entre 06:30hs e meia-noite durante a semana, e nos fins de semana funciona a cada hora entre 07:00hs e 12:00hs e depois a cada 30 minutos at\u00e9 a meia-noite. A Linha Framingham\/Worcester funciona entre 05:30hs e 00:35hs durante a semana e 05:51hs a 00:14hs nos fins de semana.","middle_description_title":"Quanto custa o \u00f4nibus Logan Express e o Commuter Rail?","middle_description":"<p>Os tickets para o <a title=\"\u00d4nibus Logan Express\" href=\"https:\/\/loganexpress.com\/buy-tickets.asp\">\u00f4nibus Logan Express<\/a> do Aeroporto Logan para Framingham podem ser comprados online a uma taxa com desconto de US$ 9 (\u20ac 8,60) por pessoa. Eles tamb\u00e9m podem ser comprados no dia no terminal ou a bordo do \u00f4nibus por US$12 (11,50) por pessoa. De Framingham, a viagem de ida para a Esta\u00e7\u00e3o Worcester custa US$ 4,25 (\u20ac4) por viajante e os tickets podem ser pagos em dinheiro ou cart\u00e3o nas m\u00e1quinas de autoatendimento no aeroporto ou uma vez em Framingham, no vendedor de bilhetes pr\u00f3ximo, &#8216;One Stop Market&#8217;. O custo total da viagem do Aeroporto de Boston para Worcester de \u00f4nibus e Commuter Rail \u00e9 de US$ 13,25 (\u20ac12,60) por viajante.<\/p>\n","middle_2_description_title":"De onde eu pego o \u00f4nibus e o trem Logan Express?","middle_2_description":"<p>O \u00f4nibus Logan Express para Framingham coleta passageiros de cada terminal, come\u00e7ando pelo Terminal A. Siga as placas para &#8216;\u00f4nibus programados&#8217; fora da \u00e1rea de coleta de bagagem de cada terminal. O Commuter Rail de Framingham para Worcester parte da Plataforma 1 na Esta\u00e7\u00e3o Framingham.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Conveni\u00eancia","bottom_description":"<p>O \u00f4nibus Logan Express coleta passageiros do lado de fora do terminal de chegadas para que voc\u00ea n\u00e3o precise se preocupar em andar muito longe com sua bagagem. Esta \u00e9 a op\u00e7\u00e3o de transporte mais r\u00e1pida usando o transporte p\u00fablico e \u00e9 apenas um pouco mais cara do que o \u00f4nibus e o trem, especialmente se voc\u00ea reservar com anteced\u00eancia online.<\/p>\n","bottom_description_rating":"4","timetables":[{"title":"Aeroporto Logan - \u00d4nibus de Framingham","description":"Hor\u00e1rios do \u00d4nibus Logan Express","view_more_url":"https:\/\/www.massport.com\/logan-airport\/to-from-logan\/transportation-options\/logan-express\/framingham\/"},{"title":"Hor\u00e1rios do Framingham - Worcester","description":"Linha do Metr\u00f4 Framingham\/Worcester","view_more_url":"https:\/\/www.mbta.com\/schedules\/CR-Worcester\/line?schedule_finder%5Bdirection_id%5D=0&schedule_finder%5Borigin%5D=place-WML-0214"}],"editors_note":"As tarifas n\u00e3o podem ser compradas na Esta\u00e7\u00e3o Framingham. Os tickets para o Commuter Rail precisam ser comprados no Framingham One Stop Market, nas proximidades, com anteced\u00eancia no aeroporto a partir de uma m\u00e1quina de venda autom\u00e1tica de tarifas ou atrav\u00e9s do aplicativo mTicket antes da partida.","useful_tips":[{"tip":"Se voc\u00ea estiver comprando sua passagem Logan Express pessoalmente, reserve tempo suficiente antes de embarcar, pois os \u00f4nibus saem dentro do hor\u00e1rio. Comprar pessoalmente tamb\u00e9m custar\u00e1 um extra de US$ 3 (\u20ac 2,90) em compara\u00e7\u00e3o com a compra antecipada do seu ticket online."},{"tip":"O Logan Express para em todos os terminais, come\u00e7ando pelo Terminal A."},{"tip":"Idosos com mais de 65 anos pagam apenas US$ 9 (8,60 euros)."},{"tip":"Crian\u00e7as e adolescentes com 17 anos ou menos viajam gratuitamente quando acompanhados por um membro da fam\u00edlia."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"12,60","price_per_passenger_2":"25,2","price_per_passenger_3":"37,8","price_per_passenger_4":"50,40","price_per_passenger_5":"63","price_per_passenger_6":"75,60","price_per_passenger_7":"88,20","price_per_passenger_8":"100,80","price_per_passenger_9":"113,40","price_per_passenger_10":"126","price_per_passenger_11":"138,60","price_per_passenger_12":"151,20","waiting_duration":"30","traveling_duration":"72","availability_from":"06:30","availability_until":"00:14","availability_picture":false,"is_247":false,"plot_color":"bus","pricing_table_header":"","pricing_table_":false},{"name":"Bonde","title_line":"Como ir do Aeroporto de Boston a Worcester de trem","top_description":"<p>Outra op\u00e7\u00e3o econ\u00f4mica para chegar a Worcester \u00e9 pegar o \u00f4nibus Silver Line (SL1) do aeroporto e mudar para o Commuter Rail na Esta\u00e7\u00e3o Sul. Da Esta\u00e7\u00e3o Sul, pegue a Linha Framingham\/Worcester at\u00e9 Worcester. A viagem leva pouco mais de 2 horas, n\u00e3o incluindo nenhum tempo de espera na Esta\u00e7\u00e3o Sul.<\/p>\n","fares":"$12.25 (\u20ac11.70)","trip_duration":"126 Min.","line_below_price_and_time":"O servi\u00e7o SL1 opera aproximadamente a cada 12 minutos. A Linha Framingham\/Worcester em dire\u00e7\u00e3o a Worcester parte a cada 45 a 60 minutos, potencialmente aumentando os tempos de espera para esta viagem. ","perks":[{"perk":"Conveni\u00eancia","rating":"3"},{"perk":"Seguran\u00e7a","rating":"5"},{"perk":"Rela\u00e7\u00e3o custo-benef\u00edcio","rating":"4"}],"availability":"O SL1 opera durante a semana entre 05:39hs e 01:20hs, aos s\u00e1bados entre 05:48hs e 01:12hs e aos domingos a partir de 05:50hs e 01:06hs. Os trens da Esta\u00e7\u00e3o Sul para Worcester funcionam das 04:45hs \u00e0s 23:45hs nos dias de semana e das 05:00hs \u00e0s 23:15hs nos fins de semana.","middle_description_title":"Tarifa de \u00f4nibus e trem do Aeroporto de Boston para Worcester","middle_description":"<p>O SL1 do Aeroporto Logan \u00e9 sempre gratuito, ent\u00e3o voc\u00ea s\u00f3 precisa cobrir o custo da sua viagem a partir da Esta\u00e7\u00e3o Sul. Uma passagem de ida da Esta\u00e7\u00e3o Sul at\u00e9 Worcester na Zona 8 no Commuter Rail custar\u00e1 US$ 12,25 (\u20ac11,70) por pessoa.<\/p>\n<p>Os CharlieTickets para o Commuter Rail podem ser comprados em m\u00e1quinas de venda autom\u00e1tica de tarifas da Esta\u00e7\u00e3o Sul ou em uma bilheteria usando dinheiro ou cart\u00e3o.<\/p>\n","middle_2_description_title":"De onde eu pego o \u00f4nibus e o trem?","middle_2_description":"<p>O SL1 parte de cada um dos terminais do aeroporto, assim que voc\u00ea sair da parte de Chegadas e seguir as placas de sa\u00edda, ver\u00e1 a parada. Na Esta\u00e7\u00e3o Sul, siga as placas para o Commuter Rail e embarque na Linha Framingham\/Worcester.<\/p>\n","before_bottom_t":"","before_bottom_description":"","before_bottom_features":false,"bottom_description_title":"Conveni\u00eancia","bottom_description":"<p>Usar o \u00f4nibus de traslado do aeroporto de Boston para Worcester certamente economizar\u00e1 dinheiro, mas, no geral, essa op\u00e7\u00e3o n\u00e3o \u00e9 a mais conveniente devido aos tempos de espera potencialmente longos na Esta\u00e7\u00e3o Sul. Se voc\u00ea estiver viajando sozinho e com um or\u00e7amento limitado, essa op\u00e7\u00e3o ainda o levar\u00e1 a Worcester em 2 a 3 horas.<\/p>\n","bottom_description_rating":"3","timetables":[{"title":"\u00d4nibus do Aeroporto Logan - Esta\u00e7\u00e3o Sul","description":"Hor\u00e1rios do \u00f4nibus da Silver Line (SL1)","view_more_url":"https:\/\/www.mbta.com\/schedules\/741\/line?schedule_direction%5Bdirection_id%5D=1&schedule_direction%5Bvariant%5D=741-_-1"},{"title":"Esta\u00e7\u00e3o Sul - Hor\u00e1rios de Worcester","description":"Linha do Metr\u00f4 Framingham\/Worcester","view_more_url":"https:\/\/www.mbta.com\/schedules\/CR-Worcester\/timetable?date=2023-10-04&schedule_direction[direction_id]=0#direction-filter"}],"editors_note":"Viajar de \u00f4nibus para a Esta\u00e7\u00e3o Sul e depois de trem para Worcester \u00e9 a op\u00e7\u00e3o de transporte mais barata para chegar ao seu destino e a melhor op\u00e7\u00e3o se voc\u00ea estiver viajando com um or\u00e7amento limitado. Dado que o trem opera apenas em m\u00e9dia uma vez por hora, esteja preparado para tempos de espera mais longos na Esta\u00e7\u00e3o Sul se voc\u00ea n\u00e3o fizer sua conex\u00e3o.","useful_tips":[{"tip":"Baixe o aplicativo mTicket para tornar o planejamento da sua viagem e a compra de tickets super r\u00e1pida e f\u00e1cil com atualiza\u00e7\u00f5es ao vivo."},{"tip":"Os servi\u00e7os de \u00f4nibus e trem operam em um hor\u00e1rio ligeiramente reduzido nos fins de semana."}],"photos":false,"gallery_subline":"","infographics_only":false,"price_per_passenger_1":"11,70","price_per_passenger_2":"23,4","price_per_passenger_3":"35,10","price_per_passenger_4":"46,80","price_per_passenger_5":"58,50","price_per_passenger_6":"70,20","price_per_passenger_7":"81,90","price_per_passenger_8":"93,60","price_per_passenger_9":"105,30","price_per_passenger_10":"117","price_per_passenger_11":"128,70","price_per_passenger_12":"140,40","waiting_duration":"30","traveling_duration":"126","availability_from":"05:39","availability_until":"23:45","availability_picture":false,"is_247":false,"plot_color":"train","pricing_table_header":"","pricing_table_":false}],"description":"<p><span style=\"font-weight: 400;\">Se voc\u00ea est\u00e1 indo para Worcester a neg\u00f3cios ou lazer, certifique-se de ter algum tempo para visitar o Museu de Arte de Worcester, que abriga uma impressionante exibi\u00e7\u00e3o de armaduras medievais, e o EcoTarium, um dos favoritos entre as crian\u00e7as (os grandes tamb\u00e9m!) Onde voc\u00ea pode literalmente colocar suas m\u00e3os em todas as coisas relacionadas \u00e0 natureza.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora existam v\u00e1rias op\u00e7\u00f5es de viagem diferentes para Worcester, o transporte mais r\u00e1pido e conveniente do Aeroporto Logan de Boston para Worcester MA \u00e9 de t\u00e1xi ou <a href=\"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/taxi-aeroporto\/\" title=\"Transfer\u00eancia Privada\">transfer\u00eancia privada<\/a>. Esta rota direta o entregar\u00e1 ao seu destino em 55 minutos em tr\u00e1fego leve, quase metade do tempo das op\u00e7\u00f5es de \u00f4nibus ou trem, e custar\u00e1 uma m\u00e9dia de US$154 (\u20ac146,50) para at\u00e9 4 passageiros. Se voc\u00ea estiver viajando sozinho, h\u00e1 duas rotas de \u00f4nibus confort\u00e1veis e convenientes; uma que passa pela Esta\u00e7\u00e3o Sul e se conecta a um \u00f4nibus Greyhound, leva cerca de 82 minutos &#8211; excluindo os tempos de espera, e custa US$14 (\u20ac13,30) por viajante; e outra que usa o servi\u00e7o Logan Express para Framingham, onde os passageiros se conectam com o trem Commuter Rail para Worcester, levando cerca de 72 minutos &#8211; excluindo os tempos de espera, e custa entre US$ 13,25 e US$16,25 (\u20ac12,60-15,50) por passageiro. A op\u00e7\u00e3o mais barata se voc\u00ea n\u00e3o estiver com pressa \u00e9 pegar o traslado gratuito do aeroporto SL1 para a Esta\u00e7\u00e3o Sul e mudar para o Commuter Rail para Worcester, que custar\u00e1 US$ 12,25 (\u20ac 11,70) por viajante e levar\u00e1 pouco mais de 2 horas, n\u00e3o incluindo nenhum tempo de espera. <\/span><\/p>\n","main_title":"Como ir do Aeroporto Logan a Worcester","brushed_up_on":"","from_id":"329128","to_id":"","flat_price_1_value":"","flat_price_2_value":"","is_seo_2":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u2708\ufe0f Como ir do Aeroporto Boston Logan a Worcester<\/title>\n<meta name=\"description\" content=\"Tudo o que voc\u00ea precisa saber sobre o seu transporte no Aeroporto de Logan - Compare todas as op\u00e7\u00f5es dispon\u00edveis do Aeroporto de Logan a Worcester.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como ir do Aeroporto Boston Logan a Worcester\" \/>\n<meta property=\"og:description\" content=\"Tudo o que voc\u00ea precisa saber sobre o seu transporte no Aeroporto de Logan - Compare todas as op\u00e7\u00f5es dispon\u00edveis do Aeroporto de Logan a Worcester.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome Pickups\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welcomepickups\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-16T14:13:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/aeroporto-para-worcester\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/aeroporto-para-worcester\\\/\",\"name\":\"\u2708\ufe0f Como ir do Aeroporto Boston Logan a Worcester | Welcome Pickups\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/aeroporto-para-worcester\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/aeroporto-para-worcester\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Worcester-Massachusetts.jpeg\",\"datePublished\":\"2023-12-08T08:40:20+00:00\",\"dateModified\":\"2023-12-16T14:13:59+00:00\",\"description\":\"Tudo o que voc\u00ea precisa saber sobre o seu transporte no Aeroporto de Logan - Compare todas as op\u00e7\u00f5es dispon\u00edveis do Aeroporto de Logan a Worcester.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/aeroporto-para-worcester\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/aeroporto-para-worcester\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/aeroporto-para-worcester\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Worcester-Massachusetts.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Worcester-Massachusetts.jpeg\",\"width\":1920,\"height\":1280,\"caption\":\"Logan Airport to Worcester\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/aeroporto-para-worcester\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boston &#8211; Hub\",\"item\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/boston\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como ir do Aeroporto Boston Logan a Worcester\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/\",\"name\":\"Welcome Pickups\",\"description\":\"Make every new city feel like home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/#organization\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/#organization\",\"name\":\"Welcome Pickups\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"contentUrl\":\"https:\\\/\\\/www.welcomepickups.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/welcome_logo_dark.png\",\"width\":347,\"height\":81,\"caption\":\"Welcome Pickups\"},\"image\":{\"@id\":\"https:\\\/\\\/www.welcomepickups.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/welcomepickups\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u2708\ufe0f Como ir do Aeroporto Boston Logan a Worcester","description":"Tudo o que voc\u00ea precisa saber sobre o seu transporte no Aeroporto de Logan - Compare todas as op\u00e7\u00f5es dispon\u00edveis do Aeroporto de Logan a Worcester.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/","og_locale":"pt_PT","og_type":"article","og_title":"Como ir do Aeroporto Boston Logan a Worcester","og_description":"Tudo o que voc\u00ea precisa saber sobre o seu transporte no Aeroporto de Logan - Compare todas as op\u00e7\u00f5es dispon\u00edveis do Aeroporto de Logan a Worcester.","og_url":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/","og_site_name":"Welcome Pickups","article_publisher":"https:\/\/www.facebook.com\/welcomepickups","article_modified_time":"2023-12-16T14:13:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/","url":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/","name":"\u2708\ufe0f Como ir do Aeroporto Boston Logan a Worcester | Welcome Pickups","isPartOf":{"@id":"https:\/\/www.welcomepickups.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/#primaryimage"},"image":{"@id":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/#primaryimage"},"thumbnailUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts.jpeg","datePublished":"2023-12-08T08:40:20+00:00","dateModified":"2023-12-16T14:13:59+00:00","description":"Tudo o que voc\u00ea precisa saber sobre o seu transporte no Aeroporto de Logan - Compare todas as op\u00e7\u00f5es dispon\u00edveis do Aeroporto de Logan a Worcester.","breadcrumb":{"@id":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/#primaryimage","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts.jpeg","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2023\/09\/Worcester-Massachusetts.jpeg","width":1920,"height":1280,"caption":"Logan Airport to Worcester"},{"@type":"BreadcrumbList","@id":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/aeroporto-para-worcester\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.welcomepickups.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Boston &#8211; Hub","item":"https:\/\/www.welcomepickups.com\/pt-pt\/boston\/"},{"@type":"ListItem","position":3,"name":"Como ir do Aeroporto Boston Logan a Worcester"}]},{"@type":"WebSite","@id":"https:\/\/www.welcomepickups.com\/pt-pt\/#website","url":"https:\/\/www.welcomepickups.com\/pt-pt\/","name":"Welcome Pickups","description":"Make every new city feel like home","publisher":{"@id":"https:\/\/www.welcomepickups.com\/pt-pt\/#organization"},"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.welcomepickups.com\/pt-pt\/#organization","name":"Welcome Pickups","url":"https:\/\/www.welcomepickups.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.welcomepickups.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","contentUrl":"https:\/\/www.welcomepickups.com\/wp-content\/uploads\/2019\/10\/welcome_logo_dark.png","width":347,"height":81,"caption":"Welcome Pickups"},"image":{"@id":"https:\/\/www.welcomepickups.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welcomepickups"]}]}},"_links":{"self":[{"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/pages\/384774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/users\/209"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=384774"}],"version-history":[{"count":6,"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/pages\/384774\/revisions"}],"predecessor-version":[{"id":385599,"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/pages\/384774\/revisions\/385599"}],"up":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/pages\/380320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/media\/372592"}],"wp:attachment":[{"href":"https:\/\/www.welcomepickups.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=384774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}